{"id":39830,"date":"2022-04-11T21:59:00","date_gmt":"2022-04-11T21:59:00","guid":{"rendered":"https:\/\/fm-comunicar.com.ar\/contenido\/19116\/a-traves-de-la-musica-un-joven-caroyense-conmueve-al-contar-sobre-la-enfermedad-"},"modified":"2022-04-11T21:59:00","modified_gmt":"2022-04-11T21:59:00","slug":"a-traves-de-la-musica-un-joven-caroyense-conmueve-al-contar-sobre-la-enfermedad-que-padece","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/04\/11\/a-traves-de-la-musica-un-joven-caroyense-conmueve-al-contar-sobre-la-enfermedad-que-padece\/","title":{"rendered":"A trav\u00e9s de la m\u00fasica, un joven caroyense conmueve al contar sobre la enfermedad que padece"},"content":{"rendered":"<p>A los seis a\u00f1os le diagnosticaron Distrofia Muscular de Duchenne y desde los ocho est\u00e1 en silla de ruedas. La m\u00fasica es su pasi\u00f3n y una de sus primeras canciones la hizo demostrando su esp\u00edritu de lucha.<img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/04\/a-traves-de-la-musica-un-joven-caroyense-conmueve-al-contar-sobre-la-enfermedad-que-padece.jpg\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A los seis a\u00f1os le diagnosticaron Distrofia Muscular de Duchenne y desde los ocho est\u00e1 en silla de ruedas. La m\u00fasica es su pasi\u00f3n y una de sus primeras canciones la hizo demostrando su esp\u00edritu de lucha.<\/p>\n","protected":false},"author":1,"featured_media":39831,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/39830"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=39830"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/39830\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/39831"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=39830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=39830"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=39830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}