{"id":38565,"date":"2022-03-18T02:20:34","date_gmt":"2022-03-18T02:20:34","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2022\/03\/18\/goles-agonicos-que-definieron-clasicos-del-futbol-argentino-ole\/"},"modified":"2022-03-18T02:20:34","modified_gmt":"2022-03-18T02:20:34","slug":"goles-agonicos-que-definieron-clasicos-del-futbol-argentino-ole","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/03\/18\/goles-agonicos-que-definieron-clasicos-del-futbol-argentino-ole\/","title":{"rendered":"Goles ag\u00f3nicos que definieron cl\u00e1sicos del <b>f\u00fatbol argentino<\/b> &#8211; Ol\u00e9"},"content":{"rendered":"<p>Goles ag\u00f3nicos que definieron cl\u00e1sicos del <b>f\u00fatbol argentino<\/b>. En la previa de una fecha muy especial en la Copa de la Liga, repasamos tantos decisivos&nbsp;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Goles ag\u00f3nicos que definieron cl\u00e1sicos del f\u00fatbol argentino. En la previa de una fecha muy especial en la Copa de la Liga, repasamos tantos decisivos&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38565"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=38565"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38565\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=38565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=38565"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=38565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}