{"id":38159,"date":"2022-03-09T20:21:26","date_gmt":"2022-03-09T20:21:26","guid":{"rendered":"https:\/\/www.espinof.com\/trailers\/obi-wan-kenobi-impresionante-trailer-serie-star-wars-para-disney-plus-protagonizada-ewan-mcgregor"},"modified":"2022-03-09T20:21:26","modified_gmt":"2022-03-09T20:21:26","slug":"obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/03\/09\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor\/","title":{"rendered":"&#8216;Obi-Wan Kenobi&#8217;: impresionante tr\u00e1iler de la serie de Star Wars para Disney+ protagonizada por Ewan McGregor"},"content":{"rendered":"<p>Aqu\u00ed tenemos el <strong>impresionante tr\u00e1iler<\/strong> de <a href=\"https:\/\/www.espinof.com\/fecha-de-estreno\/obi-wan-kenobi-todo-que-sabemos-serie-star-wars-para-disney-plus-ewan-mcgregor\">&#8216;Obi-Wan Kenobi&#8217;<\/a>, la serie de Disney+ que recupera a <strong>Ewan McGregor<\/strong> dando vida al m\u00edtico Maestro Jedi del universo Star Wars. Se ve que en Lucasfilm hab\u00eda prisa por lanzarlo, pues ha llegado apenas unas horas despu\u00e9s de la aparici\u00f3n online de <a href=\"https:\/\/www.espinof.com\/series-de-ficcion\/obi-wan-kenobi-primeras-imagenes-serie-ewan-mcgregor-presentan-a-gran-villana-funcion-traen-vuelta-a-otro-personaje-universo-star-wars\">sus primeras im\u00e1genes.<\/a><\/p>\n<p><!-- BREAK 1 --><\/p>\n<h2>10 a\u00f1os despu\u00e9s de &#8216;La venganza de los Sith&#8217;<\/h2>\n<p>La historia de &#8216;Obi-Wan Kenobi&#8217; se sit\u00faa 10 a\u00f1os despu\u00e9s de lo que vimos en <a href=\"https:\/\/www.espinof.com\/criticas\/star-wars-la-venganza-de-los-sith-bienvenida-oscuridad\">&#8216;La venganza de los Sith&#8217;<\/a>, donde su personaje cre\u00eda haber acabado con Anakin Skywalker, quien poco despu\u00e9s de esa batalla se transform\u00f3 en el temible Darth Vader. Ojo, que <strong>Hayden Christensen<\/strong> tambi\u00e9n reaparece aqu\u00ed interpretando a ese legendario villano.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/fecha-de-estreno\/obi-wan-kenobi-todo-que-sabemos-serie-star-wars-para-disney-plus-ewan-mcgregor\"> <img alt=\"'Obi-Wan Kenobi', todo lo que sabemos de la serie de Star Wars para Disney+ con Ewan McGregor \" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Llama la atenci\u00f3n que desde Lucasfilm poco menos que hayan puesto ya toda la carne en el asador, ya que el estreno de &#8216;Obi-Wan Kenobi&#8217; no est\u00e1 previsto hasta el pr\u00f3ximo <strong>25 de mayo<\/strong>. Ser\u00e1 entonces cuando podamos ver el primer episodio de los seis que dan forma a su primera -y quiz\u00e1 \u00fanica- temporada.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<div class=\"article-asset-image article-asset-large\">\n<div class=\"asset-content\">\n<div class=\"base-wrapper-image\"> <img class=\"sf-lazy \" data-sf-srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-2.jpg 681w,http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-3.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-4.jpg 1366w,\" data-sf-src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-1.jpg\" alt=\"Obi Wan Portada Ewan\"> <noscript><img alt=\"Obi Wan Portada Ewan\" class src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/03\/obi-wan-kenobi-impresionante-trailer-de-la-serie-de-star-wars-para-disney-protagonizada-por-ewan-mcgregor-1.jpg\"><\/noscript> <\/div><\/div>\n<\/div>\n<p>En &#8216;Obi-Wan Kenobi&#8217; tambi\u00e9n veremos a <strong>Moses Ingram, Joel Edgerton, Bonnie Piesse Kumail Nanjiani<\/strong> (<a href=\"https:\/\/www.espinof.com\/fecha-de-estreno\/eternals-fecha-de-estreno-trailer-reparto-pelicula-de-marvel-dirigida-por-chloe-zhao\">&#8216;Eternals&#8217;<\/a>), <strong>Indira Varma, Rupert Friend, <\/strong>O&#8217;Shea Jackson Jr., Sung Kang, Simone Kessell, Benny Safdie, Maya Erskine y Rory Ross.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Por su parte, la direcci\u00f3n corre a cargo de <strong>Deborah Chow<\/strong>, realizadora de un par de episodios de <a href=\"https:\/\/www.espinof.com\/listas\/the-mandalorian-todos-episodios-serie-star-wars-ordenados-peor-a-mejor\">&#8216;The Mandalorian&#8217;<\/a>, mientras que del guion se ha ocupado <strong>Joby Harold<\/strong> (<a href=\"https:\/\/www.espinof.com\/criticas\/rey-arturo-la-leyenda-de-excalibur-una-entretenida-revision-del-mito-arruinada-por-su-horrible-final\">&#8216;Rey Arturo: La leyenda de Excalibur&#8217;<\/a>).<\/p>\n<p><!-- BREAK 5 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed tenemos el impresionante tr\u00e1iler de &#8216;Obi-Wan Kenobi&#8217;, la serie de Disney+ que recupera a Ewan McGregor dando vida al m\u00edtico Maestro Jedi del universo Star Wars. Se ve que en Lucasfilm hab\u00eda prisa por lanzarlo, pues ha llegado apenas unas horas despu\u00e9s de la aparici\u00f3n online de sus primeras im\u00e1genes. 10 a\u00f1os despu\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38159"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=38159"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/38159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/38160"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=38159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=38159"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=38159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}