{"id":37258,"date":"2022-02-18T00:15:01","date_gmt":"2022-02-18T00:15:01","guid":{"rendered":"https:\/\/www.ole.com.ar\/fuera-de-juego\/serie-bilardo-doctor-futbol_0_hm9P3yx89t.html"},"modified":"2022-02-18T00:15:01","modified_gmt":"2022-02-18T00:15:01","slug":"todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/02\/18\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo\/","title":{"rendered":"Todo lo que ten\u00e9s que saber de la nueva serie de Bilardo"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo.jpg\"><\/p>\n<p>El <strong>jueves 24 de febrero<\/strong> se estrena en HBO Max <mark>Bilardo: el Doctor del F\u00fatbol<\/mark>, la nueva serie sobre la vida <strong><a alt=\"carlos-salvador-bilardo\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/carlos-salvador-bilardo.html\" target=\"_blank\" title=\"carlos-salvador-bilardo\" rel=\"noopener noreferrer\">Carlos Salvador Bilardo<\/a><\/strong>. Un documental dividido en cuatro episodios de 45 minutos que repasa la etapa del Narig\u00f3n como entrenador de la <strong><a alt=\"seleccion-argentina\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" target=\"_blank\" title=\"seleccion-argentina\" rel=\"noopener noreferrer\">Selecci\u00f3n Argentina<\/a><\/strong>. Pero no todo es f\u00fatbol. Tambi\u00e9n se sumerge en su vida personal, mostrando c\u00f3mo era fuera de la cancha, su relaci\u00f3n con seres queridos&nbsp;y todas sus man\u00edas y c\u00e1balas, algunas desconocidas.<\/p>\n<p> Los productores de la docuserie utilizaron cientos de horas de video que nunca hab\u00edan salido a la luz, y tambi\u00e9n incluyeron testimonios de algunos personajes que lo rodearon. Como por ejemplo <strong>Oscar Ruggeri, Sergio Goycochea, Marcelo Bielsa, Claudia Villafa\u00f1e, Sebasti\u00e1n Ver\u00f3n o el Cholo Simeone<\/strong>, entre otros. A d\u00edas de su debut en la plataforma de streaming<strong> HBO Max<\/strong>, te anticipamos todo lo que ten\u00e9s que saber antes de verla.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-2.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-2.jpg\" loading=\"lazy\" alt=\"Ruggeri en el documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Ruggeri en el documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<h2> <strong>\u00bfQU\u00c9 A\u00d1OS ABARCA?<\/strong><\/h2>\n<p>La vida de Bilardo est\u00e1 llena de haza\u00f1as y momentos memorables. Desde sus logros como jugador en <strong><a alt=\"estudiantes-lp\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/estudiantes-lp.html\" target=\"_blank\" title=\"estudiantes-lp\" rel=\"noopener noreferrer\">Estudiantes<\/a><\/strong>, su faceta como m\u00e9dico ginec\u00f3logo, y claro, toda su gesta como entrenador. Con tanto por mostrar, los productores de la serie se vieron obligados a limitarse y elegir solo un fragmento de su vida, por lo que se quedaron con su etapa como DT de la Selecci\u00f3n.<\/p>\n<p> <strong>Sebasti\u00e1n Meschengieser,<\/strong>&nbsp;uno de los guionistas, le revel\u00f3 a <strong>Ol\u00e9 <\/strong>c\u00f3mo est\u00e1 desplegado el documental a lo largo de los cap\u00edtulos: \u00ab<strong>La serie arranca en el momento que Carlos firma el contrato con la Selecci\u00f3n.<\/strong> Hist\u00f3ricamente vas a pasar de todo lo que es su primer per\u00edodo, hasta la Eliminatoria para llegar a M\u00e9xico. Un segundo episodio que est\u00e1 muy focalizado en <strong>la previa y en el Mundial de 1986<\/strong>. Un tercer episodio que tiene que ver con el <strong>per\u00edodo entre mundiales y la \u00e9pica del 90<\/strong>. Y un cap\u00edtulo cuatro que ten\u00e9s un Carlos que, si bien es el m\u00e1s actual, es el m\u00e1s variopinto e interesante, porque es docente, anfitri\u00f3n de televisi\u00f3n, actor, candidato a presidente, tiene Boca y vuelve a Estudiantes\u2026 <mark>Es un viaje incre\u00edble<\/mark>\u00ab.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/informacion-general\/carlos-salvador-bilardo-reaparecio-publico-estudiantes-foto_0_8oVITCsJzu.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Bilardo reapareci\u00f3 p\u00fablicamente: \u00a1qu\u00e9 alegr\u00eda Doctor!\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-3.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<h2><strong>QU\u00c9 SE PUEDE ESPERAR DE LA SERIE<\/strong><\/h2>\n<p> <strong>Ariel Rotter<\/strong>, director del documental, anticip\u00f3 un poco de qu\u00e9 se puede esperar encontrar. Desde sus locuras como entrenador, a los problemas que le tra\u00eda su obsesi\u00f3n por el deporte. <strong>\u00abEl tipo era un moderno<\/strong>. Vio que el f\u00fatbol empezaba a cambiar hacia un lugar mucho m\u00e1s t\u00e9cnico y de detalles. Y lo ve 20 a\u00f1os antes de que lo vea todo el mundo. As\u00ed que se tiene que enfrentar al sistema que imperaba en aquella \u00e9poca, que es el de la bajada del f\u00fatbol l\u00edrico, el Jogo Bonito brasile\u00f1o, que ten\u00eda a Menotti como int\u00e9rprete local, y \u00e9l dice: &#8216;No, cambi\u00f3. Ahora se gana con una pelota parada. Con los detalles&#8217;. <strong>Todo esto contado por los protagonistas\u00bb<\/strong>, le explic\u00f3 Rotter a Ol\u00e9.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-4.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-4.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p> Y a\u00f1adi\u00f3: \u00abA la vez <mark>hay una dimensi\u00f3n \u00edntima que nunca fue recorrida antes.<\/mark> De cu\u00e1les eran sus penas, sus tristezas, sus alegr\u00edas y sus momentos de disfrute. Y c\u00f3mo esa vida dedicada 24 horas al f\u00fatbol le imped\u00eda dormir y lo alej\u00f3 de su familia\u00bb.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-5.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-5.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p> Por otro lado, asegur\u00f3 que no ser\u00e1 el t\u00edpico film en su honor, sino que muestra tanto sus facetas y momentos negativos.<strong> \u00abYo creo que va a ser un material muy conmovedor.<\/strong> Creo que en ese sentido la serie logra algo que no es tan f\u00e1cil, que es no caer en el homenaje. <mark>Que la serie no sea un homenaje adulador<\/mark>, sino que pone en cuesti\u00f3n toda la dimensi\u00f3n y contradicciones del personaje\u00bb, aclar\u00f3.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/mundial\/mundial-qatar-202\/mundial-qatar-26-jugadores-seleccion_0_nVgfIKyral.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"\u00bfMundial con 26 jugadores por selecci\u00f3n?\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-6.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<h2><strong>M\u00c1S DE 1000 VIDEOS DE ARCHIVO<\/strong><\/h2>\n<p> Una de las joyas que tiene este documental, es la primicia de poder mostrar cientos de horas de video que estaban guardadas en la casa del Narig\u00f3n. <strong>M\u00e1s de 1000 grabaciones in\u00e9ditas, que nunca vieron la luz del d\u00eda, y por primera vez estar\u00e1n a la vista de todos.<\/strong><\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-7.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-7.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p> <mark>\u00abNosotros tuvimos acceso a la colecci\u00f3n privada de Carlos<\/mark>, con lo cual era infinito y era inabordable. Era dif\u00edcil de visionar y digitalizar todo eso. Por ejemplo, hab\u00eda&nbsp;600 tapes sin ning\u00fan tipo de r\u00f3tulo.<strong> Necesitabas una vida para ver todo lo que \u00e9l grab\u00f3 durante toda su vida\u00bb<\/strong>, sostuvo el director.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/futbol-primera\/afa-liga-arbitros-programacion_0_HD7Q5CxFxJ.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Horarios y \u00e1rbitros de la tercera fecha\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-8.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<h2><strong>EL ROL DE LA FAMILIA BILARDO<\/strong><\/h2>\n<p><strong>Federico D\u2019El\u00eda<\/strong>, uno de los productores, explic\u00f3:<strong> <\/strong>\u00abLa familia tuvo un rol fundamental, desde antes de que empecemos a rodar. <strong>Ten\u00edamos que ponernos de acuerdo para<\/strong>&nbsp;<strong>invadir y purgar su hogar<\/strong>, tratando de rescatar todo lo que quer\u00edamos tener en el documental. Cosa que logramos, consiguiendo su archivo personal y otras <strong>cosas que conseguimos abri\u00e9ndole los placares.<\/strong> Sab\u00edamos que para entender a Bilardo ten\u00edamos que entender a su entorno y a su familia\u00bb.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-9.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-9.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<h2><strong>AN\u00c9CDOTAS, C\u00c1BALAS Y M\u00c1S<\/strong><\/h2>\n<p> Bilardo es una de esas figuras del f\u00fatbol argentino que origin\u00f3 una cantidad de an\u00e9cdotas e historias innumerables. Muchas ya son conocidas, pero hay otras que segu\u00edan estando ocultas. Los videos, sumado a los testimonios de los protagonistas, expondr\u00e1n muchos detalles que todav\u00eda no eran del todo conocidos en la vida del Doctor. Y por supuesto, tambi\u00e9n mostrar\u00e1n desde adentro todas esas an\u00e9cdotas que fascinan a todos los fan\u00e1ticos del deporte.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-10.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-10.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p> \u00abEl que ya sabe de las an\u00e9cdotas de Bilardo va a escuchar de ese mundo. <strong>Va a escuchar de las c\u00e1balas, la historia del Gatorade contada desde adentro, el tema del Bid\u00f3n contra Brasil, el \u2018pisalo, pisalo\u2019.<\/strong> Hay una cantidad de an\u00e9cdotas que pocos han generado. Hay frases que son bandera y la serie tambi\u00e9n las recorre\u00bb, le dijo el guionista Gustavo Dejtiar a <strong>Ol\u00e9<\/strong>.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/europa-league\/barcelona-napoli-penal-var-mano_0_k9nnfSAj8T.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Video: el incre\u00edble penal que le dieron al Barcelona\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-11.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<h2><strong>UNA SERIE APTA PARA MENOTTISTAS<\/strong><\/h2>\n<p> <mark>Bilardismo vs. menottismo<\/mark>. El debate de las escuelas filos\u00f3ficas de dos grandes entrenadores se convirti\u00f3 en una de las grietas m\u00e1s grandes en la historia del f\u00fatbol argentino. Pero no hay de qu\u00e9 preocuparse, porque <strong>la serie de Carlos est\u00e1 preparada para ambos p\u00fablicos<\/strong>, mostrando en profundidad los dos lados de la disputa.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-12.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-12.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p> <strong>\u00abEl documental es apto para todo p\u00fablico futbolero y todo p\u00fablico no futbolero.<\/strong> Y no solo eso, sino que tiene de esa grieta de bilardismo contra menottismo, que atraviesa los \u00faltimos 30 a\u00f1os de historia. <mark>El debate est\u00e1 expuesto, las voces se enfrentan.<\/mark> No es una serie condescendiente con la mirada bilardista, por supuesto que est\u00e1 expresada por muchos defensores de esa filosof\u00eda, pero tambi\u00e9n se ve el otro bando\u00bb, argument\u00f3 Dejtiar.<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/futbol-primera\/var-argentina-afa-beligoy_0_r4WBGH03Dt.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Oficial: el VAR arranca en la octava fecha\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-13.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<h2><strong>EL TRABAJO DETR\u00c1S DEL DOCUMENTAL<\/strong><\/h2>\n<p> <strong>Alejandro Turner<\/strong>, uno de los productores de la serie, habl\u00f3 de los obst\u00e1culos que se le presentaron a la hora de encarar el proyecto, que por momentos se vio trabado por la pandemia: <strong>\u00abLas primeras reuniones fueron hace un a\u00f1o y medio. <\/strong>A partir de ah\u00ed hubo un a\u00f1o de trabajo muy muy intenso de mucha gente, en plena pandemia adem\u00e1s, lo cual dificult\u00f3 las entrevistas y los reportajes. Pero la verdad es que hubo un laburo enorme\u00bb.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-14.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-14.jpg\" loading=\"lazy\" alt=\"Simeone en el documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Simeone en el documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<h2><strong>\u00abGUIONAR A BILARDO ES IMPOSIBLE\u00bb<\/strong><\/h2>\n<p> Sebasti\u00e1n Meschengieser asegur\u00f3 que <mark>\u00abGuionar a Bilardo es imposible\u00bb<\/mark>, para expresar la dificultad que conlleva poder hacer una serie sobre una figura de tal magnitud. <strong>\u00abHicimos una investigaci\u00f3n bastante ardua los primeros dos, tres meses.<\/strong> Despu\u00e9s te vas encontrando a gente relacionada que va sumando a la investigaci\u00f3n. Sobre todo en personajes como este que ten\u00eda cosas ocultas, como el v\u00ednculo con su familia.<strong> Un personaje como Carlos, tan rico y con tantas facetas, tiene que el documental ya termin\u00f3 pero siguen apareciendo cosas nuevas\u00bb<\/strong>, solt\u00f3.<\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-15.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-15.jpg\" loading=\"lazy\" alt=\"Fragmentos del documental de Bilardo. Foto: HBO Max.\">\n<\/picture><figcaption readability=\"2\">\n<p>Fragmentos del documental de Bilardo. Foto: HBO Max.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<h2> <strong>\u00bfC\u00d3MO VER EL DOCUMENTAL DE BILARDO?<\/strong><\/h2>\n<p><mark>Bilardo: el Doctor del F\u00fatbol<\/mark>&nbsp;estar\u00e1 disponible en la plataforma HBO Max a partir del <strong>pr\u00f3ximo jueves, 24 de febrero<\/strong>. El mismo d\u00eda que se cumplen 39 a\u00f1os desde el nombramiento de Carlos como entrenador de la Selecci\u00f3n Argentina.<\/p>\n<div class=\"sp__Normal htmlLibre\">\n<div class=\"embed-responsive-c\" readability=\"6.5931034482759\">\n<blockquote class=\"twitter-tweet\" readability=\"7.4172413793103\">\n<p lang=\"es\" dir=\"ltr\">Del llanto a la risa hay un paso nada m\u00e1s. No lo decimos nosotros; lo dice el Doctor. Prep\u00e1rate para el llanto, la risa y la emoci\u00f3n: <a href=\"https:\/\/twitter.com\/hashtag\/Bilardo?src=hash&amp;ref_src=twsrc%5Etfw\">#Bilardo<\/a>, el Doctor del F\u00fatbol. Estreno el 24 de febrero por HBO Max. <a href=\"https:\/\/t.co\/ntAxqCrOAP\">pic.twitter.com\/ntAxqCrOAP<\/a><\/p>\n<p>\u2014 HBO Max Latinoam\u00e9rica (@HBOMaxLA) <a href=\"https:\/\/twitter.com\/HBOMaxLA\/status\/1491819324885114883?ref_src=twsrc%5Etfw\">February 10, 2022<\/a><\/p><\/blockquote><\/div><\/div>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/estudiantes\/andujar-citado-declaracion-reaccion_0_ZJNqzj5xq2.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Andujar, citado a declarar\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-16.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/racing\/cardona-gol-fallado-racing-defensa_0_11V2n69GoW.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Cardona, del ins\u00f3lito gol errado al penal al \u00e1ngulo\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/todo-lo-que-tenes-que-saber-de-la-nueva-serie-de-bilardo-17.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El jueves 24 de febrero se estrena en HBO Max Bilardo: el Doctor del F\u00fatbol, la nueva serie sobre la vida Carlos Salvador Bilardo. Un documental dividido en cuatro episodios de 45 minutos que repasa la etapa del Narig\u00f3n como entrenador de la Selecci\u00f3n Argentina. Pero no todo es f\u00fatbol. Tambi\u00e9n se sumerge en su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37259,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37258"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=37258"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37258\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/37259"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=37258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=37258"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=37258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}