{"id":37199,"date":"2022-02-17T00:09:11","date_gmt":"2022-02-17T00:09:11","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/river-partidos-copa-liga-profesional-libertadores-gallardo_0_XOHn6mSpHN.html"},"modified":"2022-02-17T00:09:11","modified_gmt":"2022-02-17T00:09:11","slug":"2022-los-partidos-que-se-le-vienen-a-river","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2022\/02\/17\/2022-los-partidos-que-se-le-vienen-a-river\/","title":{"rendered":"2022: Los partidos que se le vienen a River"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/2022-los-partidos-que-se-le-vienen-a-river.jpg\"><\/p>\n<div readability=\"29.6\">\n<p><h2>El fixture del equipo de Marcelo Gallardo: calendario, d\u00edas, horarios y TV para que te agendes.<\/h2>\n<\/p>\n<div class=\"breadcrumb col-lg-6 col-md-12 col-sm-12 col-xs-12\">\n<span class=\"publishedDate\"><br \/>\n16\/02\/2022 21:09<br \/>\n<\/span> <span class=\"modificatedDate\"><br \/>\nActualizado al 16\/02\/2022 21:27<br \/>\n<\/span>\n<\/div><\/div>\n<div readability=\"78.071643071643\">\n<p>\u00bfCu\u00e1ndo juega <strong><a alt=\"river-plate\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" target=\"_blank\" title=\"river-plate\" rel=\"noopener noreferrer\">River<\/a><\/strong>? Esa pregunta que te anda dando vueltas por la cabeza la ten\u00e9s siempre ac\u00e1. Porque <strong>Ol\u00e9 <\/strong>te presenta los pr\u00f3ximos partidos del equipo de Marcelo Gallardo en las distintas competencias en las que se encuentra participando: la <strong><a alt=\"copa-argentina\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/copa-argentina.html\" target=\"_blank\" title=\"copa-argentina\" rel=\"noopener noreferrer\">Copa Argentina<\/a><\/strong>, la <a alt=\"copa-de-la-liga-profesional-de\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/copa-de-la-liga-profesional-de.html\" target=\"_blank\" title=\"copa-de-la-liga-profesional-de\" rel=\"noopener noreferrer\"><strong>Copa de la Liga Profesional<\/strong> <\/a>y la <strong><a alt=\"copa-libertadores\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" target=\"_blank\" title=\"copa-libertadores\" rel=\"noopener noreferrer\">Copa CONMEBOL Libertadores<\/a><\/strong>.<\/p>\n<p><strong>FECHA A CONFIRMAR<\/strong> &#8211; Laferrere (N) &#8211; Copa Argentina<\/p>\n<p>20 de febrero, 21.30&nbsp;&#8211; Newell&#8217;s (V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>27 de febrero, 19.15&nbsp;&#8211; Racing (L) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>5 de marzo, 17.00 &#8211; San Lorenzo (V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>13 de marzo &#8211; Gimnasia LP (L) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>20 de marzo &#8211; Boca (L) &#8211; Copa de la Liga Profesional de F\u00fatbol (Interzonal)<\/p>\n<p><mark>23 de marzo &#8211; Sorteo Copa Libertadores de Am\u00e9rica &#8211; Fase de grupos<\/mark><\/p>\n<div class=\"sp__Normal\">\n<div class=\"image-embeb image-trigger\" readability=\"6\">\n<picture><source media=\"(min-width: 720px)\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/2022-los-partidos-que-se-le-vienen-a-river-2.jpg\"><img itemprop=\"image\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/2022-los-partidos-que-se-le-vienen-a-river-2.jpg\" loading=\"lazy\" alt=\"En Luque se celebrar\u00e1 el sorteo de la fase de Grupos de la Copa Libertadores de Am\u00e9rica.\">\n<\/picture><figcaption readability=\"2\">\n<p>En Luque se celebrar\u00e1 el sorteo de la fase de Grupos de la Copa Libertadores de Am\u00e9rica.\n<\/p>\n<\/figcaption><\/div>\n<\/div>\n<p>3 de abril &#8211; Defensa y Justicia (V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>Semana del 6 de abril &#8211; Primera fecha fase de grupos de la Copa Libertadores<\/p>\n<p>10 de abril &#8211; Argentinos Juniors (L) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>Semana del 13 de abril &#8211; Segunda fecha fase de grupos de la Copa Libertadores<\/p>\n<p>17 de abril &#8211; Banfield&nbsp;(V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>20 de abril &#8211; Talleres (V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>24 de abril &#8211; Atl\u00e9tico Tucum\u00e1n (L) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>Semana del 27 de abril &#8211; Tercera fecha fase de grupos de la Copa Libertadores<\/p>\n<p>30 de abril &#8211; Sarmiento de Jun\u00edn (V) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>Semana del 4 de mayo&nbsp;&#8211; Cuarta&nbsp;fecha fase de grupos de la Copa Libertadores<\/p>\n<p>8 de mayo &#8211; Platense (L) &#8211; Copa de la Liga Profesional de F\u00fatbol<\/p>\n<p>11 de mayo &#8211; Cuartos de final de la Copa de la Liga Profesional de F\u00fatbol (* En caso de avanzar)<\/p>\n<p>15 de mayo &#8211; Semifinal de la Copa de la Liga Profesional de F\u00fatbol (* En caso de avanzar)<\/p>\n<p>Semana del 18 de mayo &#8211; Quinta fecha fase de grupos de la Copa Libertadores<\/p>\n<p>22 de mayo &#8211; Final de la Copa de la Liga Profesional de F\u00fatbol (* En caso de avanzar)<\/p>\n<p>Semana del 25 de mayo &#8211; Sexta fecha fase de grupos de la Copa Libertadores<\/p>\n<div class=\"sp__SM\">\n<div class=\"content-new \">\n<span class=\"tit-mobile\">Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<div class=\"mg\">\n<div class=\"wrap-figure\">\n<picture>\n<a href=\"https:\/\/www.ole.com.ar\/river-plate\/titulos-internacionales-gano-river_0_bRbuyIwt3.html\" target=\"_self\" rel=\"noopener noreferrer\"><br \/>\n<img class=\"img-responsive\" alt=\"Todos los t\u00edtulos internacionales que gan\u00f3 River\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2022\/02\/2022-los-partidos-que-se-le-vienen-a-river-3.jpg\" loading=\"lazy\"><br \/>\n<\/a>\n<\/picture>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El fixture del equipo de Marcelo Gallardo: calendario, d\u00edas, horarios y TV para que te agendes. 16\/02\/2022 21:09 Actualizado al 16\/02\/2022 21:27 \u00bfCu\u00e1ndo juega River? Esa pregunta que te anda dando vueltas por la cabeza la ten\u00e9s siempre ac\u00e1. Porque Ol\u00e9 te presenta los pr\u00f3ximos partidos del equipo de Marcelo Gallardo en las distintas competencias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37200,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37199"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=37199"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/37199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/37200"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=37199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=37199"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=37199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}