{"id":34170,"date":"2021-12-13T14:28:00","date_gmt":"2021-12-13T14:28:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2021\/12\/13\/psg-de-lionel-messi-jugara-contra-real-madrid-en-octavos-de-la-liga-de-campeones\/"},"modified":"2021-12-13T14:28:00","modified_gmt":"2021-12-13T14:28:00","slug":"psg-de-lionel-messi-jugara-contra-real-madrid-en-octavos-de-la-liga-de-campeones","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/12\/13\/psg-de-lionel-messi-jugara-contra-real-madrid-en-octavos-de-la-liga-de-campeones\/","title":{"rendered":"PSG de Lionel Messi jugar\u00e1 contra Real Madrid en octavos de la Liga de Campeones"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/12\/psg-de-lionel-messi-jugara-contra-real-madrid-en-octavos-de-la-liga-de-campeones.jpg\"><\/p>\n<figure class=\"mb-3\"><img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/12\/psg-de-lionel-messi-jugara-contra-real-madrid-en-octavos-de-la-liga-de-campeones-2.jpg\" width=\"100%\" height=\"100%\" alt=\"La Champions tuvo un sorteo frustrado \"><figcaption> La Champions tuvo un sorteo frustrado. <\/figcaption><\/figure>\n<p>Paris Saint Germain, el equipo de Lionel Messi, jugar\u00e1 contra Real Madrid, m\u00e1ximo ganador de la Liga de Campeones de Europa, en los octavos de final luego de la repetici\u00f3n del sorteo tras un grosero error de la UEFA.<\/p>\n<p>Los otros cruces de octavos de final ser\u00e1n:<\/p>\n<p>Salzburgo (Austria)- Bayern M\u00fanich (Alemania)<\/p>\n<p>Sporting Lisboa (Portugal)- Manchester City (Inglaterra)<\/p>\n<p>Benfica (Portugal)- Ajax (Pa\u00edses Bajos)<\/p>\n<p>Chelsea (Inglaterra)- Lille (Francia)<\/p>\n<p>Atl\u00e9tico de Madrid (Espa\u00f1a)- Manchester United (Inglaterra)<\/p>\n<p>Villarreal (Espa\u00f1a)- Juventus (Italia)<\/p>\n<p>Inter (Italia)- Liverpool (Inglaterra)<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"7.5866261398176\">\n<p lang=\"es\" dir=\"ltr\">A ra\u00edz de un problema t\u00e9cnico con el software de un proveedor de servicios externo que da instrucciones a los oficiales sobre qu\u00e9 equipos son elegibles para jugar entre s\u00ed, se produjo un error material en el sorteo de los octavos de final de la UEFA Champions League.<\/p>\n<p>\u2014 Liga de Campeones (@LigadeCampeones) <a href=\"https:\/\/twitter.com\/LigadeCampeones\/status\/1470375632106401792?ref_src=twsrc%5Etfw\">December 13, 2021<\/a><\/p><\/blockquote>\n<p>La UEFA tuvo que repetir el sorteo de los octavos de final de la Liga de Campeones de Europa, por un grosero error en el procedimiento.<\/p>\n<p>\u00abTras un problema t\u00e9cnico con el software de un proveedor de servicios externo que instruye a los \u00e1rbitros sobre qu\u00e9 equipos son elegibles para jugar entre s\u00ed, se produjo un error en el sorteo de los octavos de final de la UEFA Champions League\u00bb, hab\u00eda informado la m\u00e1xima entidad europea en su cuenta oficial de Twitter.<\/p>\n<p>El primer sorteo fue declarado \u00abdesierto\u00bb y luego se repiti\u00f3 desde cero con los mismos bombos.<\/p>\n<p>La UEFA tuvo que dar marcha atr\u00e1s al sorteo ante el reclamo de Atl\u00e9tico de Madrid.<\/p>\n<p>\u00abEstamos en conversaciones con UEFA para pedir explicaciones y una soluci\u00f3n despu\u00e9s de los errores cometidos en el sorteo de octavos de Champions League\u00bb, inform\u00f3 el club madrile\u00f1o en sus cuentas oficiales, una hora despu\u00e9s del evento realizado en Nyon, Suiza.<\/p>\n<blockquote class=\"twitter-tweet\" readability=\"3.0072463768116\">\n<p lang=\"es\" dir=\"ltr\">\ud83c\uddeb\ud83c\uddf7 Paris vs Real Madrid \ud83c\uddea\ud83c\uddf8<a href=\"https:\/\/twitter.com\/hashtag\/UCLdraw?src=hash&amp;ref_src=twsrc%5Etfw\">#UCLdraw<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/hsFimDjv1P\">pic.twitter.com\/hsFimDjv1P<\/a><\/p>\n<p>\u2014 Liga de Campeones (@LigadeCampeones) <a href=\"https:\/\/twitter.com\/LigadeCampeones\/status\/1470397267924430852?ref_src=twsrc%5Etfw\">December 13, 2021<\/a><\/p><\/blockquote>\n<p>El equipo del \u00abCholo\u00bb Simeone hab\u00eda salido como rival del poderoso alem\u00e1n Bayern M\u00fanich pero desde la dirigencia \u00abcolchonera\u00bb r\u00e1pidamente se quejaron del procedimiento.<\/p>\n<p>El primer error de la UEFA fue cuando se sorte\u00f3 el rival de Villarreal y sali\u00f3 Manchester United, al que ya se hab\u00eda enfrentado en la fase de grupos.<\/p>\n<p>Luego, al momento de Atl\u00e9tico de Madrid, el oficial de la UEFA Michael Heselschwerdt cometi\u00f3 dos errores casi en simult\u00e1neo.<br \/>Primero, se sac\u00f3 la bolilla de Atl\u00e9tico de Madrid y deb\u00eda colocarse en el bombo de los cabezas de serie: Manchester City, Ajax,<br \/>Bayern, Manchester United, Lille y Juventus.<\/p>\n<p>Pero el oficial de UEFA se equivoc\u00f3 dos veces ya que puso a Liverpool, que no pod\u00eda tocarle al Atl\u00e9tico, y despu\u00e9s, se olvid\u00f3 de la bolilla de Manchester United, que luego sali\u00f3 como rival de Par\u00eds Saint Germain. Finalmente, la bolilla que sali\u00f3 fue la de Bayern de M\u00fanich.<\/p>\n<p>Luego de unos segundos de tensi\u00f3n, se dijo que ese cruce no val\u00eda y sacaron otra bolilla, en este caso de Manchester City.<\/p>\n<p>El propio Giorgio Marchetti, jefe de competiciones de la UEFA, tard\u00f3 en reaccionar, se dio cuenta que era correcto y se disculp\u00f3 por el error pero no detuvo el sorteo.<\/p>\n<p>Los emparejamientos de octavos de final hab\u00edan quedado de la siguiente manera, con el cruce entre PSG (Lionel Messi) y Manchester United (Cristiano Ronald) como principal atracci\u00f3n:<\/p>\n<p>Benfica (Portugal)-Real Madrid (Espa\u00f1a)<\/p>\n<p>Atl\u00e9tico de Madrid (Espa\u00f1a)-Bayern M\u00fanich (Alemania)<\/p>\n<p>Inter (Italia)-Ajax (Pa\u00edses Bajos)<\/p>\n<p>Chelsea (Inglaterra)-Lille (Francia)<\/p>\n<p>Villarreal (Espa\u00f1a)-Manchester City (Inglaterra)<\/p>\n<p>Salzburgo (Austria)-Liverpool (Inglaterra)<\/p>\n<p>Sporting Lisboa (Portugal)-Juventus (Italia)<\/p>\n<p>Paris Saint Germain (Francia)-Manchester United (Inglaterra).<\/p>\n<h2 class>Barcelona y Napoli se enfrentar\u00e1n en los 16avos de final de la Liga de Europa<\/h2>\n<p>Barcelona, que tras la partida de Lionel Messi qued\u00f3 eliminado en la fase de grupos de la Liga de Campeones, se enfrentar\u00e1 a Napoli en los 16avos de final de la Liga de Europa.<\/p>\n<p>El sorteo realizado este lunes a la ma\u00f1ana en la sede de la UEFA en Nyon, Suiza, determin\u00f3 un cruce entre los clubes europeos donde dej\u00f3 su huella Diego Armando Maradona.<\/p>\n<p>Tras 21 a\u00f1os, Barcelona qued\u00f3 eliminado de la fase de grupos de la Liga de Campeones y, por primera vez, disputar\u00e1 el segundo torneo europeo bajo el nombre y formato que cambi\u00f3 en la temporada 2009\/10.<\/p>\n<p>Su rival ser\u00e1 Napoli, uno de los animadores de la Serie A de Italia, y el club donde recal\u00f3 Maradona luego de su experiencia en el conjunto \u00abcul\u00e9\u00bb.<\/p>\n<p>El primer partido ser\u00e1 en el estadio Diego Armando Maradona el pr\u00f3ximo 17 de febrero y la revancha una semana despu\u00e9s en el Camp Nou.<\/p>\n<p>Los otros cruces de los 16avos de final de la Liga de Europa ser\u00e1n: Sevilla (Espa\u00f1a)- Dinamo Zagreb (Croacia); Atalanta (Italia)-Olympiacos (Grecia); Leipzig (Alemania)-Real Sociedad (Espa\u00f1a); Zenit San Petersburgo (Rusia)-Betis (Espa\u00f1a); Borussia Dortmund (Alemania)- Glasgow Rangers (Escocia); Sheriff (Moldavia)-Braga (Portugal); Porto (Portugal)-Lazio (Italia). <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Champions tuvo un sorteo frustrado. Paris Saint Germain, el equipo de Lionel Messi, jugar\u00e1 contra Real Madrid, m\u00e1ximo ganador de la Liga de Campeones de Europa, en los octavos de final luego de la repetici\u00f3n del sorteo tras un grosero error de la UEFA. Los otros cruces de octavos de final ser\u00e1n: Salzburgo (Austria)- [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34171,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/34170"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=34170"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/34170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/34171"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=34170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=34170"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=34170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}