{"id":28871,"date":"2021-09-09T01:22:00","date_gmt":"2021-09-09T01:22:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2021\/09\/09\/el-presidente-mantuvo-un-encuentro-con-empresarios-marplatenses\/"},"modified":"2021-09-09T01:22:00","modified_gmt":"2021-09-09T01:22:00","slug":"el-presidente-mantuvo-un-encuentro-con-empresarios-marplatenses","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/09\/09\/el-presidente-mantuvo-un-encuentro-con-empresarios-marplatenses\/","title":{"rendered":"El Presidente mantuvo un encuentro con empresarios marplatenses"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/09\/el-presidente-mantuvo-un-encuentro-con-empresarios-marplatenses.jpg\"><\/p>\n<div class=\"image\" id=\"image\" readability=\"7\"> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/09\/el-presidente-mantuvo-un-encuentro-con-empresarios-marplatenses-2.jpg\" alt=\"El presidente recalc\u00f3 que &quot;la actividad tur\u00edstica&quot; es para el Gobierno &quot;doblemente importante&quot;\" title=\"El presidente recalc\u00f3 que &quot;la actividad tur\u00edstica&quot; es para el Gobierno &quot;doblemente importante&quot;\"><\/p>\n<p>El presidente recalc\u00f3 que \u00abla actividad tur\u00edstica\u00bb es para el Gobierno \u00abdoblemente importante\u00bb<\/p>\n<\/div>\n<p>El presidente Alberto Fern\u00e1ndez mantuvo este mi\u00e9rcoles un encuentro con empresarios de la ciudad de Mar de Plata, y asegur\u00f3 que har\u00e1 todo lo posible \u00abpara que la Argentina tenga la mejor temporada de turismo en el verano\u00bb, informaron fuentes oficiales.<\/p>\n<p>Tras encabezar el acto por el cierre de la campa\u00f1a bonaerense del Frente de Todos (FDT) de cara a las primarias abiertas, simult\u00e1neas y obligatorias en la ciudad balnearia, <strong>Fern\u00e1ndez se reuni\u00f3 en el Hotel 13 de Julio del Sindicato de Luz y Fuerza con referentes de distintos sectores productivos para analizar el impacto de las medidas del Gobierno nacional para impulsar la reactivaci\u00f3n de la econom\u00eda.<\/strong><\/p>\n<p><strong>\u00abVoy a hacer todo lo que est\u00e9 a mi alcance para que la Argentina tenga la mejor temporada de turismo en el verano\u00bb<\/strong>, dijo el presidente, quien resalt\u00f3 que las administraciones nacionales de N\u00e9stor y Cristina Kirchner y la provincial de Daniel Scioli pusieron a la ciudad .\u00bbcomo centro tur\u00edstico de la Argentina\u00bb.<\/p>\n<p>El mandatario reconoci\u00f3 que <strong>\u00abuna de las ciudades m\u00e1s golpeadas por la pandemia fue Mar del Plata\u00bb<\/strong> y realt\u00f3, en ese sentido, que <strong>su gobierno fue \u00abpionero\u00bb con los ATP que \u00abgran parte del sector hotelero y gastron\u00f3mico us\u00f3\u00bb.<\/strong><\/p>\n<p>Fern\u00e1ndez tambi\u00e9n recalc\u00f3 que \u00ab<strong>la actividad tur\u00edstica\u00bb es para el Gobierno \u00abdoblemente importante porque b\u00e1sicamente evita la salida de d\u00f3lares del pa\u00eds\u00bb, y dijo que \u00abcuanto m\u00e1s turismo\u00bb haya \u00abinternamente, menos d\u00f3lares se van al exterior\u00bb.<\/strong><\/p>\n<p>Claudia Alvarez Arg\u00fcelles, CEO de Alvarez Arg\u00fcelles Hoteles y una de las referentes del sector a nivel nacional, agradeci\u00f3 durante el encuentro al Gobierno por los Repro que les \u00abpermiti\u00f3 mantener todos los empleos\u00bb.<\/p>\n<p>El empresario gastron\u00f3mico Hern\u00e1n Szkrohal, rese\u00f1\u00f3 que en agosto recuperaron la actividad y que \u00abese cambio se empez\u00f3 a notar a partir de la vacunaci\u00f3n masiva\u00bb.<\/p>\n<p><strong>\u00abQueremos recuperar esta ciudad como marca y nos sentimos muy apoyados por la provincia y por el Gobierno\u00bb,<\/strong> dijo.<\/p>\n<p>En el encuentro participaron tambi\u00e9n el tesorero de la Uni\u00f3n del Comercio, la Industria y la Producci\u00f3n local, Eduardo Mayer; el presidente de la Asociaci\u00f3n Empresaria Hotelero Gastron\u00f3mica de Mar del Plata y Zona de Influencia, Jes\u00fas Osorno; Carlos Philapsidis, de la C\u00e1mara de Balnearios y Recreaci\u00f3n, y el presidente de la C\u00e1mara de Empresarios de Balnearios, Restaurantes y Afines, Pablo Philapsidis, entre otros.<\/p>\n<p>Estuvieron adem\u00e1s la titular de la Administraci\u00f3n Nacional de Seguridad Social, Fernanda Raverta, y los precandidatos a concejales del FDT en General Pueyrredon, Virginia S\u00edvori, Ariel Ciano y Mariana Cuesta. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente recalc\u00f3 que \u00abla actividad tur\u00edstica\u00bb es para el Gobierno \u00abdoblemente importante\u00bb El presidente Alberto Fern\u00e1ndez mantuvo este mi\u00e9rcoles un encuentro con empresarios de la ciudad de Mar de Plata, y asegur\u00f3 que har\u00e1 todo lo posible \u00abpara que la Argentina tenga la mejor temporada de turismo en el verano\u00bb, informaron fuentes oficiales. Tras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28872,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/28871"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=28871"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/28871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/28872"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=28871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=28871"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=28871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}