{"id":27169,"date":"2021-08-15T03:02:00","date_gmt":"2021-08-15T03:02:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2021\/08\/15\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america\/"},"modified":"2021-08-15T03:02:00","modified_gmt":"2021-08-15T03:02:00","slug":"una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/08\/15\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america\/","title":{"rendered":"Una ni\u00f1era guaran\u00ed en Yapey\u00fa, la revoluci\u00f3n francesa y el sue\u00f1o de emancipar Am\u00e9rica"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/08\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america.jpg\"><\/p>\n<div class=\"image\" id=\"image\" readability=\"11\"> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/08\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america-2.jpg\" alt=\"Felipe Pigna cuenta que \u201ca los 11 a\u00f1os San Mart\u00edn ingresa al Ej\u00e9rcito, algo que era habitual para la \u00e9poca. Ya a los 13 est\u00e1 combatiendo en Argelia y Marruecos, posesiones espa\u00f1olas en el norte de \u00c1frica&quot;.\" title=\"Felipe Pigna cuenta que \u201ca los 11 a\u00f1os San Mart\u00edn ingresa al Ej\u00e9rcito, algo que era habitual para la \u00e9poca. Ya a los 13 est\u00e1 combatiendo en Argelia y Marruecos, posesiones espa\u00f1olas en el norte de \u00c1frica&quot;.\"><\/p>\n<p>Felipe Pigna cuenta que \u201ca los 11 a\u00f1os San Mart\u00edn ingresa al Ej\u00e9rcito, algo que era habitual para la \u00e9poca. Ya a los 13 est\u00e1 combatiendo en Argelia y Marruecos, posesiones espa\u00f1olas en el norte de \u00c1frica\u00bb.<\/p>\n<\/div>\n<p>Chog\u00fc\u00ed amaba las aves. Imitaba sus cantos tocando la flauta en un claro de la selva. Ellas respond\u00edan con la melod\u00eda de sus trinos. Un d\u00eda un picaflor se acerc\u00f3 desesperado. Sus pichones estaban en lo alto de un \u00e1rbol invadido por \u201chormigas asesinas\u201d. El ni\u00f1o corri\u00f3 en su auxilio. Trep\u00f3 al \u00e1rbol y lleg\u00f3 hasta el nido, que dej\u00f3 caer sobre la hierba. Las cr\u00edas se salvaron, pero las hormigas aguijonearon su cuerpo: <strong>Chog\u00fc\u00ed call\u00f3 al vac\u00edo y muri\u00f3. <\/strong>Todas aves del bosque rodearon el cuerpo y lo cubrieron de flores de color azul, las favoritas del ni\u00f1o. Tambi\u00e9n pidieron a Tup\u00e1, creador de la luz y el universo, que lo salvara. De la monta\u00f1a de flores levant\u00f3 vuelo un p\u00e1jaro azul cantando \u201cchog\u00fc\u00ed, chog\u00fc\u00ed\u201d, que desde entonces juega en los naranjales del Litoral y se confunde con el cielo.&nbsp;<\/p>\n<p>Probablemente Rosa Guar\u00fa contar\u00e1 esta leyenda guaran\u00ed a Jos\u00e9 Francisco, que al igual que Chog\u00fc\u00ed, amaba a las aves y a su canto. <strong>Jos\u00e9 era el menor de cinco hermanos y hab\u00eda nacido all\u00ed, en Nuestra Se\u00f1ora de los Tres Reyes Mayos de Yapey\u00fa<\/strong>, hoy provincia de Corrientes, <strong>el 25 de febrero de 1778<\/strong>, hijo del capit\u00e1n del ej\u00e9rcito espa\u00f1ol Juan de San Mart\u00edn y G\u00f3mez y de Gregoria Matorras.<\/p>\n<p>Rosa era la ni\u00f1era de Jos\u00e9. Fue ella quien entre cantos, historias y cuidados lo acompa\u00f1\u00f3 en sus primeros pasos. Tambi\u00e9n quien le ense\u00f1\u00f3 la lengua de su pueblo, que tanto se parece a la m\u00fasica. <strong>El futuro Libertador de Am\u00e9rica se interes\u00f3 as\u00ed por los guaran\u00edes<\/strong>, se acerc\u00f3 a la naturaleza sin intentar conquistarla, se aliment\u00f3 de aquellos cuidados maternales.<\/p>\n<p>\u201cRosa Guar\u00fa era guaran\u00ed e influy\u00f3 en el inter\u00e9s de San Mart\u00edn por los pueblos originarios, por su cultura, y va a tener siempre un gran respeto por ellos\u201d, cuenta a Tel\u00e1m <strong>el historiador Felipe Pigna<\/strong>, quien destaca el papel que jug\u00f3 aquella mujer india en los primeros a\u00f1os de vida del Padre de la Patria.<\/p>\n<p>\u201cAdem\u00e1s de su importancia en la primera educaci\u00f3n, de su pertenencia a los pueblos originarios, Rosa fue quien le ense\u00f1\u00f3 a San Mart\u00edn a distinguir el canto de los p\u00e1jaros, a conocer la lengua guaran\u00ed, y todo eso qued\u00f3 grabado en \u00e9l para siempre\u201d, agrega.<\/p>\n<p><strong>Rosa Guar\u00fa, incluso, pudo haber sido la verdadera madre de San Mart\u00edn. Al menos eso creen algunos historiadores.<\/strong> \u201cEs una hip\u00f3tesis que no se puede confirmar sin un ADN, pero que circul\u00f3 con mucha fuerza en los a\u00f1os 90 y se basa en las revelaciones de Joaquina de Alvear, hija de Carlos Mar\u00eda de Alvear, quien dec\u00eda que era la sobrina de San Mart\u00edn\u201d, detalla Pigna.<\/p>\n<p>Seg\u00fan el investigador \u201cestos dichos dan a entender que tanto Carlos de Alvear como San Mart\u00edn eran hijos de Diego de Alvear, quien efectivamente pas\u00f3 por Yapey\u00fa en aquellos momentos, un a\u00f1o antes de que naciera San Mart\u00edn, por lo que hay algunos indicios de que <strong>pudiera ser hijo de Diego de Alvear y Rosa Guar\u00fa<\/strong>. Llama la atenci\u00f3n tambi\u00e9n que el \u00fanico San Mart\u00edn que tiene ni\u00f1era estando en Yapey\u00fa sea Jos\u00e9\u201d.<\/p>\n<p> <iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/2Z1k7_SKHfA?wmode=transparent&amp;showinfo=0&amp;autohide=1&amp;rel=0\" frameborder=\"0\" allowfullscreen>[embedded content]<\/iframe> <\/p>\n<p>\u00abChamam\u00e9 del Gur\u00ed Libertador\u00bb<\/p>\n<p>Libertad, igualdad, fraternidad<\/p>\n<p>Despu\u00e9s de un breve paso de un a\u00f1o por Buenos Aires, donde Jos\u00e9 tuvo una primera escolarizaci\u00f3n, <strong>los San Mart\u00edn parten hacia Espa\u00f1a. Jos\u00e9 Francisco ten\u00eda s\u00f3lo cinco a\u00f1os<\/strong> y pronto seguir\u00e1 los pasos de su padre.<\/p>\n<p>La familia se instala primero en Madrid, luego en M\u00e1laga. El 15 de julio de 1789, al d\u00eda siguiente de que en Par\u00eds estallara la Revoluci\u00f3n Francesa, es aceptado como cadete en el Regimiento de Infanter\u00eda de Murcia.<\/p>\n<p><strong>\u201cA los 11 a\u00f1os ingresa al Ej\u00e9rcito, algo que era habitual para la \u00e9poca\u201d,<\/strong> comenta Pigna, y agrega que \u201cya a los 13 est\u00e1 combatiendo en Argelia y Marruecos, posesiones espa\u00f1olas en el norte de \u00c1frica, donde integr\u00f3 el cuerpo de Granaderos, que eran quienes manejaban los explosivos, las granadas\u201d.<\/p>\n<p>Pertenecer al cuerpo de Granaderos era voluntario, ya que sus misiones eran muy arriesgas. San Martin recibe los primeros ascensos y reconocimientos. Ser\u00e1 ascendido a teniente coronel y condecorado con la medalla de oro por su actuaci\u00f3n en la batalla de Bail\u00e9n el 19 de julio de 1808. <strong>\u201cPermanecer\u00e1 como granadero hasta los 15 a\u00f1os<\/strong>, demostrando mucho coraje, destac\u00e1ndose entre sus compa\u00f1eros\u201d, subraya el autor de \u201cLos mitos de la historia argentina\u201d.<br \/>&nbsp;&nbsp;&nbsp;<br \/>Pero Europa comenzaba a arder. Y la primera chispa se encender\u00e1 en Par\u00eds. \u201cPara San Mart\u00edn fueron muy importantes las ideas de la Revoluci\u00f3n Francesa, que conoce por su inter\u00e9s por la pol\u00edtica. \u00c9l era un liberal en el buen sentido de la palabra, que en la Argentina nos suena un poco rara despu\u00e9s de ciertas experiencias. Los liberales de fines del siglo XVIII y comienzos del XIX era gente que <strong>adher\u00eda a los ideales de libertad, igualdad y fraternidad de la Revoluci\u00f3n de 1789<\/strong>\u201d.<\/p>\n<blockquote readability=\"7\">\n<p>\u201cSan Mart\u00edn tiene una especial admiraci\u00f3n por Voltaire, lo que se nota en las recompras de su biblioteca\u201d<span class=\"comilla\">\u201d<\/span><\/p>\n<\/blockquote>\n<p>Adem\u00e1s, el Ej\u00e9rcito espa\u00f1ol tiene un alto nivel de politizaci\u00f3n, que aumentar\u00e1 con la invasi\u00f3n francesa en 1808. \u201cEsto a San Mart\u00edn le permite, por ejemplo, estar un tiempo en Marsella, donde <strong>compra una gran cantidad de libros prohibidos en Espa\u00f1a <\/strong>por la Inquisici\u00f3n, libros de ide\u00f3logos de la Revoluci\u00f3n como Voltaire, Rousseau o Montesquie\u201d, enumera Pigna.<\/p>\n<p>\u201c<strong>San Mart\u00edn es un gran lector de estos pensadores. <\/strong>Tiene una especial admiraci\u00f3n por Voltaire, lo que se nota en las recompras de su biblioteca. Fue un gran donador de bibliotecas. Funda la de Mendoza, la de Santiago, la de Lima. Va recomprando los libros que para \u00e9l son imprescindibles y siempre est\u00e1, por ejemplo, la \u2018Enciclopedia de las Ciencias Filos\u00f3ficas\u2019 de Voltaire. Tambi\u00e9n \u2018El Quijote\u2019, que es un libro que lo apasiona\u201d, agrega.<\/p>\n<p>Las lecturas sobre \u201clas nuevas ideas\u201d, la \u00e9pica que encarnaba el Romanticismo en boga en la primera parte del siglo XIX europeo y el triunfo de la Revoluci\u00f3n Francesa influyeron muy fuertemente en San Mart\u00edn. Tambi\u00e9n lo hicieron en otros patriotas latinoamericanos como Andr\u00e9s Bello, Francisco de Miranda, Bernardo O\u2019Higgins, Sim\u00f3n Bol\u00edvar, con quienes fundar\u00e1 la logia de C\u00e1diz y se juramentar\u00e1 volver a Am\u00e9rica para luchar por su liberaci\u00f3n.<\/p>\n<p>Con Napole\u00f3n, contra Napole\u00f3n<\/p>\n<p>En enero de 1808, las tropas de Napole\u00f3n invaden Portugal y despu\u00e9s el resto de la pen\u00ednsula Ib\u00e9rica. Carlos V entrega el reino de Espa\u00f1a a su favorito Manuel Godoy y \u00e9ste a Fernando VII, quien finalmente dimitir\u00e1 en favor de Jos\u00e9 Bonaparte.\u2028\u2028 Pero&nbsp;el pueblo espa\u00f1ol organiza la resistencia. Ser\u00e1&nbsp;a trav\u00e9s de juntas de gobierno instaladas en las principales ciudades, coordinadas por la de Sevilla. Desde las juntas, en unas m\u00e1s que otras, <strong>se impulsar\u00e1 tambi\u00e9n la democratizaci\u00f3n del reino. <\/strong>Y el fin del absolutismo.\u2028\u2028Adem\u00e1s, ser\u00e1n la inspiraci\u00f3n de los patriotas americanos. Y el atajo hacia la libertad en las colonias. Sin embargo Napole\u00f3n, quien hab\u00eda sido una inspiraci\u00f3n, en tanto portador de los ideales de la Revoluci\u00f3n y primer internacionalista, se convertir\u00e1 en un problema para los partidarios de un orden nuevo.<\/p>\n<p>\u201cSi bien Napole\u00f3n representa los ideales de la Revoluci\u00f3n, en el caso de Espa\u00f1a act\u00faa como un opresor\u201d, sentencia Pigna. \u201cUna parte importante de la intelectualidad europea admir\u00f3 profundamente a Napole\u00f3n hasta el punto de crisis de su popularidad, que es cuando se autoproclama emperador\u201d, detalla.<\/p>\n<p>Y recuerda:<strong> \u201cEsto vale, por ejemplo, para Beethoven, que era un gran admirador de Napole\u00f3n al punto de que le dedica la Tercera Sinfon\u00eda,<\/strong> cuya dedicatoria borrar\u00e1 con furia porque entiende que traicion\u00f3 los ideales revolucionarios al convertirse en emperador\u201d.<\/p>\n<div class=\"image\" id=\"image\" readability=\"10\"> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/08\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america-3.jpg\" alt=\"&quot;San Mart\u00edn, Protector del Per\u00fa&quot;, acr\u00edlico sobre lienzo (20021) de Diego Manuel Rodr\u00edguez (www.diegomanuel.com.ar)\" title=\"&quot;San Mart\u00edn, Protector del Per\u00fa&quot;, acr\u00edlico sobre lienzo (20021) de Diego Manuel Rodr\u00edguez (www.diegomanuel.com.ar)\"><\/p>\n<p>\u00abSan Mart\u00edn, Protector del Per\u00fa\u00bb, acr\u00edlico sobre lienzo (20021) de Diego Manuel Rodr\u00edguez (www.diegomanuel.com.ar)<\/p>\n<\/div>\n<p>\u201c<strong>Lo mismo le pasa a San Mart\u00edn, que admiraba a Napole\u00f3n<\/strong> pero lo ve actuar con mucha crueldad invadiendo Espa\u00f1a, independientemente de que el rey Fernando VII era un ser despreciable\u201d, subraya el autor de \u201cLa voz del gran jefe. Jos\u00e9 de San Mart\u00edn\u201d.<\/p>\n<p>Pero con la llegada de Bonaparte a Espa\u00f1a estalla tambi\u00e9n la experiencia de las juntas, que permiti\u00f3 sacarse de encima al Virrey Cisneros en Buenos Aires y disparar un tiro por elevaci\u00f3n contra el absolutismo, permitiendo asomar los ideales democr\u00e1ticos.<\/p>\n<p>\u201cLa experiencia espa\u00f1ola de las Juntas es una experiencia muy democr\u00e1tica. <strong>El pueblo espa\u00f1ol quer\u00eda sacarse de encima a Napole\u00f3n<\/strong> y, dentro de ese pueblo, hab\u00eda mucha gente que tambi\u00e9n detestaba el autoritarismo absolutista y pretend\u00eda instaurar una Constituci\u00f3n liberal, como fue la de 1812\u201d, asegura a T\u00e9lam el historiador.&nbsp;Y adiciona: \u201cEsto va a provocar diferentes alzamientos, como el de Rafael del Riego en 1820, que termina <strong>imponi\u00e9ndole a Fernando VII, que hab\u00eda vuelto al trono en 1814, una Constituci\u00f3n liberal\u201d.<\/strong><\/p>\n<p>\u201cEsto es lo que hay que entender cuando se habla de la participaci\u00f3n de San Mart\u00edn en el Ej\u00e9rcito espa\u00f1ol. \u00c9l lo dice claramente: la lucha contra el absolutismo no tiene fronteras y se puede luchar en Europa y se puede luchar en Am\u00e9rica\u201d, concluye.&nbsp;&nbsp;&nbsp;<\/p>\n<p>El agente ingl\u00e9s<\/p>\n<p>El inter\u00e9s de Inglaterra por imponer el libre comercio para favorecer su incipiente industria manufacturera, los procesos independentistas en Am\u00e9rica del Sur y la posterior y funesta participaci\u00f3n inglesa en la regi\u00f3n suelen confundirse, a punto de estimular simplificaciones y minimizar procesos y protagonistas.&nbsp;&nbsp;&nbsp;<\/p>\n<p><strong>\u201cPara los revolucionarios de la \u00e9poca Inglaterra era una suerte de modelo de gobierno<\/strong>, teniendo en cuenta las pocas referencias que hab\u00eda entonces. Voltaire mismo queda maravillado. Cuando estaba en Inglaterra, en el \u00faltimo cuarto del siglo XVIII, hab\u00eda all\u00ed un r\u00e9gimen parlamentario, un rey cada vez m\u00e1s simb\u00f3lico y cierta libertad de prensa, algo que no exist\u00eda en muchos pa\u00edses de Europa\u201d, repasa Pigna.<\/p>\n<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/08\/una-ninera-guarani-en-yapeyu-la-revolucion-francesa-y-el-sueno-de-emancipar-america-4.jpg\" alt=\"El Libertador y la cordillera de los Andes, por Pablo Blasberg.\" title=\"El Libertador y la cordillera de los Andes, por Pablo Blasberg.\"><\/p>\n<p>El Libertador y la cordillera de los Andes, por Pablo Blasberg.<\/p>\n<\/div>\n<p>Aquellas caracter\u00edsticas contrastaban con la opresi\u00f3n, inequidad y ahogo que expresaban las monarqu\u00edas absolutas de la Europa continental. Por ello, para el autor de \u201cLibertadores de Am\u00e9rica\u201d, ese modelo \u201caparec\u00eda como interesante desde el punto de vista pol\u00edtico, con un parlamentarismo fuerte y los grandes debates que se daban en la sociedad, con sus peri\u00f3dicos, sus sociedades secretas, etc\u201d.<\/p>\n<p>Sin embargo, <strong>que Inglaterra fuera un modelo a seguir para muchos latinoamericanos no debe confundirse<\/strong>, seg\u00fan el historiador, \u201ccon ser un agente ingl\u00e9s ni con promover la dependencia de Gran Breta\u00f1a\u201d.&nbsp;&nbsp;<\/p>\n<p>Y ejemplifica con la actitud de San Mart\u00edn cuando en 1815 Carlos Mar\u00eda de Alvear propone la entrega del Virreinato del R\u00edo de la Plata a Gran Breta\u00f1a, desesperado por la inminente ca\u00edda de Napole\u00f3n y frente a las expediciones que empezaba a mandar Fernando VII.<\/p>\n<blockquote readability=\"6\">\n<p>\u201cQue Inglaterra fuera un modelo pol\u00edtico a seguir no significaba ser un agente ingl\u00e9s ni con promover la dependencia\u201d<span class=\"comilla\">\u201d<\/span><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong>\u201cEl Director Supremo Alvear -recuerda Pigna- decide entregarnos a Gran Breta\u00f1a<\/strong> en la famosa misi\u00f3n que le encomienda a Manuel Jos\u00e9 Garc\u00eda ante Lord Strangford, embajador brit\u00e1nico en Brasil. San Mart\u00edn se opone tenazmente a esto. Si hubiera sido un agente ingl\u00e9s le hubiera sido muy sencillo acompa\u00f1ar a Alvear\u201d.<\/p>\n<p>Pero San Mart\u00edn no solo no lo acompa\u00f1\u00f3, sino que promovi\u00f3 \u201cla denuncia de Alvear y la denuncia de traici\u00f3n a la Patria. Esto no significa que no admirara al modelo brit\u00e1nico que aparec\u00eda, junto al americano, como m\u00e1s interesantes desde el punto de vista pol\u00edtico\u201d.&nbsp;<br \/>&nbsp;<\/p>\n<p>De logias y masones<\/p>\n<p>Ante el clima represivo que constitu\u00edan el absolutismo y la Inquisici\u00f3n, y donde el poder terrenal del papado se extend\u00eda mucho m\u00e1s all\u00e1 de las cuestiones espirituales, <strong>conspiradores y revolucionarios se organizaban en secreto y de manera clandestina.&nbsp;<\/strong>Pigna recuerda que \u201chab\u00eda logias de distinto tipo\u201d y que las m\u00e1s importantes eran las logias mas\u00f3nicas, que tuvieron una importante participaci\u00f3n en las revoluciones liberales del siglo XVIII.<\/p>\n<p>\u201cEn la revoluci\u00f3n norteamericana -destaca- toda su plana mayor era mas\u00f3nica y los \u00edconos revolucionarios est\u00e1n plagados de sus s\u00edmbolos, como el d\u00f3lar y esa pir\u00e1mide que es s\u00edmbolo mas\u00f3nico. Ah\u00ed est\u00e1n <strong>Washignton, Jefferson, Adams, todos ellos masones. Otro tanto sucedi\u00f3 con la Revoluci\u00f3n Francesa\u201d.<\/strong><\/p>\n<p>B\u00e1sicamente se trataba de sociedades secretas que<strong> \u201cluchaban contra el absolutismo, contra el poder de la Iglesia Cat\u00f3lica, no contra el poder de la religi\u00f3n<\/strong>, sino contra el poder terrenal de la Iglesia, contra el papado, contra el absolutismo y por la rep\u00fablica, la independencia y la Constituci\u00f3n, que eran los slogans que hab\u00edan surgido en la pionera revoluci\u00f3n norteamericana de 1776\u201d.<\/p>\n<p>Defender estos principios era sin\u00f3nimo de ser mas\u00f3n en las primeras d\u00e9cadas del siglo XIX. Y la forma de organizaci\u00f3n eran las logias, como lo fue <strong>la Logia Lautaro que integrar\u00edan tanto San Mart\u00edn como Manuel Belgrano,<\/strong> adem\u00e1s de muchos otros patriotas latinoamericanos.<\/p>\n<p>\u201cSer mas\u00f3n significaba eso y tener cierta pertenencia, no necesariamente absoluta. San Mart\u00edn es un ejemplo interesante. <strong>Cuando se produce la traici\u00f3n de Alvear rompe con la Logia Lautaro<\/strong>, cosa no frecuente en la masoner\u00eda, y forma su propia logia, tanto en Mendoza como en Santiago y en Lima, desobedeciendo a la logia de Buenos Aires\u201d, relata el estudioso.<\/p>\n<p>Pero todo esto va a empezar a cambiar a medidos del siglo XIX, cuando seg\u00fan Pigna \u201cla masoner\u00eda ya es un club de poder, como quiz\u00e1s lo es hoy en alg\u00fan sentido. Llegar\u00e1 a ser muy fuerte en la Argentina a partir de la presidencia de Mitre, y con Urquiza antes, donde <strong>tenemos una enorme cantidad de presidentes masones <\/strong>que, por ejemplo, antes de asumir la presidencia presentaban su programa de gobierno ante la masoner\u00eda\u201d.<br \/>&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<blockquote readability=\"6\">\n<p>\u201cDespu\u00e9s de la Revoluci\u00f3n de Mayo San Mart\u00edn ve que hay una guerra declarada y que hace falta alguien que ordene esa guerra\u201d<span class=\"comilla\">\u201d<\/span><\/p>\n<\/blockquote>\n<p>Mientras en Europa se suced\u00edan la guerra y las conspiraciones, <strong>en Am\u00e9rica la revoluci\u00f3n ya estaba en marcha. <\/strong>El 14 de septiembre de 1811 San Mart\u00edn se embarca hacia Londres, donde pasar\u00e1 cuatro meses. All\u00ed entrar\u00e1 en contacto con la Gran Hermandad Americana, logia fundada por el patriota venezolano Francisco de Miranda y de la que la Logia de C\u00e1diz ser\u00e1 una rama. Tambi\u00e9n se reunir\u00e1 con pol\u00edticos vinculados al gobierno brit\u00e1nico que le hacen conocer <strong>el llamado \u201cPlan Maitland\u201d, que promov\u00eda la emancipaci\u00f3n de Buenos Aires, Chile, Per\u00fa y Quito.<\/strong><\/p>\n<p>\u201cDespu\u00e9s de la Revoluci\u00f3n de Mayo, San Mart\u00edn ve que hay una guerra declarada y que hace falta alguien que ordene esa guerra, que es muy desventajosa para los americanos\u201d, asegura Pigna.&nbsp;Y agrega: \u201cSabe que tiene la capacidad de hacerlo despu\u00e9s de tantos a\u00f1os en el ej\u00e9rcito espa\u00f1ol, y ah\u00ed decide. A partir de un ardid, de enga\u00f1ar a la oficialidad espa\u00f1ola con la supuesta necesidad de un viaje familiar a Per\u00fa,<strong> logra que le conceden una licencia, viaja a Londres y de all\u00ed al R\u00edo de la Plata<\/strong>\u201d.<\/p>\n<p>En enero de 1812 San Mart\u00edn se embarca en la fragata inglesa&nbsp;\u201cGeorge Canning\u201c rumbo a Buenos Aires. La histor\u00eda, entonces, comenzar\u00e1 a escribirse en el sur del mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Felipe Pigna cuenta que \u201ca los 11 a\u00f1os San Mart\u00edn ingresa al Ej\u00e9rcito, algo que era habitual para la \u00e9poca. Ya a los 13 est\u00e1 combatiendo en Argelia y Marruecos, posesiones espa\u00f1olas en el norte de \u00c1frica\u00bb. Chog\u00fc\u00ed amaba las aves. Imitaba sus cantos tocando la flauta en un claro de la selva. Ellas respond\u00edan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27170,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/27169"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=27169"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/27169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/27170"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=27169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=27169"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=27169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}