{"id":2542,"date":"2020-09-30T08:15:00","date_gmt":"2020-09-30T08:15:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2020\/09\/30\/virgin-river-temporada-2-la-serie-se-prepara-con-estos-episodios-para-su-estreno-este-ano\/"},"modified":"2020-09-30T08:15:00","modified_gmt":"2020-09-30T08:15:00","slug":"virgin-river-temporada-2-la-serie-se-prepara-con-estos-episodios-para-su-estreno-este-ano","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/09\/30\/virgin-river-temporada-2-la-serie-se-prepara-con-estos-episodios-para-su-estreno-este-ano\/","title":{"rendered":"Virgin River temporada 2: La serie se prepara con estos episodios para su estreno este a\u00f1o"},"content":{"rendered":"<p>Una de las series m\u00e1s esperada de <b>Netflix<\/b> en este 2020 es Virgin River, muchos espectadores han estado esperando pacientemente por ella,&nbsp;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una de las series m\u00e1s esperada de Netflix en este 2020 es Virgin River, muchos espectadores han estado esperando pacientemente por ella,&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/2542"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}