{"id":19790,"date":"2021-05-09T18:52:02","date_gmt":"2021-05-09T18:52:02","guid":{"rendered":"https:\/\/www.ole.com.ar\/racing\/gol-racing-san-lorenzo-sacando-medio_0_uxTlVsdBe.html"},"modified":"2021-05-09T18:52:02","modified_gmt":"2021-05-09T18:52:02","slug":"el-insolito-gol-de-racing-sacando-del-medio","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/05\/09\/el-insolito-gol-de-racing-sacando-del-medio\/","title":{"rendered":"El ins\u00f3lito gol de Racing sacando del medio"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/05\/el-insolito-gol-de-racing-sacando-del-medio.jpg\"><\/p>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/05\/el-insolito-gol-de-racing-sacando-del-medio.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Al que madruga, Dios lo ayuda\u2026 Y <strong><a alt=\"racing\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/racing.html\" target=\"_blank\" title=\"racing\" rel=\"noopener noreferrer\">Racing<\/a> <\/strong>reaccion\u00f3 r\u00e1pido apenas son\u00f3 el despertador: <strong>convirti\u00f3 el gol del 2-0 cuando s\u00f3lo iban 13 segundos<\/strong> desde el reinicio del partido ante <strong><a alt=\"san-lorenzo\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" target=\"_blank\" title=\"san-lorenzo\" rel=\"noopener noreferrer\">San Lorenzo<\/a><\/strong>. S\u00ed, sacando del medio&#8230;<\/p>\n<p><strong><a alt=\"tomas-chancalay\" class=\"slug\" href=\"https:\/\/www.ole.com.ar\/tema\/tomas-chancalay.html\" target=\"_blank\" title=\"tomas-chancalay\" rel=\"noopener noreferrer\">Tom\u00e1s Chancalay<\/a><\/strong> fue el que defini\u00f3 una jugada que arranc\u00f3, literalmente, con el pitazo de Dar\u00edo Herrera. <strong>Enzo Copetti toc\u00f3 atr\u00e1s en el reinicio del juego para Mauricio Mart\u00ednez<\/strong>. El volante central de Racing pis\u00f3 la pelota, evalu\u00f3 jugar por izquierda pero luego retrocedi\u00f3 y <strong>busc\u00f3 a Leonardo Sigali, presionado al trote por Uvita Fern\u00e1nde<\/strong>z.<\/p>\n<p><strong>El central, para evitar complicarse, levant\u00f3 la cabeza y escrut\u00f3 en el horizonte al mismo futbolista que hab\u00eda dado inicio a las combinaciones colectivas: Copetti. El ex Rafaela se alej\u00f3 del \u00e1rea y arrastr\u00f3 la marca con \u00e9l de Diego Braghieri.<\/strong><\/p>\n<p>En el salto, claro, el blondo gan\u00f3 y atac\u00f3 con su peinada el espacio vac\u00edo y <strong>aprovechando adem\u00e1s que Gattoni se hab\u00eda adelantado mucho<\/strong>&nbsp;-quiz\u00e1s, intentando desactivar un toque corto para Cvitanich, quien transitaba el c\u00edrculo central- quedado muy adelantado, claramente mal parado.<\/p>\n<p><strong>Chancalay, a fin de cuentas, terminar\u00eda de capitalizar los desajustes defensivos de San Lorenzo<\/strong>. Porque tir\u00f3 la diagonal al enorme vac\u00edo que hab\u00eda quedado detr\u00e1s de los dos centrales, dej\u00f3 picar el bal\u00f3n y defini\u00f3 de volea al segundo palo de Sebasti\u00e1n Torrico, quien no pudo hacer nada.<\/p>\n<h2>La tarde dulce de Chancalay<\/h2>\n<p>Fue el segundo gol de <strong>Chancalay <\/strong>en el partido, puesto que en el primer tiempo hab\u00eda marcado tambi\u00e9n el primero del equipo de Juan Antonio Pizzi. Fue tras una combinaci\u00f3n entre Dar\u00edo Cvitanich y Eugenio Mena, quien envi\u00f3 un centro preciso al coraz\u00f3n del \u00e1rea.<\/p>\n<p>El ex futbolista de Col\u00f3n, en esa jugada, <strong>tambi\u00e9n sac\u00f3 provecho de una falla defensiva de San Lorenzo<\/strong> puesto que le gan\u00f3 en velocidad a Juli\u00e1n Palacios, quien estaba tom\u00e1ndolo pero perdi\u00f3 su referencia. Y Chanca aprovech\u00f3.<\/p>\n<div class=\"entry-tags\">\n<h2>TEMAS QUE APARECEN EN ESTA NOTA<\/h2>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Al que madruga, Dios lo ayuda\u2026 Y Racing reaccion\u00f3 r\u00e1pido apenas son\u00f3 el despertador: convirti\u00f3 el gol del 2-0 cuando s\u00f3lo iban 13 segundos desde el reinicio del partido ante San Lorenzo. S\u00ed, sacando del medio&#8230; Tom\u00e1s Chancalay fue el que defini\u00f3 una jugada que arranc\u00f3, literalmente, con el pitazo de Dar\u00edo Herrera. Enzo Copetti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/19790"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=19790"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/19790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/19791"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=19790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=19790"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=19790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}