{"id":18477,"date":"2021-04-22T19:21:29","date_gmt":"2021-04-22T19:21:29","guid":{"rendered":"http:\/\/ladecimaweb.com\/?p=9395"},"modified":"2021-04-22T19:21:29","modified_gmt":"2021-04-22T19:21:29","slug":"mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/04\/22\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador\/","title":{"rendered":"M\u00e1s de seis horas para destapar una boca de tormenta en Villa El Libertador"},"content":{"rendered":"<p><em><strong>Los residuos acumulados bajo la superficie eran m\u00e1s que significativos. Extrajeron hasta bandejas de carnicer\u00eda de los ca\u00f1os.\u00a0<\/strong><\/em><\/p>\n<p>M\u00e1s de seis horas de trabajo consumi\u00f3 destapar una boca de tormenta en Villa El Libertador, todo un s\u00edntoma de la cantidad de basura que obstru\u00eda el desag\u00fce pluvial.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-9399 aligncenter\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador.jpg\" alt=\"\" width=\"229\" height=\"509\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador.jpg 576w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-4.jpg 200w\" sizes=\"(max-width: 229px) 100vw, 229px\" \/><\/p>\n<p>El trabajo estuvo a cargo de una cuadrilla de cinco trabajadores del ente de Obras y Servicios municipal\u00a0 (Coys), que dirige Victoria Flores.<\/p>\n<div class=\"fitvids-video\"><iframe title=\"destapando una boca de tormenta en VEL\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/o_sqlEb8VXo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<p>&#8220;Es impresionante la mugre que se sac\u00f3&#8221;, coment\u00f3 Aldo Ortega, presidente del Centro Vecinal y trabajador del Coys.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone wp-image-9396\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-1.jpg\" alt=\"\" width=\"648\" height=\"292\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-1.jpg 850w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-5.jpg 800w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-6.jpg 768w\" sizes=\"(max-width: 648px) 100vw, 648px\" \/><\/p>\n<p>La boca de tormenta est\u00e1 ubicada en Tilcara y R\u00edo Negro, y fue intervenida luego de los reclamos por el agua acumulada manifestados por comerciantes y vecinos del sector.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-9400 aligncenter\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-2.jpg\" alt=\"\" width=\"278\" height=\"618\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-2.jpg 576w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-7.jpg 200w\" sizes=\"(max-width: 278px) 100vw, 278px\" \/><\/p>\n<p>&#8220;Los compa\u00f1eros hicieron un trabajo enorme, meti\u00e9ndose con la manguera adentro de la boca para poder destapar la uni\u00f3n con la otra parte de la calle&#8221;, detall\u00f3 Ortega a La D\u00e9cima.<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-9403 aligncenter\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-3.jpg\" alt=\"\" width=\"250\" height=\"556\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-3.jpg 576w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador-8.jpg 200w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/p>\n<p>Ortega testimoni\u00f3 los trabajos con fotos impresionantes del operativo, m\u00e1s arduo de lo que muchos pueden imaginarse.<\/p>\n<p>&#8220;Hab\u00eda botellas, bandejas de carnicer\u00edas, pedazos de asfalto, de todo se sac\u00f3&#8221;, enumer\u00f3 el vecinalista.<\/p>\n<p>Esta nota deber\u00eda ser le\u00edda como un llamado de atenci\u00f3n para los que se comportan con desprecio arrojando cualquier tipo de residuo a la calle, o, directamente a la boca del desag\u00fce.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.youtube.com\/watch?v=4MQW8zM648g\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/mas-de-seis-horas-para-destapar-una-boca-de-tormenta-en-villa-el-libertador.gif\" alt=\"\"><\/a><\/div>\n<p>&nbsp;<\/p>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/limpieza-de-boca-de-tormenta-en-vel-es-impresionante-la-cantidad-de-mugre-que-se-saco\/\">M\u00e1s de seis horas para destapar una boca de tormenta en Villa El Libertador<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los residuos acumulados bajo la superficie eran m\u00e1s que significativos. Extrajeron hasta bandejas de carnicer\u00eda de los ca\u00f1os.\u00a0 M\u00e1s de seis horas de trabajo consumi\u00f3 destapar una boca de tormenta en Villa El Libertador, todo un s\u00edntoma de la cantidad de basura que obstru\u00eda el desag\u00fce pluvial. El trabajo estuvo a cargo de una cuadrilla [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/18477"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=18477"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/18477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/18478"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=18477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=18477"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=18477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}