{"id":17691,"date":"2021-04-14T19:42:52","date_gmt":"2021-04-14T19:42:52","guid":{"rendered":"http:\/\/ladecimaweb.com\/?p=9210"},"modified":"2021-04-14T19:42:52","modified_gmt":"2021-04-14T19:42:52","slug":"murio-bernard-madoff-el-autor-de-la-mayor-estafa-de-wall-street","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/04\/14\/murio-bernard-madoff-el-autor-de-la-mayor-estafa-de-wall-street\/","title":{"rendered":"Muri\u00f3 Bernard Madoff, el autor de la mayor estafa de Wall Street"},"content":{"rendered":"<p><em>(Agencia T\u00e9lam)<\/em> Bernard Madoff, el inversionista burs\u00e1til que <strong>estaf\u00f3 por m\u00e1s de US$ 64.000 millones a inversionistas de Wall Street<\/strong>, muri\u00f3 hoy de causas naturales mientras\u00a0<strong>purgaba una condena de 150 a\u00f1os<\/strong>, informaron medios estadounidenses.<\/p>\n<p>Madoff, que el pr\u00f3ximo 29 de abril cumplir\u00eda 83 a\u00f1os, falleci\u00f3 en el centro m\u00e9dico de Butner, Carolina del Norte, cercano a la prisi\u00f3n en la que se encontraba, aparentemente por\u00a0<strong>causas naturales<\/strong>.<\/p>\n<p>La estafa que protagoniz\u00f3 consisti\u00f3 en tomar capitales a cambio de grandes ganancias que al principio fueron efectivas, pero que a\u00f1os m\u00e1s tarde se evidenci\u00f3 consist\u00edan en un\u00a0<strong>sistema piramidal o esquema Ponzi,<\/strong>\u00a0convertido hoy en uno de los mayores fraudes de la historia.<\/p>\n<p>Los desfalcos fueron cometidos a trav\u00e9s de Bernard Madoff Investement Securities, una financiera que fundara en 1960, y utilizando el esquema piramidal ideado por el italiano Carlo Ponzi en 1920.<\/p>\n<p><strong>El sistema necesita cada vez m\u00e1s inversores<\/strong>, ya que si esto no sucede, el sistema cae por la falta de inyecci\u00f3n de divisas, provocando que los inversores &#8220;nuevos&#8221; no reciban ni intereses ni devoluci\u00f3n del capital.<\/p>\n<p>El enga\u00f1o\u00a0<strong>no s\u00f3lo alcanz\u00f3 a instituciones bancarias y grupos inversores<\/strong>, ya que fueron v\u00edctimas tambi\u00e9n fundaciones, obras de caridad y la comunidad jud\u00eda de los Estados Unidos, de la cual el financista era un activo participante.<\/p>\n<p>Bernie Madoff fue apresado por el FBI en 2008, acusado de fraude, luego de que \u00e9ste le confesara a su mujer e hijos las operaciones fraudulentas, lo que provoc\u00f3 que\u00a0<strong>su propia familia lo denunciara<\/strong>. Fue sentenciado en 2009 a prisi\u00f3n perpetua, pena que le fue conmutada a 150 a\u00f1os durante el desarrollo del juicio.<\/p>\n<p>Madoff no perdi\u00f3 en prisi\u00f3n sus habilidades como inversor: seg\u00fan el medio especializado MarketWatch,\u00a0<strong>en 2017 compr\u00f3 todo el chocolate de taza de la prisi\u00f3n para especular con el precio.<\/strong><\/p>\n<div class=\"ubm_banner\"><a href=\"https:\/\/www.youtube.com\/watch?v=4MQW8zM648g\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/04\/murio-bernard-madoff-el-autor-de-la-mayor-estafa-de-wall-street.gif\" alt=\"\"><\/a><\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/murio-bernard-madoff-el-autor-de-la-mayor-estafa-de-wall-street\/\">Muri\u00f3 Bernard Madoff, el autor de la mayor estafa de Wall Street<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Agencia T\u00e9lam) Bernard Madoff, el inversionista burs\u00e1til que estaf\u00f3 por m\u00e1s de US$ 64.000 millones a inversionistas de Wall Street, muri\u00f3 hoy de causas naturales mientras\u00a0purgaba una condena de 150 a\u00f1os, informaron medios estadounidenses. Madoff, que el pr\u00f3ximo 29 de abril cumplir\u00eda 83 a\u00f1os, falleci\u00f3 en el centro m\u00e9dico de Butner, Carolina del Norte, cercano [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17692,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/17691"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=17691"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/17691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/17692"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=17691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=17691"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=17691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}