{"id":16918,"date":"2021-04-05T23:46:21","date_gmt":"2021-04-05T23:46:21","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2021\/04\/05\/el-increible-golazo-de-87-metros-que-acaparo-las-miradas-en-el-futbol-argentino\/"},"modified":"2021-04-05T23:46:21","modified_gmt":"2021-04-05T23:46:21","slug":"el-increible-golazo-de-87-metros-que-acaparo-las-miradas-en-el-futbol-argentino","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/04\/05\/el-increible-golazo-de-87-metros-que-acaparo-las-miradas-en-el-futbol-argentino\/","title":{"rendered":"El incre\u00edble golazo de 87 metros que acapar\u00f3 las miradas en el <b>f\u00fatbol argentino<\/b>"},"content":{"rendered":"<p>Este fin de semana, en la Primera Nacional de <b>Argentina<\/b> (segunda divisi\u00f3n), el jugador Facundo Su\u00e1rez vio al portero rival adelantado y protagoniz\u00f3&nbsp;&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana, en la Primera Nacional de Argentina (segunda divisi\u00f3n), el jugador Facundo Su\u00e1rez vio al portero rival adelantado y protagoniz\u00f3&nbsp;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/16918"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=16918"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/16918\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=16918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=16918"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=16918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}