{"id":141060,"date":"2026-09-02T17:55:08","date_gmt":"2026-09-02T17:55:08","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/dato-dejo-traspaso-enzo-fernandez-manchester-city-supero-registro-cristiano-ronaldo_0_BfSZdSlWPh.html"},"modified":"2026-09-02T17:55:08","modified_gmt":"2026-09-02T17:55:08","slug":"el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/09\/02\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo\/","title":{"rendered":"El otro dato que dej\u00f3 el traspaso de Enzo Fern\u00e1ndez al Manchester City: super\u00f3 un registro de Cristiano Ronaldo"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo.jpg\"><\/p>\n<div id=\"element-body-0\" class=\"sc-df222161-0 hNvwjb\" readability=\"33.183381088825\">\n<p><strong>Enzo Fern\u00e1ndez<\/strong> fue el gran protagonista del cierre del mercado de pases en el f\u00fatbol europeo: <a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/inglaterra\/define-futuro-enzo-fernandez-manchester-city-chelsea-negocian-contrarreloj-cifra-record-millones-libras_0_6McaznrbYQ.html\" target=\"_blank\" title=\"pas\u00f3 del Chelsea al Manchester City \" alt=\"pas\u00f3 del Chelsea al Manchester City \" rel=\"noopener noreferrer\">pas\u00f3 del Chelsea al Manchester City<\/a> por la impresionante cifra de <strong>145.000.000 de euros<\/strong>, lo que lo transform\u00f3 en el fichaje m\u00e1s caro en la historia de la Premier League. Pero adem\u00e1s su traspaso dej\u00f3 otro dato, <strong> super\u00f3 una marca de Cristiano Ronaldo.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-df222161-0 hNvwjb\" readability=\"37\">\n<p>Para el volante formado en River este fue su <strong>segunda venta que supera los 100 millones de euros<\/strong>. Anteriormente, tras romperla y ser una de las figuras de la Scaloneta en el Mundial de Qatar 2022, <strong>el Chelsea le pag\u00f3 121 millones al Benfica.<\/strong> Esto lo ubica en podio de los futbolistas que m\u00e1s dinero movieron en transferencias en toda la historia.<\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-df222161-0 hNvwjb\" readability=\"38\">\n<p>Seg\u00fan el sitio Transfermarkt, especializado en los pases de los futbolistas, todas las ventas de Enzo Fern\u00e1ndez <strong>acumulan 310.250.000 euros<\/strong> (tambi\u00e9n suman la venta de River al Benfica). As\u00ed, <strong>el volante pas\u00f3 a Cristiano Ronaldo en el ranking de los jugadores que m\u00e1s dinero acumularon con sus ventas.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\" class=\"sc-df222161-0 hNvwjb\" readability=\"36\">\n<p>El delantero de la selecci\u00f3n de Portugal, que tuvo ventas top como la del Manchester United al Real Madrid en 2009 (que hab\u00eda establecido un r\u00e9cord en su momento con 94.000.000 de euros), <strong> acumula traspasos que suman 247.000.000.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-4\" class=\"sc-df222161-0 hNvwjb\" readability=\"36\">\n<p>El l\u00edder de este peculiar ranking que toma todas las transferencias de un jugador a lo largo de su carrera es <strong>Neymar<\/strong>, con 4 <strong>00.000.000 de euros<\/strong>: m\u00e1s de la mitad (unos 222.000.000) fueron cuando el PSG le pag\u00f3 la cl\u00e1usula de salida al Barcelona, a mediados de 2027.<\/p>\n<\/div>\n<div id=\"element-body-5\" class=\"sc-df222161-0 hNvwjb\" readability=\"36\">\n<p>Mientras que en el segundo lugar se ubica un nombre llamativo: el belga <strong>Romelu Lukaku. <\/strong> Sin llegar a ser una mega figura, al nivel de Neymar o Cristiano Ronaldo, el delantero supo acumular traspasos por <strong>375.920.000 euros.<\/strong><\/p>\n<\/div>\n<div class=\"sc-c0843421-0 iNysjD image-embed\" id=\"element-body-6\"><img alt=\"Enzo Fern\u00e1ndez en el Manchester City.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-2.jpg\"><span class=\"epigraphe\">Enzo Fern\u00e1ndez en el Manchester City.<\/span><\/div>\n<p><h2><strong>El ranking de los futbolistas que m\u00e1s dinero movieron<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-8\" class=\"sc-df222161-0 hNvwjb\">\n<ol>\n<li>Neymar: \u20ac400.000.000<\/li>\n<li>Lukaku: \u20ac375.920.000<\/li>\n<li>Enzo Fern\u00e1ndez: \u20ac310.250.00<\/li>\n<li>Cristiano Ronaldo: \u20ac247.000.000<\/li>\n<li>Alexander Isak: \u20ac246.100.000<\/li>\n<\/ol>\n<\/div>\n<p><h2><strong>\u00bfPor qu\u00e9 usar\u00e1 la camiseta 17?<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-10\" class=\"sc-df222161-0 hNvwjb\" readability=\"35\">\n<p>Luego de concretarse su llegada desde Chelsea sobre el cierre del mercado de pases europeo, el mediocampista argentino conoci\u00f3 el n\u00famero que utilizar\u00e1 en el equipo dirigido por Enzo Maresca llevar\u00e1 la camiseta 17.<\/p>\n<\/div>\n<div id=\"element-body-11\" class=\"sc-df222161-0 hNvwjb\" readability=\"37\">\n<p>La elecci\u00f3n no fue casual. A sus 25 a\u00f1os, el campe\u00f3n del mundo con la Selecci\u00f3n Argentina decidi\u00f3 volver a un dorsal que ya forma parte de su historia personal. De hecho, fue uno de los primeros n\u00fameros que utiliz\u00f3 con la Albiceleste, antes de consolidarse con la n\u00famero 24.<\/p>\n<\/div>\n<div class=\"sc-c0843421-0 iNysjD image-embed\" id=\"element-body-12\"><img alt=\"El nuevo dorsal de Enzo\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-3.jpg\"><span class=\"epigraphe\">El nuevo dorsal de Enzo<\/span><\/div>\n<div id=\"element-body-13\" class=\"sc-df222161-0 hNvwjb\" readability=\"38\">\n<p>Fern\u00e1ndez firm\u00f3 un contrato por cinco a\u00f1os con el conjunto ingl\u00e9s y afrontar\u00e1 as\u00ed un nuevo desaf\u00edo en su carrera. Ser\u00e1 su quinta experiencia a nivel de clubes: se inici\u00f3 y volvi\u00f3 a River, antes p as\u00f3 por Defensa y Justicia. Luego, ya en Europa, en Benfica y Chelsea antes de convertirse en jugador del City<\/p>\n<\/div>\n<div id=\"element-body-14\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Enzo Fern\u00e1ndez ya tiene n\u00famero en el Manchester City: \u00bfpor qu\u00e9 eligi\u00f3 el 17?\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Enzo Fern\u00e1ndez ya tiene n\u00famero en el Manchester City: \u00bfpor qu\u00e9 eligi\u00f3 el 17?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-15\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"La Premier rompi\u00f3 el mercado: gast\u00f3 m\u00e1s que las otras cuatro grandes ligas juntas\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La Premier rompi\u00f3 el mercado: gast\u00f3 m\u00e1s que las otras cuatro grandes ligas juntas<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-16\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Con Enzo Fern\u00e1ndez en el Top 5, los pases m\u00e1s caros de la historia del f\u00fatbol\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con Enzo Fern\u00e1ndez en el Top 5, los pases m\u00e1s caros de la historia del f\u00fatbol<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-17\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Por qu\u00e9 el pase de Enzo Fern\u00e1ndez al City estuvo a punto de caerse\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Por qu\u00e9 el pase de Enzo Fern\u00e1ndez al City estuvo a punto de caerse<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-18\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Los grandes jugadores que quedaron libres tras el cierre del mercado europeo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-8.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Los grandes jugadores que quedaron libres tras el cierre del mercado europeo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-19\" class=\"sc-a7166897-0 eTTZWU\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"La Scaloneta y los pases que hubo en el mercado que se cerr\u00f3\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/09\/el-otro-dato-que-dejo-el-traspaso-de-enzo-fernandez-al-manchester-city-supero-un-registro-de-cristiano-ronaldo-9.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La Scaloneta y los pases que hubo en el mercado que se cerr\u00f3<\/h3>\n<\/p>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Enzo Fern\u00e1ndez fue el gran protagonista del cierre del mercado de pases en el f\u00fatbol europeo: pas\u00f3 del Chelsea al Manchester City por la impresionante cifra de 145.000.000 de euros, lo que lo transform\u00f3 en el fichaje m\u00e1s caro en la historia de la Premier League. Pero adem\u00e1s su traspaso dej\u00f3 otro dato, super\u00f3 una [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":141061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/141060"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=141060"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/141060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/141061"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=141060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=141060"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=141060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}