{"id":1386,"date":"2020-09-09T09:46:09","date_gmt":"2020-09-09T09:46:09","guid":{"rendered":"https:\/\/www.mujerhoy.com\/vivir\/salud\/202009\/09\/vuelta-cole-medidas-coronavirus-20200903142158.html"},"modified":"2020-09-09T09:46:09","modified_gmt":"2020-09-09T09:46:09","slug":"la-vuelta-al-cole-aulas-saludables","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2020\/09\/09\/la-vuelta-al-cole-aulas-saludables\/","title":{"rendered":"La vuelta al cole: aulas saludables"},"content":{"rendered":"<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2020\/09\/la-vuelta-al-cole-aulas-saludables.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Esta semana comienza <strong>la vuelta al cole en nuestro pa\u00eds<\/strong>. Esta va a realizarse de manera progresiva y va a variar, en su metodolog\u00eda, dependiendo de cada comunidad aut\u00f3noma, ya que estas tienen la competencia en educaci\u00f3n. Como es l\u00f3gico esto <strong>plantea diversas preocupaciones<\/strong> a los alumnos pero sobre todo a los padres. \u00bfEs seguro volver a las clases de manera presencial? \u00bfHabr\u00e1 rebotes en los colegios y esto obligar\u00e1 a cerrarlos? \u00bfLa ense\u00f1anza presencial es segura para los ni\u00f1os y para los que tienen contacto con ellos? \u00bfQu\u00e9 pasa con la salud de los profesores y dem\u00e1s personal de los colegios? Estos y otros muchos dilemas se van a plantear despu\u00e9s del inicio de las clases.<\/p>\n<p>En los pa\u00edses europeos pr\u00f3ximos al nuestro se plantean los mismos interrogantes. Las medidas tomadas para la vuelta a las aulas son de lo m\u00e1s variopintas. Van desde no hacer pr\u00e1cticamente nada, como en Suecia, donde no ha parado la actividad presencial en ning\u00fan momento, a<strong> medidas m\u00e1s estrictas como las de Espa\u00f1a e Italia. <\/strong>Donde parece que el tema no se lo toman a broma es en <strong>China y no bajan la guardia, estrictos controles de temperatura, test r\u00e1pidos en las aulas, etc<\/strong>. A pesar de que en la actualidad no tienen ning\u00fan caso y la pandemia est\u00e1 pr\u00e1cticamente controlada.<\/p>\n<h3 class=\"ladillo\">Uso de la mascarilla<\/h3>\n<p>Existe una serie de recomendaciones elaboradas hace algunos meses por la OMS, estas son de car\u00e1cter muy general. En los distintos pa\u00edses, como el nuestro, el Ministerio de Educaci\u00f3n respectivo ha elaborado un informe sobre la vuelta a las aulas. En pa\u00edses como <strong>Espa\u00f1a o Alemania<\/strong>, donde la educaci\u00f3n est\u00e1 descentralizada, estos <strong>informes son orientativos y la decisi\u00f3n de las medidas finales a tomar dependen de cada comunidad aut\u00f3noma o L\u00e4nder<\/strong>, respectivamente. En<strong> Francia<\/strong>, donde las cosas est\u00e1n mucho m\u00e1s centralizadas, <strong>las medidas del gobierno son casi obligatorias en todo el territorio nacional. <\/strong><\/p>\n<div class=\"comp_sumario\">\n<h3>El 80% de los espa\u00f1oles no tienen confianza en las medidas tomadas por las autoridades<\/h3>\n<\/div>\n<p>Un tema donde no parece haber consenso es en el uso de las mascarillas. <strong>En nuestro pa\u00eds ser\u00e1n obligatorias en todo momento a partir de los 6 a\u00f1os.<\/strong> En Francia ser\u00e1n obligatorias a partir de los 11 a\u00f1os. En Alemania solo se utilizar\u00e1n en los espacios comunes, ya que en las aulas no ser\u00e1n obligatorias. <\/p>\n<p>Donde parece haber acuerdo es en que <strong>la experiencia con la ense\u00f1anza a distancia<\/strong>, durante el \u00faltimo confinamiento, ha demostrado que produce <strong>desigualdades<\/strong>, sobre todo por motivos econ\u00f3micos. En Francia han constatado que entre un 4% y un 6% de los alumnos han dejado los estudios desde marzo y no han vuelto a saber nada de ellos. Para evitar las diferencias econ\u00f3micas en el acceso y tener un dispositivo con capacidad de conectarse a Internet, en<strong> Alemania han adoptado una conexi\u00f3n barata con un coste de 10 \u20ac<\/strong> para estudiantes. Tambi\u00e9n existen ayudas para poner a su disposici\u00f3n un ordenador cuando sea necesario. <\/p>\n<p>Parece ser que en la mayor\u00eda de comunidades aut\u00f3nomas de nuestro pa\u00eds habr\u00e1 un <strong>aumento en la contrataci\u00f3n de personal docente <\/strong>o relacionado con la ense\u00f1anza, unas <strong>25.000 personas en total.<\/strong> En este aspecto, quien se lleva la matr\u00edcula de honor es Italia, donde van a realizar 100.000 contrataciones permanentes y 50.000 temporales para reforzar la educaci\u00f3n. En Francia van a dar una paga extra a los directores de colegios e institutos y existe un compromiso para subir el sueldo de los profesores en a\u00f1os sucesivos. Algo parecido ocurre en Italia, <strong>en Espa\u00f1a parece que, al igual que con el personal sanitario, los responsables pol\u00edticos se han olvidado de las subidas salariales para la ense\u00f1anza<\/strong>. \u00bfSabremos alg\u00fan d\u00eda por qu\u00e9 somos tan diferentes de nuestros vecinos y a d\u00f3nde se destina el dinero de nuestros impuestos?<\/p>\n<h3 class=\"ladillo\">Rebrotes en las aulas<\/h3>\n<p>En <strong>Alemania<\/strong>, que ha empezado las clases a mediados de agosto, <strong>han tenido que cerrar ya dos escuelas por rebrotes<\/strong>. Aunque existen protocolos para aislar a los ni\u00f1os cuando tengan fiebre o cualquier otro s\u00edntoma en los centros docentes, <strong>debemos asumir que nuestro pa\u00eds terminar\u00e1 por cerrar alg\u00fan centro <\/strong>educativo debido a un rebrote. Esperemos que sean los m\u00ednimos posibles y sobre todo que no sea algo generalizado que obligue a un nuevo confinamiento educativo, algo que l\u00f3gicamente producir\u00eda p\u00e1nico en los hogares. Cerca del 80% de las personas, seg\u00fan diversas encuestas realizadas por medios de comunicaci\u00f3n, no tienen confianza en las medidas tomadas por las autoridades para la vuelta a las clases presenciales, en nuestro pa\u00eds <strong>. En Alemania, seg\u00fan diversas encuestas, esta valoraci\u00f3n negativa la tienen el 49% de las personas y en Francia este porcentaje baja al 19%.<\/strong> Por lo tanto, en este aspecto, algo est\u00e1 fallando en Espa\u00f1a y parece que las familias necesitan m\u00e1s apoyo psicol\u00f3gico e informaci\u00f3n por parte de las autoridades a la hora de encarar esta vuelta a las clases.<\/p>\n<div class=\"tb-interesa\">\n<h3>Tambi\u00e9n te interesa<\/h3>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana comienza la vuelta al cole en nuestro pa\u00eds. Esta va a realizarse de manera progresiva y va a variar, en su metodolog\u00eda, dependiendo de cada comunidad aut\u00f3noma, ya que estas tienen la competencia en educaci\u00f3n. Como es l\u00f3gico esto plantea diversas preocupaciones a los alumnos pero sobre todo a los padres. \u00bfEs seguro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/1386"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=1386"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/1386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/1387"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=1386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=1386"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=1386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}