{"id":136406,"date":"2026-05-13T02:41:28","date_gmt":"2026-05-13T02:41:28","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2026\/05\/13\/esteban-domecq-el-trabajo-de-milei-era-controlar-la-inflacion-pero-ahora-la-gente-prioriza-llegar-a-fin-de-mes\/"},"modified":"2026-05-13T02:41:28","modified_gmt":"2026-05-13T02:41:28","slug":"esteban-domecq-el-trabajo-de-milei-era-controlar-la-inflacion-pero-ahora-la-gente-prioriza-llegar-a-fin-de-mes","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/05\/13\/esteban-domecq-el-trabajo-de-milei-era-controlar-la-inflacion-pero-ahora-la-gente-prioriza-llegar-a-fin-de-mes\/","title":{"rendered":"Esteban Domecq: \u00abEl trabajo de Milei era controlar la inflaci\u00f3n pero ahora la gente prioriza llegar a fin de mes\u00bb"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/esteban-domecq-el-trabajo-de-milei-era-controlar-la-inflacion-pero-ahora-la-gente-prioriza-llegar-a-fin-de-mes.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>El economista de Invecq expuso en el C<strong>omit\u00e9 de Inversiones de SyC Inversiones<\/strong> y advirti\u00f3 sobre las tensiones entre inflaci\u00f3n, reservas y crecimiento. Adem\u00e1s, plante\u00f3 que la<strong> principal preocupaci\u00f3n social ya no es la suba de precios sino la p\u00e9rdida del poder adquisitivo y el empleo<\/strong>.<\/p>\n<p>En una nueva edici\u00f3n del Comit\u00e9 de Inversiones de SyC Inversiones, el economista Esteban Domecq traz\u00f3 un diagn\u00f3stico crudo sobre el presente econ\u00f3mico argentino y sostuvo que el gran desaf\u00edo del Gobierno ser\u00e1 encontrar equilibrio entre estabilizaci\u00f3n, acumulaci\u00f3n de reservas y recuperaci\u00f3n de la actividad.<\/p>\n<p>Durante la charla conducida por Sa\u00fal Musicante, Domecq defini\u00f3 el escenario actual como una etapa de \u201calta tensi\u00f3n macroecon\u00f3mica\u201d y se centr\u00f3 en el concepto del \u201cTrilema econ\u00f3mico\u201d, una din\u00e1mica en la que distintos objetivos econ\u00f3micos chocan entre s\u00ed.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/nacion-ajusto-provincias-volvieron-a-gastar-la-grieta-fiscal-que-amenaza-el-modelo.phtml\" rel=\"noopener noreferrer\">Naci\u00f3n ajust\u00f3, provincias volvieron a gastar: la grieta fiscal que amenaza el modelo<\/a><\/p>\n<p>\u201cAcumular reservas es absolutamente necesario. El riesgo pasa por el volumen de acumulaci\u00f3n que a su vez puede afectar el proceso de desinflaci\u00f3n dependiendo de d\u00f3nde se ubique el tipo de cambio\u201d, explic\u00f3 el director de Invecq.<\/p>\n<p>El economista tambi\u00e9n puso el foco en el <strong>cambio de humor social respecto de la gesti\u00f3n de Javier Milei<\/strong>. Seg\u00fan sostuvo, la <strong>inflaci\u00f3n dej\u00f3 de ser la principal preocupaci\u00f3n de la poblaci\u00f3n y fue reemplazada por la ca\u00edda del consumo<\/strong>, el deterioro salarial y el temor por el empleo.<\/p>\n<p>\u201cEl \u2018<strong>job description\u2019 del presidente Milei era terminar con la inflaci\u00f3n. Pero hoy la sociedad empieza a decir: \u2018me importa llegar a fin de mes, recuperar el consumo y cuidar mi trabajo<\/strong>\u2019\u201d, se\u00f1al\u00f3.<\/p>\n<p>En el plano internacional, Domecq describi\u00f3 al 2026 como un a\u00f1o \u201cca\u00f3tico pero favorable\u201d para Am\u00e9rica Latina y destac\u00f3 factores externos que benefician a Argentina, como el fortalecimiento del real brasile\u00f1o y el buen desempe\u00f1o de los commodities.<\/p>\n<p>No obstante, advirti\u00f3 que el contexto financiero global seguir\u00e1 siendo exigente. \u201cLa tasa de inter\u00e9s en Estados Unidos continuar\u00e1 elevada y eso complica cualquier intento de Argentina de regresar al mercado de capitales\u201d, afirm\u00f3.<\/p>\n<p>Otro de los ejes centrales de la exposici\u00f3n fue la creciente fragmentaci\u00f3n de la econom\u00eda local. Para Domecq, hoy conviven sectores \u201cultra expansivos\u201d como el agro, la energ\u00eda y la miner\u00eda, con actividades ligadas al mercado interno que todav\u00eda permanecen en recesi\u00f3n.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/buscan-frenar-el-endeudamiento-con-tarjetas-en-cordoba-con-intervencion-del-banco-de-cordoba.phtml\" rel=\"noopener noreferrer\">Buscan frenar el endeudamiento con tarjetas en C\u00f3rdoba con apoyo del banco provincial<\/a><\/p>\n<p>\u201cUna proyecci\u00f3n de crecimiento del 2,5% esconde sectores cayendo 10% y otros creciendo m\u00e1s de 20%\u201d, ejemplific\u00f3.<\/p>\n<p>Como cierre, el economista sostuvo que la salida no pasa por buscar resultados extremos, sino por construir un sendero de estabilidad gradual que permita sostener crecimiento y desinflaci\u00f3n al mismo tiempo.<\/p>\n<p>\u201cSi vamos a buscar una inflaci\u00f3n del 10% a cualquier costo, tal vez la encontremos en la paz de los cementerios. El desaf\u00edo es apuntarle al medio: tener crecimiento moderado con inflaci\u00f3n en descenso\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El economista de Invecq expuso en el Comit\u00e9 de Inversiones de SyC Inversiones y advirti\u00f3 sobre las tensiones entre inflaci\u00f3n, reservas y crecimiento. Adem\u00e1s, plante\u00f3 que la principal preocupaci\u00f3n social ya no es la suba de precios sino la p\u00e9rdida del poder adquisitivo y el empleo. En una nueva edici\u00f3n del Comit\u00e9 de Inversiones de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":136407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[2626,35,3140,1525,175,3141,80,1527],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/136406"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=136406"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/136406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/136407"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=136406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=136406"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=136406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}