{"id":136386,"date":"2026-05-13T02:46:27","date_gmt":"2026-05-13T02:46:27","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-primera\/argentinos-huracan-torneo-apertura-cuartos-final-gol-tatuaje-hincha_0_bI0wNwtRnA.html"},"modified":"2026-05-13T02:46:27","modified_gmt":"2026-05-13T02:46:27","slug":"tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/05\/13\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo\/","title":{"rendered":"Tiene un tatuaje de Hurac\u00e1n y fue determinante para que Argentinos elimine al Globo"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo.jpg\"><\/p>\n<p><span class=\"createDate\">12\/05\/2026 23:46hs.<\/span><time class=\"modificatedDate\" datetime=\"2026-05-13T00:33:17-03:00\"> Actualizado al 13\/05\/2026 00:33hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p><strong>Tiene las siglas CAH tatuadas en la nuca.<\/strong> Es confeso hincha. Surgi\u00f3 de las Inferiores del club, pero apenas pudo disputar cuatro partidos en Primera entre 2016 y 2017. Y ahora, <strong>fue determinante para que Argentinos elimine justamente a Hurac\u00e1n<\/strong>: <strong>Tom\u00e1s Molina<\/strong>, cuando se iniciaba el tiempo suplementario, le convirti\u00f3 de cabeza al club del cual es hincha y le ahog\u00f3 las ilusiones de ser campe\u00f3n en este Apertura luego del batacazo ante <strong>Boca<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"41\">\n<p><strong>\u201cCuando era muy chico, me hice el tatuaje con las iniciales de Hurac\u00e1n. Fue una idea en conjunto con mi hermano\u201d<\/strong>, explic\u00f3 este goleador de 31 a\u00f1os en el 2021, en un di\u00e1logo con Por Siempre Globo. Sin embargo, las pulsaciones del encuentro y la importancia de su tanto lo llevaron a festejarlo desaforadamente de cara a los hinchas del Bicho, una situaci\u00f3n radicalmente opuesta a la que hab\u00eda sucedido hace un par de semanas, cuando tambi\u00e9n le anot\u00f3 al Globo por la \u00faltima fecha de la fase regular en el Duc\u00f3 y pidi\u00f3 perd\u00f3n (fue el empate transitorio del 2-1 final).<\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p><strong>De hecho, en esta historia de vaivenes, el a\u00f1o pasado le hab\u00eda tocado errar un penal contra Hurac\u00e1n por los octavos de final de la Copa Argentina<\/strong>. Una situaci\u00f3n que lo llev\u00f3 a ser algo criticado por un sector de los hinchas de Argentinos, m\u00e1s all\u00e1 de haber sido una pieza determinante en el equipo que pele\u00f3 ambos torneos locales hasta los cuartos de final y la propia Copa hasta la final (afortunadamente para \u00e9l, termin\u00f3 pasando de ronda).<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-3\"><img alt=\"Tom\u00e1s Molina, verdugo de Hurac\u00e1n, tiene un tatuaje del Globo (Por Siempre Globo).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo-2.jpg\"><span class=\"epigraphe\">Tom\u00e1s Molina, verdugo de Hurac\u00e1n, tiene un tatuaje del Globo (Por Siempre Globo).<\/span><\/div>\n<div id=\"element-body-4\" class=\"sc-136cd478-0 ekTCfV\" readability=\"42\">\n<p>Esta vez, su cuarto grito en el a\u00f1o (producci\u00f3n m\u00e1s baja que en el 2025, cuando convirti\u00f3 17) no solo fue clave, sino que tuvo su sello: tras una buena jugada que mut\u00f3 de la izquierda a la derecha, Lozano le tir\u00f3 un centro muy preciso y \u00e9l, astutamente, <strong>fue a espaldas de Blondel para ganarle c\u00f3modamente y meter un cabezazo al \u00e1ngulo<\/strong> que fue imposible para cualquier esfuerzo de Gal\u00edndez. \u201cS\u00e9 que a los laterales les suele costar cuando lleg\u00e1s a sus espaldas\u201d, cont\u00f3 post partido.<\/p>\n<\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"40\">\n<p><strong>\u201cEs dif\u00edcil explicar las sensaciones, me sale del alma haberlo gritado as\u00ed. Sab\u00eda que era dif\u00edcil que no pudiera gritarlo, le pido perd\u00f3n a mi familia, aunque creo que est\u00e1n contentos.<\/strong> La sensaci\u00f3n de hacer un gol en esta instancia y para ganar es \u00fanica. Estoy en Argentinos y feliz de estar ac\u00e1. Mi viejo capaz tiene sensaciones encontradas, pero quiere lo mejor para m\u00ed\u201d, dijo.<\/p>\n<\/div>\n<p><h2><strong>El gol de Molina a Hurac\u00e1n<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-7\" class=\"sc-ef81c825-1 evSCNc\"><figcaption class=\"JWvideoNota_title\">\n<p>Video: TNT Sports<\/p>\n<\/figcaption><\/div>\n<div id=\"element-body-8\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"San Mart\u00edn de Tucum\u00e1n baj\u00f3 al puntero y se puso segundo en la tabla\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo-3.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>San Mart\u00edn de Tucum\u00e1n baj\u00f3 al puntero y se puso segundo en la tabla<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-9\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"G\u00fcemes- Quilmes: el partido que dej\u00f3 al \u00e1rbitro en offside\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>G\u00fcemes- Quilmes: el partido que dej\u00f3 al \u00e1rbitro en offside<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-10\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Se estren\u00f3 la nueva medida implementada por el VAR en la recta final del Torneo Apertura\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/05\/tiene-un-tatuaje-de-huracan-y-fue-determinante-para-que-argentinos-elimine-al-globo-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Se estren\u00f3 la nueva medida implementada por el VAR en la recta final del Torneo Apertura<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>12\/05\/2026 23:46hs. Actualizado al 13\/05\/2026 00:33hs. Tiene las siglas CAH tatuadas en la nuca. Es confeso hincha. Surgi\u00f3 de las Inferiores del club, pero apenas pudo disputar cuatro partidos en Primera entre 2016 y 2017. Y ahora, fue determinante para que Argentinos elimine justamente a Hurac\u00e1n: Tom\u00e1s Molina, cuando se iniciaba el tiempo suplementario, le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":136387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/136386"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=136386"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/136386\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/136387"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=136386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=136386"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=136386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}