{"id":133831,"date":"2026-03-28T11:54:37","date_gmt":"2026-03-28T11:54:37","guid":{"rendered":"https:\/\/www.mujerhoy.com\/moda\/tendencias\/gafas-sol-tendencia-primavera-2026-20260328112114-nt.html"},"modified":"2026-03-28T11:54:37","modified_gmt":"2026-03-28T11:54:37","slug":"todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/03\/28\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026\/","title":{"rendered":"Todas las gafas de sol que van a ser tendencia esta primavera 2026"},"content":{"rendered":"<p><!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial \">\n<!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial__signature \">\n<!-- IMAGE AUTHOR -->\n<picture class=\"voc-image-signature\">\n<img class=\"voc-image-signature__img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026.jpg\" alt=\"Patricia Mart\u00edn\">\n<\/picture>\n<!-- INFO AUTHOR --> <\/div><\/div>\n<p><!-- COMPONENTS --><\/p>\n<p class=\"voc-paragraph\">Llega<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/prendas-zara-comprar-conseguir-mejores-looks-primavera-20260306133452-nt.html\" data-voc-vtm-id=\"in-text-traffic\" title=\" la primavera \" data-mrf-link=\"www.mujerhoy.com\"> la primavera <\/a>y con ella mi accesorio favorito: <strong>las gafas de sol.<\/strong> Soy de las que siempre lleva un par -a veces incluso dos- en el bolso independientemente de la estaci\u00f3n, pero ahora que suben las temperaturas y cada vez hay m\u00e1s d\u00edas con sol, se convierten en un imprescindible en mis looks. <\/p>\n<p class=\"voc-paragraph\">Esta temporada las gafas de sol no solo van a ser un elemento pr\u00e1ctico, sino que van a convertirse en toda una declaraci\u00f3n de estilo a la hora de crear un estilismo. Si bien los dise\u00f1os m\u00e1s <strong>minimalistas y cl\u00e1sicos <\/strong>van a seguir llev\u00e1ndose, esta temporada se llevan las<strong> monturas XXL <\/strong>y los dise\u00f1os tipo pantalla. <\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/jerseis-finitos-primavera-sientan-bien-marcan-diferencia-20260317124143-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Los jers\u00e9is finitos que no me quito en primavera: sientan bien con todo y marcan la diferencia\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-1.jpg\" alt=\"Los jers\u00e9is finitos que no me quito en primavera: sientan bien con todo y marcan la diferencia\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/gafas-sol-amarillas-ayudan-dormir-polemica-realidad-mito-20260314010219-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"\u00bfUnas gafas de sol que ayudan a dormir? El cristal que favorece la producci\u00f3n de melatonina\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-2.jpg\" alt=\"\u00bfUnas gafas de sol que ayudan a dormir? El cristal que favorece la producci\u00f3n de melatonina\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Tambi\u00e9n vamos a ver gafas con una <strong>est\u00e9tica futurista <\/strong>y monturas estrechas y afiladas. En cuanto a lso colores, los tonos neutros como el negro o el gris van a ser los m\u00e1s demandados, sin olvidarnos de los estampados que nunca fallan como el carey o incluso el animal print.<\/p>\n<p><h3 class=\"v-cmp-suh\">\nLas gafas de sol m\u00e1s bonitas de nueva temporada<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Lo m\u00e1s importante a la hora de escoger nuestras pr\u00f3ximas gafas de sol es <strong>sentirnos c\u00f3modas y seguras <\/strong>con ella. Son el complemento perfecto para elevar un look b\u00e1sico y te salvan en los d\u00edas en los que duermes poco. Si est\u00e1s pensando en comprarte unas nuevas de cara a la primavera, estos son los modelos que me tienen obsesionada \u00faltimamente.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-264\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-3.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Las mejores gafas de sol de la temporada\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nLas mejores gafas de sol de la temporada<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nMULTI\u00d3PTICAS<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-264\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-264\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-3.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Empezamos por las gafas de sol Koosha Sun de<strong> Multi\u00f3pticas<\/strong>, unas <strong>gafas tipo aviador<\/strong> pero m\u00e1s grandes y con montura gruesa de acetato. Los detalles enfrente y varilla recuerdan a las formas del bindi tradicional de Asia aportando elegancia y sofisticaci\u00f3n, e incluye lentes de sol polarizadas (49,00 \u20ac). <\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-759\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-4.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Las mejores gafas de sol de la temporada\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nLas mejores gafas de sol de la temporada<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nJIMMY FAIRLY<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-759\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-759\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-4.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\"><strong>Cl\u00e1sicas<\/strong> y muy favorecedoras, las gafas de sol Emmy de<strong> Jimmy Fairly<\/strong>, con una montura ovalada de acetato de celulosa en color negro. Cuentan con un ojal dorado en la patilla, que permite enganchar a la cadena, y combinan con todo (1345,00 \u20ac). <\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-83\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-5.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Las mejores gafas de sol de la temporada\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nLas mejores gafas de sol de la temporada<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nDEEPLY<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-83\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-83\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-5.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">De <strong>Deeply<\/strong> nos quedamos con las gafas de sol Granite 01, un dise\u00f1o moderno y atemporal con montura de acetato en <strong>acabado carey.<\/strong> La forma de las lentes es rectangular ligeramente suavizada en los bordes, lo que les da un aire elegante pero vers\u00e1til, adecuado tanto para looks casuales como m\u00e1s pulidos (49,90 \u20ac). <\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-446\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-6.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Las mejores gafas de sol de la temporada\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nLas mejores gafas de sol de la temporada<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nARCHY WELFARE<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-446\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-446\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-6.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Inspiradas en el<strong> estilo franc\u00e9s<\/strong> y desenfadado de Brigitte Bardot, este modelo de <strong>Archy Welfare<\/strong> pretende convertirse en un imprescindible de esta temporada. Su montura de acero, combinada con las varillas en diferentes tonos de carey, lo convierten en un dise\u00f1o \u00fanico y lleno de estilo (150,00 \u20ac). <\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-762\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-7.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt=\"Las mejores gafas de sol de la temporada\" data-voc-vtm-id=\"in-text-traffic\"> <\/button><figcaption class=\"v-fc\">\n<span class=\"v-fc__t\"><br \/>\nLas mejores gafas de sol de la temporada<br \/>\n<\/span><br \/>\n<span class=\"v-fc__p\"><br \/>\nSUNGLASS HUT<br \/>\n<\/span><br \/>\n<\/figcaption><\/div>\n<\/div>\n<div id=\"photo-762\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-762\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-7.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p class=\"voc-paragraph\">Por \u00faltimo, en Sunglass Hut encontramos estas<strong> gafas de sol de Miu Miu <\/strong>con un aire retro muy marcado. La montura es de color negro brillante, con una forma estrecha y ligeramente envolvente. Las lentes oscuras refuerzan su est\u00e9tica minimalista y moderna, mientras que en las varillas destaca el logotipo dorado de la marca, a\u00f1adiendo un detalle lujoso y llamativo (245,00 \u20ac).<\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/chaquetas-baratas-basicos-zara-instagram-2026-20260314114044-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Dile adi\u00f3s a la americana: esta primavera apuesta por una chaqueta corta\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-8.jpg\" alt=\"Dile adi\u00f3s a la americana: esta primavera apuesta por una chaqueta corta\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/falda-zara-chicas-bohemias-agotada-20260314170112-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Las chicas bohemias han agotado esta falda de Zara que llevar\u00e1s con jers\u00e9is y blusas\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/todas-las-gafas-de-sol-que-van-a-ser-tendencia-esta-primavera-2026-9.jpg\" alt=\"Las chicas bohemias han agotado esta falda de Zara que llevar\u00e1s con jers\u00e9is y blusas\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"media_block\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Llega la primavera y con ella mi accesorio favorito: las gafas de sol. Soy de las que siempre lleva un par -a veces incluso dos- en el bolso independientemente de la estaci\u00f3n, pero ahora que suben las temperaturas y cada vez hay m\u00e1s d\u00edas con sol, se convierten en un imprescindible en mis looks. Esta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":133832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133831"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=133831"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/133832"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=133831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=133831"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=133831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}