{"id":133736,"date":"2026-03-28T00:31:58","date_gmt":"2026-03-28T00:31:58","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2026\/03\/28\/borges-nos-dejo-mundos-sutiles-pero-hoy-triunfa-la-estupidez\/"},"modified":"2026-03-28T00:31:58","modified_gmt":"2026-03-28T00:31:58","slug":"borges-nos-dejo-mundos-sutiles-pero-hoy-triunfa-la-estupidez","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/03\/28\/borges-nos-dejo-mundos-sutiles-pero-hoy-triunfa-la-estupidez\/","title":{"rendered":"Borges nos dej\u00f3 mundos sutiles, pero hoy triunfa la estupidez"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/borges-nos-dejo-mundos-sutiles-pero-hoy-triunfa-la-estupidez.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Ni siquiera <strong>Jorge Luis Borges<\/strong> hubiese imaginado la escena grotesca que presenta nuestra realidad. Ni siquiera \u00e9l, que el pr\u00f3ximo 14 de junio sumar\u00e1 a sus memorias 40 a\u00f1os de haberse ido de este mundo. Vivimos sumergidos en una tragicomedia sin ensayo. La <strong>Argentina <\/strong>contempor\u00e1nea se parece a una versi\u00f3n degradada del c\u00e9lebre cuento <em>Tl\u00f6n, Uqbar, Orbis Tertius:<\/em> ese mundo fant\u00e1stico regido por un lenguaje exquisitamente extravagante, pero coherente; el gobierno actual, en cambio, ha renunciado a toda pretensi\u00f3n de coherencia. Y, como toda construcci\u00f3n precaria, intenta sostenerse<a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/medios\/nuevo-informe-de-fopea-como-uso-milei-el-insulto-en-x-para-silenciar-a-la-prensa-estigmatizar-a-la-oposicion-y-movilizar-a-sus-seguidores.phtml\" rel=\"noopener noreferrer\"><strong> con violencia y a los gritos.<\/strong><\/a><\/p>\n<p>Borges fue el genio de la met\u00e1fora. La met\u00e1fora \u2014cuando es buena\u2014 ilumina; no oscurece. \u201cNadie lo vio desembarcar en la un\u00e1nime noche\u201d, escribi\u00f3. Quiz\u00e1s hoy Borges hubiese adaptado esa extraordinaria frase a Milei: \u201ctodos lo vimos desembarcar en la un\u00e1nime noche argentina\u2026 y aun as\u00ed logr\u00f3 oscurecerla a\u00fan m\u00e1s\u201d. Los insultos de Milei son todo lo contrario a la met\u00e1fora. La met\u00e1fora es sutil, inteligente y est\u00e9tica; la incontinencia del insulto es su negaci\u00f3n.<\/p>\n<p>El presidente ha elevado la asociaci\u00f3n libre al rango de pol\u00edtica de Estado. Sus inquebrantables certezas constituyen una forma curiosa de pensamiento: primero la autoconvicci\u00f3n, despu\u00e9s el cinismo disparatado. \u201cLos empresarios que evaden impuestos son h\u00e9roes\u201d. Es dif\u00edcil no admirar la proeza conceptual: transformar la evasi\u00f3n en virtud y el <strong>delito<\/strong> en \u00e9pica.<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/milei-celebro-el-fallo-por-ypf-y-volvio-a-cargar-contra-cristina-y-kicillof-expropiar-esta-mal-porque-robar-esta-mal.phtml\" rel=\"noopener noreferrer\">Milei festej\u00f3 el fallo por YPF y volvi\u00f3 a cargar contra Cristina y Kicillof: \u201cExpropiar est\u00e1 mal porque robar est\u00e1 mal\u201d<\/a><\/p>\n<p>Aunque, siendo justos, aqu\u00ed aparece un <strong>dilema<\/strong> casi <strong>borgeano<\/strong>: Milei, como otros presidentes, juraba eliminar la corrupci\u00f3n; y, al hacerlo, enfrenta el dilema de c\u00f3mo convertir un delito en un acto legal. En su l\u00f3gica torcida, redefine el delito mediante los blanqueos. Los actos corruptos se desvanecen, metaf\u00f3ricamente, en la un\u00e1nime noche&#8230;<\/p>\n<h2>Hoy triunfa la estupidez<\/h2>\n<p>Desde la Fundaci\u00f3n \u201cEl Faro\u201d, donde se libra la llamada \u201cbatalla cultural\u201d, su pedagogo m\u00e1s brillante,<strong> Agust\u00edn Laje<\/strong> \u2014autodeclarado intelectual muy formado e inteligente\u2014, para explicar por qu\u00e9 ser\u00eda peor ser de izquierda que ser homosexual, ha logrado una s\u00edntesis memorable: invocando supuestos estudios, sostuvo que una persona homosexual de derecha ser\u00eda m\u00e1s feliz que una heterosexual de izquierda.<\/p>\n<blockquote readability=\"0\">\n<p><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/columnistas\/borges-y-la-primera-vez-por-silvia-hopenhayn.phtml\" rel=\"noopener noreferrer\"><strong>Borges<\/strong> escribi\u00f3 que &#8216;la hipocres\u00eda es el homenaje que el vicio rinde a la virtud&#8217; \u201d<\/a><\/p>\n<\/blockquote>\n<p>Ahora bien, teniendo en cuenta que Laje es un tipo brillante, cabe la sospecha \u2014casi borgeana\u2014 de si no ser\u00e1, despu\u00e9s de todo, un infiltrado (brillante) desde la izquierda en la derecha, capaz de formular esa y otras imbecilidades con el \u00fanico prop\u00f3sito de desprestigiar a la ultraderecha desde adentro.<\/p>\n<p>Quiz\u00e1s otra infiltrada sea <strong>Lilia Lemoine<\/strong>, quien logr\u00f3 ser designada secretaria de la Comisi\u00f3n de Ciencia, Tecnolog\u00eda e Innovaci\u00f3n Productiva de la C\u00e1mara de Diputados. Una terraplanista convertida en autoridad de pol\u00edtica cient\u00edfica\u2026Lo que permite imaginar que solo una infiltrada podr\u00eda exhibir semejante audacia.<\/p>\n<p>Borges desconfiaba de las inteligencias ruidosas y de las convicciones demasiado firmes. Sab\u00eda que el pensamiento aut\u00e9ntico tiene algo de vacilaci\u00f3n, de pudor. Aqu\u00ed ocurre lo contrario: cuanto menos se piensa, m\u00e1s se afirma.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cultura\/de-quien-hablaba-borges-realmente-cuando-escribio-no-nos-une-el-amor-sino-el-espanto.phtml\" rel=\"noopener noreferrer\">De qui\u00e9n hablaba Borges realmente cuando escribi\u00f3 \u201cNo nos une el amor sino el espanto\u00bb<\/a><\/p>\n<p>Lo mismo ocurre con la moral declamada desde los atriles oficiales. Tenemos voceros convertidos en custodios de una \u00e9tica s\u00fabita, casi militante, que aparece con la misma velocidad con la que desaparece cuando la realidad se vuelve inc\u00f3moda. Borges escribi\u00f3 que \u201cla hipocres\u00eda es el homenaje que el <strong>vicio <\/strong>rinde a la <strong>virtud<\/strong>\u201d. Dif\u00edcil encontrar una definici\u00f3n m\u00e1s precisa del tono de \u00e9poca.<\/p>\n<h2>Borges nos dej\u00f3 mundos sutiles<\/h2>\n<p>En <em>Historia de la eternidad<\/em>, habla del eterno retorno. Mientras tanto, en el plano econ\u00f3mico, asistimos a una escena conocida: el eterno retorno del <em>carry trade <\/em>y del d\u00f3lar barato. Un ministro de Econom\u00eda que reaparece, como una versi\u00f3n menor del <strong>eterno retorno<\/strong>, reciclando sus fracasos. Un modelo que, una y otra vez, se presenta como novedad, como hallazgo, como signo de inteligencia financiera. Borges, que imagin\u00f3 el tiempo como un <strong>laberinto <\/strong>de repeticiones, probablemente sonreir\u00eda: no por la sofisticaci\u00f3n del mecanismo, sino por la obstinaci\u00f3n en creer que esta vez ser\u00e1 distinto\u2026 incluso cuando Caputo ya sabe que no lo ser\u00e1.<\/p>\n<p>Lo verdaderamente inquietante no es la bizarr\u00eda de este gobierno ni siquiera su ignorancia. Es la naturalidad con la que ambas se instalan como norma. La facilidad con la que la <strong>estupidez <\/strong>se vuelve estilo, la intolerancia car\u00e1cter y la simplificaci\u00f3n, m\u00e9todo, al servicio de la injusticia, la discriminaci\u00f3n y el inter\u00e9s econ\u00f3mico.<\/p>\n<p>En Borges: una disputa con los dilemas irresueltos de su literatura he tratado de tomar las paradojas que el maestro de los mundos ilusorios pero l\u00f3gicos, dej\u00f3 abiertos. Ir m\u00e1s all\u00e1 de sus dilemas y establecer sus consecuencias: un divertimento filos\u00f3fico-literario. El actual dilema argentino, lejos de ser un divertimento, es un laberinto cruel del que el gobierno no sabe salir\u2026 y del que la sociedad deber\u00e1 encontrar la salida cuando el cinismo, la estupidez y la impostura dejen de imponerse como m\u00e9todo.<\/p>\n<h4><em>*Escritor, f\u00edsico y fil\u00f3sofo, ex director del Departamento de Historia de la UBA, autor de \u00abBorges: una disputa con los dilemas irresueltos de su literatur\u00bb<\/em><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Ni siquiera Jorge Luis Borges hubiese imaginado la escena grotesca que presenta nuestra realidad. Ni siquiera \u00e9l, que el pr\u00f3ximo 14 de junio sumar\u00e1 a sus memorias 40 a\u00f1os de haberse ido de este mundo. Vivimos sumergidos en una tragicomedia sin ensayo. La Argentina contempor\u00e1nea se parece a una versi\u00f3n degradada del c\u00e9lebre cuento Tl\u00f6n, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":133737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[2988,403,2986,2987],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133736"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=133736"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/133737"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=133736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=133736"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=133736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}