{"id":133218,"date":"2026-03-19T12:52:48","date_gmt":"2026-03-19T12:52:48","guid":{"rendered":"https:\/\/cordobaturismo.gov.ar\/?p=900901"},"modified":"2026-03-19T12:52:48","modified_gmt":"2026-03-19T12:52:48","slug":"la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/03\/19\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas\/","title":{"rendered":"La Feria Internacional de Artesan\u00edas vuelve a C\u00f3rdoba con nuevos talentos y propuestas in\u00e9ditas"},"content":{"rendered":"<p>La 43\u00aa edici\u00f3n del tradicional encuentro reunir\u00e1 a m\u00e1s de 500 expositores y sumar\u00e1 una nueva generaci\u00f3n de artesanos que presentar\u00e1n obras y productos nunca antes vistos. Ser\u00e1 del 28 de marzo al 5 de abril en el Complejo Ferial C\u00f3rdoba<br \/>C\u00f3rdoba, 16 de marzo de 2026. Con la llegada del oto\u00f1o, la ciudad de C\u00f3rdoba volver\u00e1 a convertirse en punto de encuentro para el arte manual con la 43\u00aa Feria Internacional de Artesan\u00edas, uno de los eventos culturales y tur\u00edsticos m\u00e1s representativos de su agenda anual.<br \/>Del 28 de marzo al 5 de abril, el Complejo Ferial C\u00f3rdoba recibir\u00e1 a m\u00e1s de 500 expositores, en una edici\u00f3n marcada por la incorporaci\u00f3n de nuevos artesanos y propuestas nunca antes presentadas al p\u00fablico.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas.jpg\" alt class=\"wp-image-900907\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas.jpg 1000w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-3.jpg 300w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-4.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\"><\/figure>\n<p>Este a\u00f1o, el encuentro apuesta a una renovaci\u00f3n generacional dentro del universo artesanal, con la llegada de una nueva camada de talentos que aportar\u00e1 miradas contempor\u00e1neas, t\u00e9cnicas innovadoras y piezas exclusivas que ampliar\u00e1n el recorrido tradicional del evento.<br \/>\u201cDespu\u00e9s de m\u00e1s de cuatro d\u00e9cadas, la feria se consolid\u00f3 como un s\u00edmbolo cultural y tur\u00edstico de C\u00f3rdoba. En esta edici\u00f3n, que est\u00e1 completamente sold out, incorporamos nuevos talentos y propuestas originales, lo que permite que quienes visitan el evento siempre encuentren algo diferente\u201d, destac\u00f3 Ernesto Halac, director de Modus, empresa responsable de la organizaci\u00f3n.<br \/>Durante nueve jornadas, el predio se transformar\u00e1 en un gran paseo donde convivir\u00e1n oficios tradicionales, creatividad contempor\u00e1nea, dise\u00f1o, sabores regionales y actividades para todo p\u00fablico.<br \/>Oficios que atraviesan generaciones<br \/>El encuentro reunir\u00e1 a especialistas de distintas disciplinas que trabajan con materiales y t\u00e9cnicas muy diversas: cer\u00e1mica, talabarter\u00eda, vitrofusi\u00f3n, cester\u00eda, hierro forjado, filigrana, batik, mosaico, cuero, piedra, metal, tejidos, crochet, papel mach\u00e9, asta y hueso, entre muchas otras.<br \/>Cada participante es seleccionado mediante un proceso de evaluaci\u00f3n que garantiza la autenticidad y calidad de las piezas presentadas.<br \/>\u201cBuscamos preservar los saberes tradicionales y al mismo tiempo abrir espacio a nuevas interpretaciones del trabajo manual. Este a\u00f1o se ver\u00e1n exploraciones originales en materiales y procesos creativos, producto del intercambio entre generaciones de creadores\u201d, explic\u00f3 la arquitecta Diana Cohen, integrante del jurado fiscalizador.<\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-1.jpg\" alt class=\"wp-image-900906\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-1.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-5.jpg 300w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-6.jpg 768w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-7.jpg 1536w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-8.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/figure>\n<p>Adem\u00e1s de la exhibici\u00f3n y comercializaci\u00f3n, el evento funciona como un espacio de intercambio entre quienes se dedican a estos oficios, favoreciendo el surgimiento de nuevas ideas, colaboraciones y desarrollos t\u00e9cnicos.<\/p>\n<p>Dise\u00f1o, sabores y un paseo cultural.<br \/>La propuesta se ampl\u00eda con un sector dedicado al dise\u00f1o urbano, donde m\u00e1s de 150 emprendedores exhibir\u00e1n indumentaria, accesorios y objetos contempor\u00e1neos.<br \/>El recorrido tambi\u00e9n incluir\u00e1 un \u00e1rea comercial con productos regionales, conservas, embutidos y textiles, adem\u00e1s de un patio gastron\u00f3mico con food trucks que ofrecer\u00e1n distintas opciones culinarias, desde platos internacionales hasta cervezas artesanales y propuestas dulces.<br \/>De esta manera, la feria se convierte en un espacio que combina arte, identidad cultural, compras y entretenimiento, ideal para recorrer en familia o con amigos.<br \/>Informaci\u00f3n para visitantes.<\/p>\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-2.jpg\" alt class=\"wp-image-900904\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-2.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-9.jpg 300w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-10.jpg 768w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/03\/la-feria-internacional-de-artesanias-vuelve-a-cordoba-con-nuevos-talentos-y-propuestas-ineditas-11.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"><\/figure>\n<p>La Feria Internacional de Artesan\u00edas abrir\u00e1 sus puertas del 28 de marzo al 5 de abril, entre las 15 y las 21 horas, en el Complejo Ferial C\u00f3rdoba.<br \/>\u25cf Primer fin de semana: $7000<\/p>\n<p>\u25cf De lunes a mi\u00e9rcoles: $5000<\/p>\n<p>\u25cf De jueves a domingo: $10000<br \/>Los menores de 10 a\u00f1os ingresan sin cargo, el estacionamiento inferior es gratuito y el de la parte superior tiene un valor por veh\u00edculo de $10000 el d\u00eda.<br \/>Con m\u00e1s de cuarenta a\u00f1os de trayectoria, el encuentro vuelve a renovarse y reafirma su papel como una vidriera clave para el trabajo manual, celebrando tanto la herencia cultural como la llegada de nuevas voces que impulsan la evoluci\u00f3n de la artesan\u00eda<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 43\u00aa edici\u00f3n del tradicional encuentro reunir\u00e1 a m\u00e1s de 500 expositores y sumar\u00e1 una nueva generaci\u00f3n de artesanos que presentar\u00e1n obras y productos nunca antes vistos. Ser\u00e1 del 28 de marzo al 5 de abril en el Complejo Ferial C\u00f3rdobaC\u00f3rdoba, 16 de marzo de 2026. Con la llegada del oto\u00f1o, la ciudad de C\u00f3rdoba [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":133219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133218"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=133218"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/133218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/133219"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=133218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=133218"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=133218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}