{"id":131144,"date":"2026-02-11T21:06:52","date_gmt":"2026-02-11T21:06:52","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/japon-elimina-empates-define-penales_0_gNuFzFLtDj.html"},"modified":"2026-02-11T21:06:52","modified_gmt":"2026-02-11T21:06:52","slug":"japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/11\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates\/","title":{"rendered":"Jap\u00f3n revoluciona el f\u00fatbol y le dice adi\u00f3s a los empates"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2026-02-11T18:06:52-03:00\">11\/02\/2026 18:06hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35.545454545455\">\n<p>El <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/futbol-japones.html\" title=\"F\u00fatbol japon\u00e9s\" alt=\"F\u00fatbol japon\u00e9s\" class=\"slug\">f\u00fatbol japon\u00e9s<\/a><\/strong> dio un paso audaz en su temporada n\u00famero 100. La <strong>J1 League puso en marcha una regla que elimina el empate <\/strong>como resultado final y <strong>propone una definici\u00f3n por penales cada vez que un encuentro termine igualado tras los 90 minutos<\/strong>. La medida comenz\u00f3 a aplicarse desde la primera fecha del campeonato, disputada el \u00faltimo fin de semana, y ya gener\u00f3 repercusi\u00f3n dentro y fuera del pa\u00eds.<\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p>El nuevo sistema modifica la l\u00f3gica tradicional de puntuaci\u00f3n. El <strong>ganador en el tiempo reglamentario contin\u00faa sumando tres puntos<\/strong> y <strong> el perdedor ninguno<\/strong>. Sin embargo, <strong>en caso de empate, ambos equipos ejecutan una tanda de penales<\/strong>: <strong> el vencedor se queda con dos unidades<\/strong> y <strong>el derrotado suma una<\/strong>. De esta manera, cada partido reparte puntos y se busca reducir la cantidad de igualdades.<\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Seg\u00fan explicaron desde la organizaci\u00f3n, <strong> el objetivo es aumentar la competitividad y el atractivo del torneo<\/strong>, incentivando a los equipos a buscar el triunfo hasta el final. En la primera jornada se registraron cuatro empates en diez partidos, todos resueltos desde el punto penal, lo que marc\u00f3 el estreno oficial de esta norma en la historia del f\u00fatbol japon\u00e9s.<\/p>\n<\/div>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p>Cabe destacar que esta regla no es nueva en el mundo del f\u00fatbol y ya se prob\u00f3 en otros pa\u00edses. Sin ir m\u00e1s lejos, <strong>la AFA introdujo las definiciones por penales en caso de empate en 1988<\/strong>, utilizando el mismo sistema de puntos que en Jap\u00f3n. La prueba dur\u00f3 solamente un a\u00f1o hasta que se comenzaron a otorgar los tres puntos por victoria, uno por igualdad y ninguno por derrota.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-4\"><img alt=\"Este sistema de desempate ya se utiliz\u00f3 en otros pa\u00edses.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-2.jpg\"><span class=\"epigraphe\">Este sistema de desempate ya se utiliz\u00f3 en otros pa\u00edses.<\/span><\/div>\n<p><h2>Una medida excepcional en una temporada de transici\u00f3n<\/h2>\n<\/p>\n<div id=\"element-body-6\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37\">\n<p><strong>La eliminaci\u00f3n de los empates no ser\u00e1 permanente<\/strong>. La J-League <strong>la implement\u00f3 \u00fanicamente para la llamada \u201ctemporada de transici\u00f3n\u201d<\/strong>, que se disputar\u00e1 entre <strong>febrero y junio de 2026<\/strong>. Este per\u00edodo servir\u00e1 como puente antes del cambio definitivo de calendario, ya que <strong>a partir de agosto el campeonato japon\u00e9s adoptar\u00e1 el modelo europeo<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-7\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Desde la segunda mitad de 2026, <strong>la liga pasar\u00e1 a jugarse entre agosto y mayo o junio<\/strong>, con mercados de pases alineados a los de Europa. En principio, la tanda de penales para resolver empates no continuar\u00e1 una vez completado el ajuste del calendario, aunque sus impulsores no descartan evaluar su continuidad seg\u00fan el impacto deportivo y la aceptaci\u00f3n de clubes e hinchas.<\/p>\n<\/div>\n<div id=\"element-body-8\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35.470588235294\">\n<p>Mientras tanto, <strong>esta mini-temporada contar\u00e1 con 20 equipos divididos en regiones Este y Oeste<\/strong> y <strong>tras la fase regular se disputar\u00e1 un playoff para definir al campe\u00f3n<\/strong>, en un formato similar al de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/nba.html\" title=\"NBA\" alt=\"NBA\" class=\"slug\">NBA<\/a><\/strong>.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-9\"><img alt=\"Capitanes de los 20 equipos de la J-League.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-3.jpg\"><span class=\"epigraphe\">Capitanes de los 20 equipos de la J-League.<\/span><\/div>\n<p><h2>Los primeros antecedentes y el impacto inicial<\/h2>\n<\/p>\n<div id=\"element-body-11\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>El <strong>primer partido oficial en aplicar la nueva norma fue el empate 1-1 entre Kyoto Sanga y Vissel Kobe<\/strong>. Tras la igualdad en el tiempo reglamentario, <strong>el conjunto de Kobe se impuso en la tanda de penales<\/strong> y sum\u00f3 dos puntos, mientras que su rival se qued\u00f3 con uno. Tambi\u00e9n <strong>hubo definiciones desde los doce pasos en los encuentros entre FC Tokyo 1(5) &#8211; 1(4) Kashima Antlers<\/strong>, <strong>Gamba Osaka 0(5) &#8211; 0(4) Cerezo Osaka<\/strong>, y <strong>Avispa Fukuoka 1(5) &#8211; 1(6) Okayama<\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-12\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>La iniciativa, comparada por algunos con formatos alternativos que priorizan el espect\u00e1culo, abri\u00f3 el debate sobre el futuro de los empates en el f\u00fatbol tradicional. Por ahora, Jap\u00f3n ensaya un cambio profundo en una temporada especial, con la mira puesta en modernizar su competencia y alinearla con los grandes mercados del deporte mundial.<\/p>\n<\/div>\n<div id=\"element-body-13\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"\u00bfCu\u00e1ndo es el partido inaugural del Mundial 2026?\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00bfCu\u00e1ndo es el partido inaugural del Mundial 2026?<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-14\" class=\"sc-a7166897-0 eoLsBE\" readability=\"32\">\n<section readability=\"4\"><picture><img alt=\"Con un gran partido del Dibu Mart\u00ednez, Aston Villa le gan\u00f3 a Brighton y sigue en la pelea por la Premier League\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con un gran partido del Dibu Mart\u00ednez, Aston Villa le gan\u00f3 a Brighton y sigue en la pelea por la Premier League<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-15\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Ins\u00f3lito: el jugador al que le cobraron dos laterales mal sacados \u00a1en menos de cinco minutos!\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Ins\u00f3lito: el jugador al que le cobraron dos laterales mal sacados \u00a1en menos de cinco minutos!<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-16\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Alianza Lima dio de baja a Carlos Zambrano luego de su causa de abuso sexual \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Alianza Lima dio de baja a Carlos Zambrano luego de su causa de abuso sexual <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-17\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"La figura de Espa\u00f1a que ser\u00e1 baja por cuatro meses y no estar\u00e1 en la Finalissima ante la Selecci\u00f3n\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/japon-revoluciona-el-futbol-y-le-dice-adios-a-los-empates-8.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La figura de Espa\u00f1a que ser\u00e1 baja por cuatro meses y no estar\u00e1 en la Finalissima ante la Selecci\u00f3n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>11\/02\/2026 18:06hs. El f\u00fatbol japon\u00e9s dio un paso audaz en su temporada n\u00famero 100. La J1 League puso en marcha una regla que elimina el empate como resultado final y propone una definici\u00f3n por penales cada vez que un encuentro termine igualado tras los 90 minutos. La medida comenz\u00f3 a aplicarse desde la primera fecha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":131145,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/131144"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=131144"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/131144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/131145"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=131144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=131144"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=131144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}