{"id":130951,"date":"2026-02-09T21:52:53","date_gmt":"2026-02-09T21:52:53","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-ascenso\/ascenso-primera-b-maradona-san-lorenzo-refuerzo-villa-san-carlos_0_SNot2JiqhR.html"},"modified":"2026-02-09T21:52:53","modified_gmt":"2026-02-09T21:52:53","slug":"jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/09\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b\/","title":{"rendered":"Jug\u00f3 en Europa, lo dirigi\u00f3 Maradona y es refuerzo en la Primera B"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2026-02-09T18:52:53-03:00\">09\/02\/2026 18:52hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"33.359042553191\">\n<p>El <strong>2025 de <a href=\"https:\/\/www.ole.com.ar\/tema\/villa-san-carlos.html\" title=\"Villa San Carlos\" alt=\"Villa San Carlos\" class=\"slug\">Villa San Carlos<\/a><\/strong> se puede describir como un a\u00f1o <strong>positivo<\/strong>. La <strong>s\u00e9ptima posici\u00f3n en el Apertura<\/strong> y la <strong>d\u00e9cima en el Clausura<\/strong> le permitieron <strong>ingresar al Reducido desde la sexta plaza<\/strong>, instancia en la que cay\u00f3 frente al ascendido <a href=\"https:\/\/www.ole.com.ar\/tema\/acassuso.html\" title=\"Acassuso\" alt=\"Acassuso\" class=\"slug\">Acassuso<\/a> en la primera ronda. Pero desde la CD quieren que <strong>2026 sea distinto<\/strong>, y <strong>para reforzar el mediocampo incorporaron a <a href=\"https:\/\/www.ole.com.ar\/tema\/franco-mussis.html\" title=\"Franco Mussis\" alt=\"Franco Mussis\" class=\"slug\">Franco Mussis<\/a><\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>S\u00ed, el futbolista que <strong>supo jugar en Europa y militar durante varias temporadas en San Lorenzo<\/strong>, esta campa\u00f1a prestar\u00e1 sus servicios en la <strong>tercera categor\u00eda del f\u00fatbol argentino<\/strong>. Luego de quedar <strong>libre desde Chile<\/strong>, el mediocampista se entren\u00f3 en Berisso y a una semana del arranque de la divisional, <strong>el cuerpo t\u00e9cnico dio el visto bueno para su contrataci\u00f3n definitiva<\/strong>.<\/p>\n<\/div>\n<p><h2>Una carrera con nombres pesados<\/h2>\n<\/p>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37.486338797814\">\n<p>El Cele mete un refuerzo que <strong>llega en buena edad (33 a\u00f1os)<\/strong>, con <strong>roce internacional y del Ascenso<\/strong> <strong>y con una enorme trayectoria<\/strong>. Esas variables, con el diario del viernes, avalan por dem\u00e1s su contrataci\u00f3n. <strong>Surgi\u00f3 de <a href=\"https:\/\/www.ole.com.ar\/tema\/gimnasia-la-plata.html\" title=\"Gimnasia La Plata\" alt=\"Gimnasia La Plata\" class=\"slug\">Gimnasia<\/a><\/strong> y logr\u00f3 ascender con el Lobo. Fue tal su rendimiento que <strong>en 2014, a sus 22 a\u00f1os, emigr\u00f3 a Europa y jug\u00f3 en el <a href=\"https:\/\/www.ole.com.ar\/tema\/fc-copenhague.html\" title=\"FC Copenhague\" alt=\"FC Copenhague\" class=\"slug\">Copenhague<\/a> y en el <a href=\"https:\/\/www.ole.com.ar\/tema\/genoa.html\" title=\"Genoa\" alt=\"Genoa\" class=\"slug\">Genoa<\/a><\/strong>. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-4\"><img alt=\"Mussis en su paso por Genoa.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b-2.jpg\"><span class=\"epigraphe\">Mussis en su paso por Genoa.<\/span><\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"36.285035629454\">\n<p>Dos partidos solamente disput\u00f3 en el Viejo Continente y regres\u00f3 para tener una de sus mejores etapas. Fue en <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" title=\"San Lorenzo\" alt=\"San Lorenzo\" class=\"slug\">San Lorenzo<\/a><\/strong> donde jug\u00f3 de manera bastante regular y <strong>cerr\u00f3 su etapa reci\u00e9n en 2018<\/strong>, luego de <strong>98 encuentros y tres tantos<\/strong>. Y su destino no fue cualquiera. Uno vuelve a donde siempre fue feliz dice el dicho, y eso hizo el Gordo: <strong>tuvo un segundo ciclo en el Tripero, y tuvo el lujo de ser dirigido por <a href=\"https:\/\/www.ole.com.ar\/tema\/diego-maradona.html\" title=\"Diego Maradona\" alt=\"Diego Maradona\" class=\"slug\">Maradona<\/a><\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-6\" class=\"sc-136cd478-0 ekTCfV\" readability=\"34.174242424242\">\n<p>Tras un <strong>paso por <a href=\"https:\/\/www.ole.com.ar\/tema\/atletico-tucuman.html\" title=\"Atl\u00e9tico Tucum\u00e1n\" alt=\"Atl\u00e9tico Tucum\u00e1n\" class=\"slug\">Atl\u00e9tico Tucum\u00e1n<\/a>, se fue a Rumania<\/strong> para jugar durante una temporada en el Fotbal Club Boto\u0219ani. Posteriormente pas\u00f3 por el <strong>Aquila 1902 Montevarchi de la tercera italiana y desembarc\u00f3 despu\u00e9s en <a href=\"https:\/\/www.ole.com.ar\/tema\/ferro.html\" title=\"Ferro\" alt=\"Ferro\" class=\"slug\">Ferro<\/a><\/strong>, para estar presente en 30 cotejos y jugar la PN tras 11 a\u00f1os. Su <strong>\u00faltimo paso fue en Chile<\/strong>, <strong>en <a href=\"https:\/\/www.ole.com.ar\/tema\/universidad-de-concepcion.html\" title=\"Universidad de Concepci\u00f3n\" alt=\"Universidad de Concepci\u00f3n\" class=\"slug\">Universidad de Concepci\u00f3n<\/a>, donde logr\u00f3 el Ascenso a la m\u00e1xima categor\u00eda<\/strong>. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-7\"><img alt=\"Llega luego de ser campe\u00f3n en Chile.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b-3.jpg\"><span class=\"epigraphe\">Llega luego de ser campe\u00f3n en Chile.<\/span><\/div>\n<p><h2>Un mercado de pases auspicioso<\/h2>\n<\/p>\n<div id=\"element-body-9\" class=\"sc-136cd478-0 ekTCfV\" readability=\"32.325791855204\">\n<p>En nombres, <strong>las incorporaciones de la Villa retumban fuerte<\/strong>. La v <strong>uelta de <a href=\"https:\/\/www.ole.com.ar\/tema\/rodrigo-salinas.html\" title=\"Rodrigo Salinas\" alt=\"Rodrigo Salinas\" class=\"slug\">Rodrigo Salinas<\/a><\/strong> al club despu\u00e9s de 17 a\u00f1os hacen ilusionar al pueblo de Berisso. Pero a los grandes nombres como el del Potro o Mussis los acompa\u00f1an <strong>jugadores de gran 2025 y tambi\u00e9n juveniles que llegan libres o a pr\u00e9stamo desde <a href=\"https:\/\/www.ole.com.ar\/tema\/primera-division.html\" title=\"Primera Divisi\u00f3n\" alt=\"Primera Divisi\u00f3n\" class=\"slug\">Primera Division<\/a><\/strong>, tales como Fernando Far\u00edas (de <a href=\"https:\/\/www.ole.com.ar\/tema\/defensa-y-justicia.html\" title=\"Defensa y Justicia\" alt=\"Defensa y Justicia\" class=\"slug\">Defensa y Justicia<\/a>), Sebasti\u00e1n Flores (de <a href=\"https:\/\/www.ole.com.ar\/tema\/racing.html\" title=\"Racing\" alt=\"Racing\" class=\"slug\">Racing<\/a>) o Santino Fabi (de <a href=\"https:\/\/www.ole.com.ar\/tema\/estudiantes-de-la-plata.html\" title=\"Estudiantes de La Plata\" alt=\"Estudiantes de La Plata\" class=\"slug\">Estudiantes<\/a>).<\/p>\n<\/div>\n<div id=\"element-body-10\" class=\"sc-136cd478-0 ekTCfV\" readability=\"34.25\">\n<p>El <strong>debut de Villa San Carlos<\/strong> ser\u00e1 el <strong>s\u00e1bado 14 de febrero, a las 17 horas, en condici\u00f3n de local, ante <a href=\"https:\/\/www.ole.com.ar\/tema\/liniers.html\" title=\"Liniers\" alt=\"Liniers\" class=\"slug\">Liniers<\/a><\/strong>. El Cele quiere pelear arriba.<\/p>\n<\/div>\n<div id=\"element-body-11\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Informe Ol\u00e9: los argentinos de las cinco grandes ligas que pasaron por el Ascenso\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Informe Ol\u00e9: los argentinos de las cinco grandes ligas que pasaron por el Ascenso<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-12\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Se vienen las finales del Regional Amateur: los ocho equipos que pelear\u00e1n por los cuatro ascensos al Federal A\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Se vienen las finales del Regional Amateur: los ocho equipos que pelear\u00e1n por los cuatro ascensos al Federal A<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-13\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Rescindi\u00f3 en River y continuar\u00e1 su carrera en el Ascenso \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jugo-en-europa-lo-dirigio-maradona-y-es-refuerzo-en-la-primera-b-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Rescindi\u00f3 en River y continuar\u00e1 su carrera en el Ascenso <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>09\/02\/2026 18:52hs. El 2025 de Villa San Carlos se puede describir como un a\u00f1o positivo. La s\u00e9ptima posici\u00f3n en el Apertura y la d\u00e9cima en el Clausura le permitieron ingresar al Reducido desde la sexta plaza, instancia en la que cay\u00f3 frente al ascendido Acassuso en la primera ronda. Pero desde la CD quieren que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130951"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130951"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130952"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130951"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}