{"id":130949,"date":"2026-02-09T21:53:22","date_gmt":"2026-02-09T21:53:22","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-primera\/gigliotti-retiro-colon-puma_0_wFxXvJ2h7Q.html"},"modified":"2026-02-09T21:53:22","modified_gmt":"2026-02-09T21:53:22","slug":"emmanuel-gigliotti-anuncio-su-retiro","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/09\/emmanuel-gigliotti-anuncio-su-retiro\/","title":{"rendered":"Emmanuel Gigliotti anunci\u00f3 su retiro"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2026-02-09T18:53:22-03:00\">09\/02\/2026 18:53hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"36.034985422741\">\n<p>De alta eficacia dentro del \u00e1rea y <strong>autor de m\u00e1s de 100 goles<\/strong> en su paso por el f\u00fatbol argentino, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/emmanuel-gigliotti.html\" title=\"Emmanuel Gigliotti\" alt=\"Emmanuel Gigliotti\" class=\"slug\">Emmanuel Gigliotti<\/a><\/strong> es un delantero que se destac\u00f3 por jugar en tres grandes, San Lorenzo, Boca e Independiente, desde <strong>2010.<\/strong> Formando en <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/general-lamadrid.html\" title=\"General Lamadrid\" alt=\"General Lamadrid\" class=\"slug\">General Lamadrid<\/a><\/strong>, el Puma visti\u00f3 la camiseta de 13 clubes a lo largo de su carrera y gan\u00f3 seis t\u00edtulos.<\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35.776081424936\">\n<p>Sin embargo, nada dura para siempre y Gigliotti lo sabe: <strong>hoy con 38 a\u00f1os, el atacante anunci\u00f3 su retiro tras finalizar su segunda etapa en <a href=\"https:\/\/www.ole.com.ar\/tema\/colon.html\" title=\"Col\u00f3n\" alt=\"Col\u00f3n\" class=\"slug\">Col\u00f3n<\/a> de Santa Fe<\/strong>. El futbolista hab\u00eda retornado al Sabalero en enero de 2025 para luchar por el <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/primera-nacional.html\" title=\"Primera Nacional\" alt=\"Primera Nacional\" class=\"slug\">ascenso<\/a><\/strong> a la Primera Divisi\u00f3n. Luego de no poder cumplir el objetivo y despu\u00e9s de tener una extensa trayectoria <strong>el jugador decidi\u00f3 colgar los botines.<\/strong><\/p>\n<\/div>\n<p><h2><strong>Las palabras del Puma<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>\u00abLo ven\u00eda trabajando todo este a\u00f1o con una psic\u00f3loga. Lo quer\u00eda hacer en 2025 cuando volv\u00ed de Chile, pero sali\u00f3 lo de Col\u00f3n y empec\u00e9 a pensar qu\u00e9 hacer. <strong>Con el transcurrir del a\u00f1o, decid\u00ed que no iba a jugar m\u00e1s<\/strong>. No s\u00e9 si estoy contentando por la decisi\u00f3n, pero me pasa que tampoco estoy triste. <strong>Estoy tranquilo<\/strong>\u00ab, explic\u00f3 el bonaerense en el programa Todo Pasa de Urbana Play.<\/p>\n<\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>\u00bb <strong>Tom\u00e9 la decisi\u00f3n teniendo todav\u00eda oportunidades<\/strong>. Por suerte, para mi ego, me siguieron llamando clubes. F\u00edsicamente yo me sent\u00eda bien, no estaba todo roto, lo que pasa es que me cans\u00e9 un poco\u00bb, agreg\u00f3.<\/p>\n<\/div>\n<p><h2><strong>Una carrera postivia<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-7\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35.653206650831\">\n<p>Como muchos futbolistas, y por m\u00e1s clich\u00e9 que suene, <strong>Gigliotti tuvo una carrera mucho mejor de la que alguna vez so\u00f1\u00f3<\/strong>. El Puma dio sus primeros pasos en General Lamadrid de la 4\u00aa categor\u00eda del f\u00fatbol argentino en 2006 y <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/argentinos-juniors.html\" title=\"Argentinos Juniors\" alt=\"Argentinos Juniors\" class=\"slug\">Argentinos Juniors<\/a><\/strong> lo compr\u00f3 en 2008. Sin embargo, el delantero r\u00e1pidamente fue dado a pr\u00e9stamo a <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/all-boys.html\" title=\"All Boys\" alt=\"All Boys\" class=\"slug\">All Boys<\/a><\/strong> e instantemente la rompi\u00f3 al convertir m\u00e1s de 20 tantos con el cuadro de Floresta.<\/p>\n<\/div>\n<div id=\"element-body-8\" class=\"sc-136cd478-0 ekTCfV\" readability=\"29.761732851986\">\n<p>Aquel paso le abri\u00f3 las puertas de <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/atletico-tucuman.html\" title=\"Atl\u00e9tico Tucum\u00e1n\" alt=\"Atl\u00e9tico Tucum\u00e1n\" class=\"slug\">Atl\u00e9tico Tucum\u00e1n<\/a><\/strong> y del <strong>Novara Calcio<\/strong> italiano, previo a recalar en <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" title=\"San Lorenzo\" alt=\"San Lorenzo\" class=\"slug\">San Lorenzo<\/a><\/strong> a mediados de 2011. En esa temporada, el atacante fue clave para que el <strong>Cicl\u00f3n llegase a la <a href=\"https:\/\/www.ole.com.ar\/tema\/promocion.html\" title=\"Promocion\" alt=\"Promocion\" class=\"slug\">Promoci\u00f3n<\/a><\/strong> y se salvara de perder la categor\u00eda frente a <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/instituto-cordoba.html\" title=\"Instituto de C\u00f3rdoba\" alt=\"Instituto de C\u00f3rdoba\" class=\"slug\">Instituto<\/a><\/strong>.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-9\"><img alt=\"Gigliotti fue clave para que el Cicl\u00f3n se salvara del descenso. \" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro-2.jpg\"><span class=\"epigraphe\">Gigliotti fue clave para que el Cicl\u00f3n se salvara del descenso. <\/span><\/div>\n<div id=\"element-body-10\" class=\"sc-136cd478-0 ekTCfV\" readability=\"31.076604554865\">\n<p>Con la misi\u00f3n cumplida, el ariete se march\u00f3 a Col\u00f3n y en su primer paso por el conjunto de Santa Fe <strong>convirti\u00f3 23 anotaciones en 41 presencias<\/strong>; grandes n\u00fameros que le permitieron llegar a <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/boca-juniors.html\" title=\"Boca Juniors\" alt=\"Boca Juniors\" class=\"slug\">Boca<\/a><\/strong>, un cap\u00edtulo medio amargo en su historia: su ciclo en el Xeneize qued\u00f3 inmortalizado por su gol ante <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a><\/strong> Torneo Inicial 2013 y <strong><a href=\"https:\/\/www.ole.com.ar\/river-plate\/marcelo-barovero-river-gallardo_0_BUYGV4ju-.html\" target=\"_self\" title=\"su penal atajado por Marcelo Barovero en la vuelta de la Copa Sudamericana 2014\" alt=\"su penal atajado por Marcelo Barovero en la vuelta de la Copa Sudamericana 2014\" rel=\"noopener noreferrer\">su penal atajado por Marcelo Barovero en la vuelta de la Copa Sudamericana 2014<\/a><\/strong>, d\u00eda en el que el Millonario elimin\u00f3 al Club de la Ribera en semifinales.<\/p>\n<\/div>\n<div id=\"element-body-11\" class=\"sc-136cd478-0 ekTCfV\" readability=\"32.845425867508\">\n<p>Sin embargo, tras jugar en el <strong>Chongqing Lifan<\/strong> chino, el jugador tuvo su revancha con la casaca de <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/club-atletico-independiente.html\" title=\"Club Atl\u00e9tico Independiente\" alt=\"Club Atl\u00e9tico Independiente\" class=\"slug\">Independiente<\/a><\/strong>: el goleador fue fundamental en la obtenci\u00f3n de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/copa-sudamericana.html\" title=\"Copa Sudamericana\" alt=\"Copa Sudamericana\" class=\"slug\">Copa Sudamericana 2017<\/a><\/strong> al marcarle al <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/flamengo.html\" title=\"Flamengo\" alt=\"Flamengo\" class=\"slug\">Flamengo<\/a><\/strong> en la final de ida. En total, el bonaerense rompi\u00f3 las redes en 27 ocasiones durante su etapa en el Rojo.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-12\"><img alt=\"El Puma tuvo su revancha en la Sudamericana con Independiente. \" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro-3.jpg\"><span class=\"epigraphe\">El Puma tuvo su revancha en la Sudamericana con Independiente. <\/span><\/div>\n<div id=\"element-body-13\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39.09756097561\">\n<p>Finalmente, luego de ser pasar por el <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/toluca.html\" title=\"Toluca\" alt=\"Toluca\" class=\"slug\">Toluca<\/a><\/strong>, <strong>Le\u00f3n<\/strong>, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/nacional-montevideo.html\" title=\"Nacional Montevideo\" alt=\"Nacional Montevideo\" class=\"slug\">Nacional<\/a> <\/strong>-con el que fue tricampe\u00f3n- <strong>Uni\u00f3n La Calera<\/strong> y nuevamente por <strong>Col\u00f3n<\/strong>, <strong>Gigliotti anunci\u00f3 su retiro durante este lunes para dejar atr\u00e1s una trayectoria m\u00e1s que deseada<\/strong>. En conjunto, hizo <strong>172 goles y dio 36 asistencias en 544 encuentros<\/strong>. Adem\u00e1s, junto a sus seis t\u00edtulos colectivos ganados, tambi\u00e9n se suma su premio al <strong>M\u00e1ximo Goleador del Torneo Final 2013<\/strong> y el gusto de haber vestido la camiseta de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Selecci\u00f3n Argentina<\/a><\/strong>.<\/p>\n<\/div>\n<div id=\"element-body-14\" class=\"sc-a7166897-0 eoLsBE\" readability=\"32\">\n<section readability=\"4\"><picture><img alt=\"Con el 5 a 0 del PSG, estas son las goleadas m\u00e1s abultadas de los \u00faltimos a\u00f1os en los cl\u00e1sicos del mundo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con el 5 a 0 del PSG, estas son las goleadas m\u00e1s abultadas de los \u00faltimos a\u00f1os en los cl\u00e1sicos del mundo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-15\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Copa Argentina: la llave, dos partidos en la semana y debuta Di Mar\u00eda\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Copa Argentina: la llave, dos partidos en la semana y debuta Di Mar\u00eda<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-16\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Argentina cay\u00f3 ante Chile en el inicio del Torneo Internacional J\u00f3venes Promesas \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/emmanuel-gigliotti-anuncio-su-retiro-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Argentina cay\u00f3 ante Chile en el inicio del Torneo Internacional J\u00f3venes Promesas <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>09\/02\/2026 18:53hs. De alta eficacia dentro del \u00e1rea y autor de m\u00e1s de 100 goles en su paso por el f\u00fatbol argentino, Emmanuel Gigliotti es un delantero que se destac\u00f3 por jugar en tres grandes, San Lorenzo, Boca e Independiente, desde 2010. Formando en General Lamadrid, el Puma visti\u00f3 la camiseta de 13 clubes a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130950,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130949"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130949"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130950"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130949"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}