{"id":130878,"date":"2026-02-08T21:01:52","date_gmt":"2026-02-08T21:01:52","guid":{"rendered":"https:\/\/www.trendencias.com\/silver\/jose-abellan-cardiologo-quienes-usan-colutorio-forma-habitual-aumentan-su-riesgo-hipertension-85-comparacion-quienes-no-usan"},"modified":"2026-02-08T21:01:52","modified_gmt":"2026-02-08T21:01:52","slug":"jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/08\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan\/","title":{"rendered":"Jos\u00e9 Abell\u00e1n, cardi\u00f3logo: \u00abQuienes usan colutorio de forma habitual aumentan su riesgo de hipertensi\u00f3n un 85%, en comparaci\u00f3n con quienes no los usan\u00bb"},"content":{"rendered":"<p>Si tu cardi\u00f3logo no te recomienda usar <a rel=\"noopener, noreferrer\" href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC9124908\/\">colutorios antibacterianos<\/a> no es que est\u00e9 loco ni se crea que no has ido al dentista es que la ciencia los vincula con <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.elconfidencial.com\/alma-corazon-vida\/2025-09-11\/1qrt-isabel-vina-medico-sandia-tomate_4204407\/\">riesgo de hipertensi\u00f3n<\/a>. El problema est\u00e1 en que muchos de los colutorios antibacterianos orales contienen <strong>clorhexidina o compuestos con nitratos<\/strong>, que s\u00ed, ayudan a combatir bacterias y la placa, pero algunos de los ingredientes pueden interferir con <a rel=\"noopener, noreferrer\" href=\"https:\/\/pubmed.ncbi.nlm.nih.gov\/32210245\/\">la microbiota de tu boca<\/a>.&nbsp;<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>\u00abQuienes los usan de forma habitual <strong>aumentan su riesgo de hipertensi\u00f3n un 85%<\/strong>, en comparaci\u00f3n con quienes no los usan\u201d, ha publicado el doctor <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/doctorabellan\/?hl=es\">Jos\u00e9 Abell\u00e1n<\/a> en un <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/p\/DUOc_tyDUGr\/?hl=es\">v\u00eddeo<\/a> muy divertido que ha compartido en su perfil de Instagram, donde literalmente tira el colutorio por la taza del w\u00e1ter. Y poca broma con esto porque existen varios estudios relacionados con el tema.&nbsp;<\/p>\n<p><!-- BREAK 2 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/p\/DUOc_tyDUGr\/?hl=es\"> <img class=\"centro_sinmarco\" height=\"553\" width=\"656\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-3.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-4.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-5.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan.jpg\" alt=\"Colutorios Hipertension\"> <noscript><img alt=\"Colutorios Hipertension\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan.jpg\"><\/noscript> <\/a> <\/div>\n<\/div>\n<p>El cardi\u00f3logo adem\u00e1s advierte que <strong>la consecuencia puede ser directa y casi inmediata<\/strong> \u201cen minutos o en menos de una hora y su efecto es m\u00e1s intenso en colutorios que tienen clorhexidina\u201d, a\u00f1ade.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>Nuestra boca juega un papel fundamental en la producci\u00f3n de \u00f3xido n\u00edtrico, un <strong>vasodilatador natural que ayuda a mantener bajo control la presi\u00f3n arteria<\/strong>l. El problema est\u00e1 en que \u201clos colutorios antibacterianos atacan a las bacterias orales con capacidad de <a rel=\"noopener, noreferrer\" href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC6700760\/\">convertir los nitratos a nitritos<\/a>, y ello reduce el \u00f3xido n\u00edtrico que pasa a tu cuerpo&#8230;\u201d, lo que provoca la hipertensi\u00f3n, explica el doctor.<\/p>\n<p>Por lo que el uso de colutorios antibacterianos puede alterar este equilibrio y en aquellas personas que ya sufren hipertensi\u00f3n o riesgo cardiovascular, notar la repercusi\u00f3n en el mismo instante. Pero, la buena noticia, tal y como dice el doctor es que \u201c<strong>la recuperaci\u00f3n de la microbiota, tras suspender el colutorio se asocia con la normalizaci\u00f3n de la presi\u00f3n arterial<\/strong>\u201d, tranquiliza.&nbsp;<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1500\" width=\"1000\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-6.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-7.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-8.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-1.jpg\" alt=\"Colutorio Bucal\"> <noscript><img alt=\"Colutorio Bucal\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jose-abellan-cardiologo-quienes-usan-colutorio-de-forma-habitual-aumentan-su-riesgo-de-hipertension-un-85-en-comparacion-con-quienes-no-los-usan-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Y no hace falta que te obsesiones con el tema porque Abell\u00e1n tambi\u00e9n comenta que hasta donde \u00e9l sabe estos efectos <strong>no se han asociado con \u201cpastas dent\u00edfricas o colutorios no antibacterianos\u201d<\/strong>.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Algo importante que debes tener en cuenta es que<strong> la salud bucal <\/strong>no puede faltar en tu d\u00eda a d\u00eda porque est\u00e1 directamente relacionada con el buen funcionamiento de tu coraz\u00f3n, puesto que \u201c<a rel=\"noopener, noreferrer\" href=\"https:\/\/www.mdpi.com\/1660-4601\/21\/10\/1319\">disminuye tu riesgo de sufrir un evento cardiovascular<\/a> como un infarto, o infecciones importantes del coraz\u00f3n como las endocarditis\u201d.&nbsp;<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<p>Y es que ya lo dicen expertos como el doctor Gundry, un mal <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/silver\/dr-steven-gundy-cirujano-relacion-higiene-oral-alzheimer-hay-ciertas-bacterias-como-que-causan-gingivitis-que-se-han-aislado-pacientes-han-llegado-alli-mala-higiene-dental\" data-vars-post-title=\"Cuidar tu sonrisa podr\u00eda proteger tu cerebro de desarrollar una demencia o padecer Alzh\u00e9imer, as\u00ed lo explica el cirujano Steven Gundry \" data-vars-post-url=\"https:\/\/www.trendencias.com\/silver\/dr-steven-gundy-cirujano-relacion-higiene-oral-alzheimer-hay-ciertas-bacterias-como-que-causan-gingivitis-que-se-han-aislado-pacientes-han-llegado-alli-mala-higiene-dental\">cuidado del microbioma bucal&nbsp;<\/a>puede generar <strong>la aparici\u00f3n de Alzh\u00e9imer<\/strong>, <strong>la enfermedad de Parkinson<\/strong>, <strong>demencia<\/strong> y <strong>tambi\u00e9n afectar al coraz\u00f3<\/strong><strong>n<\/strong>.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>Fotograf\u00edas |&nbsp;Freepik, <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.instagram.com\/p\/DUOc_tyDUGr\/?hl=es\">@doctorabellan<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/vital.doctorabellan.com\/sobre-mi\/\">www.vital.doctorabellan.com<\/a><\/p>\n<p>En Trendencias |&nbsp;<a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/silver\/aurelio-rojas-cardiologo-solo-tres-nueces-tres-veces-a-semana-bajaras-colesterol-malo-riesgo-infarto-46\" data-vars-post-title=\"Aurelio Rojas, cardi\u00f3logo: &quot;Come varias nueces a la semana, especialmente si quieres proteger tu coraz\u00f3n sin medicamentos y con alimentos de verdad&quot;\" data-vars-post-url=\"https:\/\/www.trendencias.com\/silver\/aurelio-rojas-cardiologo-solo-tres-nueces-tres-veces-a-semana-bajaras-colesterol-malo-riesgo-infarto-46\">Aurelio Rojas, cardi\u00f3logo: \u00abCome varias nueces a la semana, especialmente si quieres proteger tu coraz\u00f3n sin medicamentos y con alimentos de verdad\u00bb<\/a><\/p>\n<p><!-- BREAK 8 --><\/p>\n<p>En Trendencias |&nbsp;<a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/silver\/alexandre-olmos-medico-estas-cinco-analiticas-que-me-hago-cada-ano-para-adelantarme-a-que-pasa-cuerpo-evitar-enfermedades-cronicas\" data-vars-post-title=\"Alexandre Olmos, m\u00e9dico: &quot;Para prevenir enfermedades y optimizar energ\u00eda, una vez al a\u00f1o me hago estas anal\u00edticas&quot;\" data-vars-post-url=\"https:\/\/www.trendencias.com\/silver\/alexandre-olmos-medico-estas-cinco-analiticas-que-me-hago-cada-ano-para-adelantarme-a-que-pasa-cuerpo-evitar-enfermedades-cronicas\">Alexandre Olmos, m\u00e9dico: \u00abPara prevenir enfermedades y optimizar energ\u00eda, una vez al a\u00f1o me hago estas anal\u00edticas\u00bb<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tu cardi\u00f3logo no te recomienda usar colutorios antibacterianos no es que est\u00e9 loco ni se crea que no has ido al dentista es que la ciencia los vincula con riesgo de hipertensi\u00f3n. El problema est\u00e1 en que muchos de los colutorios antibacterianos orales contienen clorhexidina o compuestos con nitratos, que s\u00ed, ayudan a combatir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130878"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130878"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130878\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130879"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130878"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}