{"id":130858,"date":"2026-02-08T19:16:57","date_gmt":"2026-02-08T19:16:57","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/espana\/sevilla-girona-almeyda-penal-liga-espana_0_CKQ5PXy00x.html"},"modified":"2026-02-08T19:16:57","modified_gmt":"2026-02-08T19:16:57","slug":"la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/08\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta\/","title":{"rendered":"La bomba de Almeyda tras el empate ag\u00f3nico del Sevilla: \u00abYa ni el arbitraje nos respeta\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta.jpg\"><\/p>\n<p><span class=\"createDate\">08\/02\/2026 16:16hs.<\/span><time class=\"modificatedDate\" datetime=\"2026-02-08T16:48:03-03:00\"> Actualizado al 08\/02\/2026 16:48hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"34.655440414508\">\n<p><a href=\"https:\/\/www.ole.com.ar\/tema\/sevilla.html\" title=\"Sevilla\" alt=\"Sevilla\" class=\"slug\">Sevilla<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/girona.html\" title=\"girona\" alt=\"girona\" class=\"slug\">Girona<\/a>, <strong>dos equipos que luchan por la permanencia en la <a href=\"https:\/\/www.ole.com.ar\/tema\/la-liga-de-espana.html\" title=\"La Liga de Espa\u00f1a\" alt=\"La Liga de Espa\u00f1a\" class=\"slug\">Liga de Espa\u00f1a<\/a>, empataron 1-1 en el S\u00e1nchez-Pizju\u00e1n<\/strong> en un partido que fue aplazado el s\u00e1bado por la alerta meteorol\u00f3gica en Andaluc\u00eda. Un gol de Kike Salas y un penal atajado por el griego Odysseas Vlachodimos al uruguayo Cristhian Stuani, en el tiempo a\u00f1adido, <strong>dieron algo de aire al conjunto de <a href=\"https:\/\/www.ole.com.ar\/tema\/matias-almeyda.html\" title=\"Mat\u00edas Almeyda\" alt=\"Mat\u00edas Almeyda\" class=\"slug\">Mat\u00edas Almeyda<\/a>.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"40\">\n<p>El Pelado, luego del partido, <strong>se quej\u00f3 por un penal que no le dieron a su equipo<\/strong> a los siete minutos del primer tiempo, cuando ya perd\u00edan 1-0. En la jugada, la pelota le da en la mano al defensor al defensor de Girona cuando estaba en una posici\u00f3n antinatural, pero el VAR no convoc\u00f3 al juez de campo. <\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"40\">\n<p>Luego del partido, el entrenador explot\u00f3 contra los jueces, teniendo en cuenta que cada punto vale oro para sus dirigidos. <strong>\u00abHe visto la foto, parece que el VAR y el \u00e1rbitro no la han visto\u00bb<\/strong>, sentenci\u00f3 Almeyda. Sobre la foto en cuesti\u00f3n que menciona el DT, la cuenta oficial de Sevilla public\u00f3 la imagen donde se ve c\u00f3mo la pelota le pega en la mano al central de Girona.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-3\"><img alt=\"Almeyda, furioso contra el arbitraje. (EFE)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-2.jpg\"><span class=\"epigraphe\">Almeyda, furioso contra el arbitraje. (EFE)<\/span><\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"44\">\n<p>\u00bb <strong>No s\u00e9 si la foto es trucada, pero parec\u00eda que iba a jugar al basket.<\/strong> No me detengo en eso, porque el \u00faltimo penalti lo hicimos nosotros. <strong>Es dif\u00edcil que nos cobren algo, porque ya ni el arbitraje nos respeta<\/strong>\u00ab, apunt\u00f3. Acerca del juego, dijo: \u00abLo hicimos muy mal en el primer tiempo. En el segundo tiempo mejoramos, por eso empatamos. Por otro error, casi perdemos nuevamente. Esto es lo que somos, esto es lo que tenemos que seguir trabajando, porque no es f\u00e1cil\u00bb.<\/p>\n<\/div>\n<div id=\"element-body-6\" class=\"sc-ef81c825-1 evSCNc\"><figcaption class=\"JWvideoNota_title\">\n<p>Video: @elchiringuitotv<\/p>\n<\/figcaption><\/div>\n<p><h2><strong>Sevilla y Girona igualaron 1-1<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-8\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Tras un primer tiempo dominado por los visitantes, que se adelantaron con un gol del franc\u00e9s Thomas Lemar, cuando s\u00f3lo hab\u00eda pasado un <strong>minuto y 40 segundos de juego<\/strong>, y tuvieron ocasiones para ampliar su ventaja, el Sevilla reaccion\u00f3 en el segundo con un triple cambio al descanso y empuj\u00f3 hasta <strong> igualar en el tiempo a\u00f1adido con un golazo de Kike Salas en un final de infarto<\/strong>. <strong>Stuani tuvo en sus pies el triunfo para el Girona pero Vlachodimos se visti\u00f3 de h\u00e9roe para los locales.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-9\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p>Era un duelo trascendental en la lucha por la permanencia, entre dos equipos muy cerca de la zona de descenso y separados por un solo punto, que llegaban a la cita tras dos derrotas dolorosas. Sevilla ante otro rival directo como el Mallorca (4-1) y el Girona de M\u00edchel S\u00e1nchez en casa ante el Real Oviedo, el \u00faltimo de la tabla (1-0). <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-10\"><img alt=\"Odysseas Vlachodimos, el h\u00e9roe del Sevilla. (EFE)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-3.jpg\"><span class=\"epigraphe\">Odysseas Vlachodimos, el h\u00e9roe del Sevilla. (EFE)<\/span><\/div>\n<div id=\"element-body-11\" class=\"sc-136cd478-0 ekTCfV\" readability=\"29.586206896552\">\n<p><strong>El <a href=\"https:\/\/www.ole.com.ar\/tema\/claudio-echeverri.html\" title=\"Claudio Echeverri\" alt=\"Claudio Echeverri\" class=\"slug\">Diablito Echeverri<\/a> ingres\u00f3 para jugar toda la segunda mitad en Girona.<\/strong> El volante argentino perdi\u00f3 la pelota en la jugada que termin\u00f3 en el empate del conjunto andaluz.<\/p>\n<\/div>\n<div id=\"element-body-12\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p>La pr\u00f3xima fecha, habr\u00e1 otro partido de alto voltaje para Sevilla, tambi\u00e9n en condici\u00f3n de local. <strong>Recibir\u00e1 al Alav\u00e9s de Eduardo Coudet el pr\u00f3ximo s\u00e1bado 14 de febrero a las 14:30 de la Argentina. <\/strong>En un duelo de entrenadores argentinos y con la zona roja cada vez m\u00e1s cerca para ambos. En tanto, Girona recibir\u00e1 en su casa al puntero Barcelona el lunes 16 a las 17:00.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-13\"><img alt=\"Sevilla y Girona empataron 1-1. (EFE)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-4.jpg\"><span class=\"epigraphe\">Sevilla y Girona empataron 1-1. (EFE)<\/span><\/div>\n<p><h2><strong>El resumen del partido<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-15\" class=\"sc-ef81c825-1 evSCNc\"><figcaption class=\"JWvideoNota_title\">\n<p>Cr\u00e9ditos: DSports<\/p>\n<\/figcaption><\/div>\n<p><h2><strong>La tabla de la Liga de Espa\u00f1a<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-18\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"El gol del ex Boca que complic\u00f3 al Alav\u00e9s de Chacho Coudet \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El gol del ex Boca que complic\u00f3 al Alav\u00e9s de Chacho Coudet <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-19\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"La impresionante goleada de Costa Rica por \u00a126-0! que rompi\u00f3 los r\u00e9cords del f\u00fatbol en Am\u00e9rica\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La impresionante goleada de Costa Rica por \u00a126-0! que rompi\u00f3 los r\u00e9cords del f\u00fatbol en Am\u00e9rica<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-20\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31.5\">\n<section readability=\"3\"><picture><img alt=\"Video: el golazo de Christian Ord\u00f3\u00f1ez para darle el triunfo ag\u00f3nico a Parma en el cl\u00e1sico ante Bologna\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/la-bomba-de-almeyda-tras-el-empate-agonico-del-sevilla-ya-ni-el-arbitraje-nos-respeta-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: el golazo de Christian Ord\u00f3\u00f1ez para darle el triunfo ag\u00f3nico a Parma en el cl\u00e1sico ante Bologna<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>08\/02\/2026 16:16hs. Actualizado al 08\/02\/2026 16:48hs. Sevilla y Girona, dos equipos que luchan por la permanencia en la Liga de Espa\u00f1a, empataron 1-1 en el S\u00e1nchez-Pizju\u00e1n en un partido que fue aplazado el s\u00e1bado por la alerta meteorol\u00f3gica en Andaluc\u00eda. Un gol de Kike Salas y un penal atajado por el griego Odysseas Vlachodimos al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130858"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130858"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130859"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130858"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}