{"id":130850,"date":"2026-02-08T21:32:40","date_gmt":"2026-02-08T21:32:40","guid":{"rendered":"https:\/\/www.ole.com.ar\/basquet\/quimsa-gimnasia-triunfo-liga-nacional-basquet_0_NpJcTYhCwY.html"},"modified":"2026-02-08T21:32:40","modified_gmt":"2026-02-08T21:32:40","slug":"quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/08\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido\/","title":{"rendered":"Quimsa lo cerr\u00f3 mejor, venci\u00f3 a Gimnasia y sum\u00f3 su cuatro triunfo seguido"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2026-02-08T18:32:40-03:00\">08\/02\/2026 18:32hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p><strong>Quimsa est\u00e1 en racha y la prolong\u00f3 contra Gimnasia de Comodoro Rivadavia, al que derrot\u00f3 por 92-82<\/strong> para conseguir su cuarta victoria en fila. El inicio fue parejo y efectivo, Figueredo con ocho puntos para el local y en la visita Totetta junto a Dato con cinco cada uno para el 14-14. <strong>Ambos equipos rotaron jugadores<\/strong>, Freeman y Solanas intentaron crear ventaja para la Fusi\u00f3n pero del otro lado sum\u00f3 Horton para el 26 a 26.<\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"36\">\n<p>Triples de Johnson y Robinson movieron el score de Quimsa, mientras que Gimnasia contest\u00f3 con Cosolito. Cuando parec\u00eda que Dato mandaba a los dirigidos por Favarel arriba al entretiempo, <strong>un triple de Lema estamp\u00f3 el 49-48 santiague\u00f1o.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37\">\n<p>Luego del descanso la dupla Dato-Toretta le dio ventaja de seis a los de Comodoro Rivadavia, tras un minuto del local, Robinson encontr\u00f3 los aciertos en ofensiva para no quedarse atr\u00e1s. Tras un nuevo pasaje gol a gol, <strong>68 iguales a falta de diez minutos.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-3\"><img alt=\"Quimsa sigue on fire. (Prensa Liga Nacional)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido-2.jpg\"><span class=\"epigraphe\">Quimsa sigue on fire. (Prensa Liga Nacional)<\/span><\/div>\n<div id=\"element-body-4\" class=\"sc-136cd478-0 ekTCfV\" readability=\"37\">\n<p>Las defensas aparecieron con el inicio del \u00faltimo segmento, Lema con una volcada levant\u00f3 al p\u00fablico presente, <strong>pero cinco puntos de Cisneros pon\u00edan el 78-78 con 2:40<\/strong>. Meyinsse y Johnson fueron claves cerca de los aros sumando y tomando rebotes defensivos frente a un rival que no pudo ante la f\u00e9rrea defensa de Quimsa.<\/p>\n<\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Johnson a distancia liquid\u00f3 el encuentro, victoria de los dirigidos por Victoriano por 92 a 82. <strong> Brandon Robinson se destac\u00f3 con 17 tantos<\/strong>, adem\u00e1s de los 14 puntos con 8 rebotes de Jerome Meyinsse, del otro lado Martiniano Dato aport\u00f3 22. <strong> Quimsa (14-10) visitar\u00e1 el jueves 19 del corriente a San Lorenzo<\/strong>, Gimnasia (13-10) enfrentar\u00e1 el martes a Ol\u00edmpico.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-6\"><img alt=\"Lucas Victoriano contin\u00faa invicto desde su arribo. (Prensa Liga Nacional)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido-3.jpg\"><span class=\"epigraphe\">Lucas Victoriano contin\u00faa invicto desde su arribo. (Prensa Liga Nacional)<\/span><\/div>\n<div id=\"element-body-7\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Ferro se qued\u00f3 con el cl\u00e1sico hist\u00f3rico de la Liga Nacional frente a Atenas\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Ferro se qued\u00f3 con el cl\u00e1sico hist\u00f3rico de la Liga Nacional frente a Atenas<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-8\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Video: la gente de San Lorenzo cant\u00f3 contra Hurac\u00e1n en un partido de b\u00e1squet \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: la gente de San Lorenzo cant\u00f3 contra Hurac\u00e1n en un partido de b\u00e1squet<br \/>\n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-9\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Zanetti llev\u00f3 la antorcha ol\u00edmpica y dej\u00f3 su huella en los Juegos de Invierno 2026\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/quimsa-lo-cerro-mejor-vencio-a-gimnasia-y-sumo-su-cuatro-triunfo-seguido-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Zanetti llev\u00f3 la antorcha ol\u00edmpica y dej\u00f3 su huella en los Juegos de Invierno 2026<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>08\/02\/2026 18:32hs. Quimsa est\u00e1 en racha y la prolong\u00f3 contra Gimnasia de Comodoro Rivadavia, al que derrot\u00f3 por 92-82 para conseguir su cuarta victoria en fila. El inicio fue parejo y efectivo, Figueredo con ocho puntos para el local y en la visita Totetta junto a Dato con cinco cada uno para el 14-14. Ambos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130851,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130850"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130850"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130850\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130851"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130850"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}