{"id":130590,"date":"2026-02-05T22:01:53","date_gmt":"2026-02-05T22:01:53","guid":{"rendered":"https:\/\/www.trendencias.com\/gourmet\/jorge-pascual-chef-abeto-este-truco-para-afilar-cuchillos-me-enseno-chef-vasco-famoso"},"modified":"2026-02-05T22:01:53","modified_gmt":"2026-02-05T22:01:53","slug":"jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/02\/05\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso\/","title":{"rendered":"Jorge Pascual, chef de El Abeto: \u00abEste truco para afilar cuchillos me lo ense\u00f1\u00f3 un chef vasco famoso\u00bb"},"content":{"rendered":"<p>En tiempos de cocinas cada vez m\u00e1s peque\u00f1as, las soluciones pr\u00e1cticas valen por dos. Por ello, si te quieres ahorrar un cachivache m\u00e1s en cajones y armarios, hay un truco con el que <strong>no necesitas tener en casa ning\u00fan afilador de cuchillos <\/strong>ni gastarte el dinero en dicho accesorio.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Jorge Pascual, chef al frente de <a rel=\"noopener, noreferrer\" href=\"https:\/\/elabetoelche.es\/\">El Abeto<\/a> (en Elche), no solo lo revela sino que lo demuestra en un v\u00eddeo compartido en el TikTok del restaurante. Se trata de <strong>afilar los cuchillos usando la base de una taza de porcelana<\/strong>. Nada de gadgets ni piedras profesionales. Solo una taza del rev\u00e9s y un movimiento de mu\u00f1eca.<\/p>\n<p>Seg\u00fan cuenta Pascual, este truco se lo ense\u00f1\u00f3 \u00abun chef vasco muy conocido\u00bb, aunque no revela el nombre. La explicaci\u00f3n de por qu\u00e9 funciona es muy sencilla: <strong>la porcelana sin esmaltar de la base de la taza es un material abrasivo<\/strong>, similar al que se utiliza en las piedras de afilar.&nbsp;<\/p>\n<p><!-- BREAK 2 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"1619\" width=\"944\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso-2.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso-3.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso-4.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso.jpg\" alt=\"Whatsapp Image 2026 02 05 At Heheh\"> <noscript><img alt=\"Whatsapp Image 2026 02 05 At Heheh\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/02\/jorge-pascual-chef-de-el-abeto-este-truco-para-afilar-cuchillos-me-lo-enseno-un-chef-vasco-famoso.jpg\"><\/noscript> <span>@elabetoelche<\/span> <\/div><\/div>\n<\/div>\n<p>En el v\u00eddeo, el chef hace una demostraci\u00f3n sin trampa ni cart\u00f3n: primero intenta cortar un papel con un cuchillo claramente desafilado, que apenas avanza. Sin embargo, despu\u00e9s de <strong>restregar el filo varias veces por la base de la taza<\/strong>, el mismo cuchillo corta el papel de forma limpia y sin esfuerzo.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>La clave es colocar la taza boca abajo y el cuchillo en un \u00e1ngulo de menos de 90\u00ba para pasar el cuchillo con suavidad, <strong>alternando ambos lados del filo<\/strong>. Un truco sencillo, barato y sorprendentemente eficaz. Eso s\u00ed, m\u00e1s all\u00e1 de por este truco viral, Pascual es un nombre reconocido de la cocina ilicitana.&nbsp;<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>El Abeto, su restaurante en Elche, apuesta por una cocina honesta, de producto y t\u00e9cnica depurada, donde <strong>el respeto por los b\u00e1sicos<\/strong> (como un buen cuchillo bien afilado) es parte esencial de cada plato. En resumen, un lugar al que acudir en busca de una cocina que no necesita de fuegos artificiales, sino herramientas bien cuidadas y saber hacer.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>Foto de portada | <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.tiktok.com\/@elabetoelche\/video\/7551439166765059350\">@elabetoelche<\/a> y <a rel=\"noopener, noreferrer\" href=\"https:\/\/unsplash.com\/es\/@brandoncormier\">Brandon Cormier<\/a><\/p>\n<p>En Trendencias | <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/shopping\/piedra-blanca-limpieza-mercadona-precio-diez-milagro-suciedad-alternativas-mercado\" data-vars-post-title=\"Piedra blanca de limpieza: c\u00f3mo usar este milagro contra la suciedad, precio y alternativas en el mercado\" data-vars-post-url=\"https:\/\/www.trendencias.com\/shopping\/piedra-blanca-limpieza-mercadona-precio-diez-milagro-suciedad-alternativas-mercado\">Piedra blanca de limpieza: c\u00f3mo usar este milagro contra la suciedad, precio y alternativas en el mercado<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tiempos de cocinas cada vez m\u00e1s peque\u00f1as, las soluciones pr\u00e1cticas valen por dos. Por ello, si te quieres ahorrar un cachivache m\u00e1s en cajones y armarios, hay un truco con el que no necesitas tener en casa ning\u00fan afilador de cuchillos ni gastarte el dinero en dicho accesorio. Jorge Pascual, chef al frente de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":130591,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130590"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130590"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/130591"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130590"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}