{"id":130079,"date":"2026-01-30T12:53:45","date_gmt":"2026-01-30T12:53:45","guid":{"rendered":"https:\/\/ladecimaweb.com\/?p=33832"},"modified":"2026-01-30T12:53:45","modified_gmt":"2026-01-30T12:53:45","slug":"solicitan-proteccion-para-la-enfermera-aguero-por-agresiones-y-amenazas-en-la-carcel","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2026\/01\/30\/solicitan-proteccion-para-la-enfermera-aguero-por-agresiones-y-amenazas-en-la-carcel\/","title":{"rendered":"Solicitan protecci\u00f3n para la enfermera Ag\u00fcero por agresiones y amenazas en la c\u00e1rcel"},"content":{"rendered":"<div class=\"boldgrid-section\">\n<div class=\"container\">\n<div class=\"row\">\n<div class=\"col-md-12 col-xs-12 col-sm-12\">\n<p class=\"\"><a href=\"https:\/\/noticiasargentinas.com\/\"><strong>Buenos Aires, 30 enero (NA)<\/strong><span>&nbsp;<\/span><\/a>\u2013 La<span>&nbsp;<\/span><strong>enfermera<span>&nbsp;<\/span><\/strong><a href=\"https:\/\/noticiasargentinas.com\/sociedad\/caso-neonatal---cuando-brenda-aguero-dejo-de-asistir-al-hospital-cesaron-los-hechos---expreso-el-tribunal_a6880f1dbcf6c799375e31fcf\"><strong>Brenda Ag\u00fcero<\/strong><\/a>, quien result\u00f3 condenada a prisi\u00f3n perpetua en la causa por la muerte de beb\u00e9s en el Hospital Neonatal de C\u00f3rdoba,<span>&nbsp;<\/span><strong>denunci\u00f3 sufrir desde hace meses agresiones y amenazas en la c\u00e1rcel<\/strong>, por lo que<span>&nbsp;<\/span><strong>solicit\u00f3 de car\u00e1cter urgente protecci\u00f3n<\/strong>. Aunque el Juzgado de Ejecuci\u00f3n Penal de Feria hab\u00eda decretado d\u00edas atr\u00e1s que se cumpla la medida pedida, todav\u00eda sigue sin cumplirse.<\/p>\n<p class=\"\">El<span>&nbsp;<\/span><strong>abogado Gustavo Nievas<\/strong>, defensor de Ag\u00fcero, confirm\u00f3 en di\u00e1logo con la<span>&nbsp;<\/span><a href=\"https:\/\/es.wikipedia.org\/wiki\/Noticias_Argentinas\" target=\"_blank\" rel=\"noopener nofollow noreferrer\"><strong>Agencia Noticias Argentinas<span>&nbsp;<\/span><\/strong><\/a>que d\u00edas atr\u00e1s informaron al Juez de Feria que la enfermera est\u00e1 en una<span>&nbsp;<\/span><strong>situaci\u00f3n de peligro grave concreto y afectaci\u00f3n de la integridad f\u00edsica en su lugar de alojamiento<\/strong>, que es el Establecimiento Penitenciario N\u00b03.<\/p>\n<p class=\"\">A partir de esa solicitud, el Juzgado<span>&nbsp;<\/span><strong>dispuso que el Servicio Penitenciario establezca medidas de protecci\u00f3n con car\u00e1cter urgente y que se ordene el cambio de pabell\u00f3n de la acusada<\/strong>:<span>&nbsp;<\/span><i>\u201cNosotros no queremos ning\u00fan privilegio, solo que se la proteja. Por el momento no se cumpli\u00f3 con lo decretado, solo hicieron recambio de reclusas\u201d.<\/i><\/p>\n<p>A su vez, Nievas dio a conocer una<span>&nbsp;<\/span><strong>reuni\u00f3n<\/strong><span>&nbsp;<\/span>que su clienta tuvo con la<strong><span>&nbsp;<\/span>jefa de la c\u00e1rcel<span>&nbsp;<\/span><\/strong>donde<span>&nbsp;<\/span><strong>le reproch\u00f3 porque no hab\u00eda hablado con ella<span>&nbsp;<\/span><\/strong>cuando ocurrieron los hechos:<span>&nbsp;<\/span><i><strong>\u201cLuego de eso le dijo que \u2018no quer\u00eda tener problemas\u2019 por lo que la obligaron a firmar un documento&nbsp;en la que constaba que no hab\u00eda sufrido agresiones\u201d.<\/strong><\/i><\/p>\n<p><i><strong>\u201cCuando el juez se anoticia a trav\u00e9s de nosotros de esa acta falsa, que aparte es un delito, se produce el traslado de Brenda a tribunales para que pueda hablar con el magistrado\u201d<\/strong><\/i>, explic\u00f3 y destac\u00f3:<span>&nbsp;<\/span><i><strong>\u201cSabemos que est\u00e1 detenida y cu\u00e1les son las condiciones carcelarias, solo advertimos que vienen empeorando sus condiciones de detenci\u00f3n, que ella no est\u00e1 con una condena firme\u201d.<\/strong><\/i><\/p>\n<p class=\"\" title=\"__IP__\" data-ipspy=\"__IP__\">Frente a esta falta de respuesta, Nievas expuso que en los \u00faltimos d\u00edas<span>&nbsp;<\/span><strong>presentaron un escrito en el que ratifican en la grave situaci\u00f3n en la que se encuentra su defendida<\/strong><span>&nbsp;<\/span>y que por ahora no se cumple lo impuesto por el juez: \u201c<span>Me permito recordar que en las \u00faltimas semanas tanto en la c\u00e1rcel de varones como de mujeres ya se registran varias muertes violentas de internos, que luego (cuando ya era tarde) se verifico que denunciaron haber sido amenazados\u201d.<\/span><\/p>\n<p><i><strong>\u201cAc\u00e1 lo que pasa es que no se respetan las condiciones. En una c\u00e1rcel hay pabellones que se dividen seg\u00fan el delito cometido, lo que genera un clima mas ameno, pero en este caso no sucede eso, est\u00e1n todas mezcladas\u201d<\/strong><\/i>, explic\u00f3.<\/p>\n<p>En este marco, expres\u00f3:<span>&nbsp;<\/span><i><strong>\u201cEl pabell\u00f3n no son las paredes o los hierros, sino la gente que los compone. Si traen a tres o cuatro personas que son violentas, el clima se enrarece, y m\u00e1s si se enteran de que all\u00ed est\u00e1 Ag\u00fcero. En este caso la amenazaron con cuchillos, con facas, y hasta le dijeron que la iba a matar\u201d.<\/strong><\/i><\/p>\n<p>&nbsp;<\/p>\n<div class=\"ubm_banner\"><a href=\"https:\/\/youtu.be\/D-ddTxQeBmI\" target=\"_blank\" rel=\"dofollow noopener noreferrer\"><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2026\/01\/solicitan-proteccion-para-la-enfermera-aguero-por-agresiones-y-amenazas-en-la-carcel.gif\" alt=\"\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>La entrada <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\/solicitan-proteccion-para-la-enfermera-aguero-por-agresiones-y-amenazas-en-la-carcel\/\">Solicitan protecci\u00f3n para la enfermera Ag\u00fcero por agresiones y amenazas en la c\u00e1rcel<\/a> se public\u00f3 primero en <a rel=\"nofollow\" href=\"https:\/\/ladecimaweb.com\">LaDecima<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos Aires, 30 enero (NA)&nbsp;\u2013 La&nbsp;enfermera&nbsp;Brenda Ag\u00fcero, quien result\u00f3 condenada a prisi\u00f3n perpetua en la causa por la muerte de beb\u00e9s en el Hospital Neonatal de C\u00f3rdoba,&nbsp;denunci\u00f3 sufrir desde hace meses agresiones y amenazas en la c\u00e1rcel, por lo que&nbsp;solicit\u00f3 de car\u00e1cter urgente protecci\u00f3n. Aunque el Juzgado de Ejecuci\u00f3n Penal de Feria hab\u00eda decretado d\u00edas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[32],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130079"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=130079"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/130079\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=130079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=130079"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=130079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}