{"id":126091,"date":"2025-12-23T17:00:59","date_gmt":"2025-12-23T17:00:59","guid":{"rendered":"https:\/\/www.espinof.com\/criticas\/anaconda-peliculas-divertidas-ano-entretenido-disparate-al-servicio-jack-black-paul-rudd"},"modified":"2025-12-23T17:00:59","modified_gmt":"2025-12-23T17:00:59","slug":"anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/12\/23\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd\/","title":{"rendered":"&#8216;Anaconda&#8217; es una de las pel\u00edculas m\u00e1s divertidas del a\u00f1o. Un entretenido disparate al servicio de Jack Black y Paul Rudd"},"content":{"rendered":"<p>Hace 28 a\u00f1os se estrenaba <strong>&#8216;Anaconda&#8217;<\/strong>, una pel\u00edcula de terror liderada por <strong>Jennifer Lopez<\/strong> que acab\u00f3 siendo el inicio de una improbable franquicia que pareci\u00f3 llegar a su final en 2015 con el lanzamiento del crossover <strong>&#8216;Mand\u00edbulas contra Anaconda&#8217;<\/strong>. Sin embargo, es muy dif\u00edcil que una saga muera en Hollywood y Sony ha estado varios a\u00f1os intentando dar forma a un reboot que finalmente llega a los cines este viernes 25 de diciembre.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Lo primero que conviene tener claro sobre esta &#8216;Anaconda&#8217; es que se trata de una actualizaci\u00f3n inusual, ya que gira alrededor de un grupo de amigos que est\u00e1 intentando hacer una nueva versi\u00f3n de la pel\u00edcula estrenada en 1997, con la mala suerte de que acaba teniendo que enfrentarse a una de estas serpientes. Eso se traduce en <strong>una comedia muy divertida si conectas con el enfoque que propone<\/strong>, pues no deja de ser un simp\u00e1tico disparate al servicio de <strong>Jack Black y Paul Rudd<\/strong>.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<h2>Directa y efectiva<\/h2>\n<p>Hay muchos motivos por los que ser\u00eda sencillo sepultar esta nueva &#8216;Anaconda&#8217;, desde el hecho de ser muy previsible -el \u00fanico giro m\u00e1s o menos sorprendente forma parte de la subtrama m\u00e1s fallida de la funci\u00f3n- hasta que el acabado visual de la serpiente no est\u00e1 nada conseguido y <strong>grita artefacto digital en todo momento<\/strong>. Pero a su favor tiene algo que resulta contagioso, y es su apuesta decidida por tom\u00e1rselo todo a cachondeo, pero sabiendo mantener siempre los pies en el suelo.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/otros\/carcajadas-y-panico-13-comedias-de-terror-para-reirte-en-halloween\" class=\"pivot-outboundlink\" data-vars-post-title=\"Terror\u00edficamente divertidas: las 13 mejores pel\u00edculas para pasar un Halloween de risa y miedo\"> <img loading=\"lazy\" alt=\"Terror\u00edficamente divertidas: las 13 mejores pel\u00edculas para pasar un Halloween de risa y miedo\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>De hecho, la propia premisa de la pel\u00edcula parte de un grupo de amigos que ten\u00edan el sue\u00f1o de peque\u00f1os de triunfar en el cine que se re\u00fanen porque uno de ellos dice haber conseguido los derechos para hacer un reboot de &#8216;Anaconda&#8217;. Eso lleva a que siempre haya de fondo <strong>una historia de perdedores d\u00e1ndolo todo con la que resulta muy sencillo empatizar<\/strong>, sobre todo si encima le a\u00f1ades a Rudd y Black exprimiendo sus habilidades para la comedia.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Dicho esto, que nadie espere personajes con mucha entidad, ya que a &#8216;Anaconda&#8217; tampoco es algo que le interese demasiado. El caso m\u00e1s grave es el de <strong>Daniela Melchior<\/strong>, que uno nunca sabe muy bien qu\u00e9 pinta ah\u00ed m\u00e1s all\u00e1 de la guapa que es, pero a cambio esa tendencia a no tomarse nada en serio funciona de maravilla en el caso del singular adiestrador interpretado por <strong>Selton Mello<\/strong>, quien nos deja algunos de los mejores momentos de la funci\u00f3n.<\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1333\" width=\"2000\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-4.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-5.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-6.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-1.jpg\" alt=\"Escena Anaconda\"> <noscript><img alt=\"Escena Anaconda\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>S\u00ed es cierto que la acci\u00f3n -y peque\u00f1as dosis de terror- va ganando peso a medida que pasan los minutos y que tampoco es algo que est\u00e9 especialmente conseguido. <strong>El humor tambi\u00e9n es entonces lo que mejor funciona, incluso cuando la pel\u00edcula abraza abiertamente el disparate<\/strong> y no queda otra que aceptar lo que vaya sucediendo sin uno preguntarse demasiado si lo que sucede tiene mucho sentido.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/mejores-sagas-peliculas-historia\" class=\"pivot-outboundlink\" data-vars-post-title=\"Las 29 mejores sagas de pel\u00edculas de la historia\"> <img loading=\"lazy\" alt=\"Las 29 mejores sagas de pel\u00edculas de la historia\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/anaconda-es-una-de-las-peliculas-mas-divertidas-del-ano-un-entretenido-disparate-al-servicio-de-jack-black-y-paul-rudd-2.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Eso lleva a que <strong>en ning\u00fan caso pueda decirse que &#8216;Anaconda&#8217; sea una gran pel\u00edcula<\/strong>, pero s\u00ed que es perfectamente consciente tanto de lo que quiere ser como de sus limitaciones -de ah\u00ed que las apariciones en pantalla de la monstruosa serpiente se reduzcan al m\u00ednimo-. Aqu\u00ed lo que importa realmente es que sus protagonistas se lo pasen bien y que esa energ\u00eda se transmita al espectador.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<p><strong>Tom Gormican<\/strong>, coguionista y director de esta nueva &#8216;Anaconda&#8217;, tambi\u00e9n es perfectamente consciente de ello, abordando su trabajo de puesta en escena desde lo meramente funcional para que sean sus estrellas las que eleven un material tampoco especialmente memorable. Elegir al actor adecuado para el papel suma mucho y aqu\u00ed tenemos un buen ejemplo de ello.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>Por lo dem\u00e1s, &#8216;Anaconda&#8217; tambi\u00e9n dedica un poco de cari\u00f1o a la pel\u00edcula original y hace un uso efectivo de ese componente meta que explica su mera existencia -aunque siempre manteniendo su tendencia a ser tan sutil como un pu\u00f1etazo en la cara-. Sin embargo, <strong>no deja de ser una bobada en la que hay que aceptar que poco menos que todo vale para hacernos pasar un rato entretenido<\/strong>. Y si no entras de primeras en lo que propone, es probable que lo \u00fanico que quieras es que se acabe cuando antes.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-netflix-2025\" data-vars-post-title=\"Las 12 mejores pel\u00edculas de Netflix en 2025\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-netflix-2025\">Las mejores pel\u00edculas de Netflix en 2025<\/a><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-amazon-prime-video-2025\" data-vars-post-title=\"Las 12 mejores pel\u00edculas en Amazon Prime Video de 2025\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-amazon-prime-video-2025\">Las mejores pel\u00edculas en Prime Video de 2025<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 28 a\u00f1os se estrenaba &#8216;Anaconda&#8217;, una pel\u00edcula de terror liderada por Jennifer Lopez que acab\u00f3 siendo el inicio de una improbable franquicia que pareci\u00f3 llegar a su final en 2015 con el lanzamiento del crossover &#8216;Mand\u00edbulas contra Anaconda&#8217;. Sin embargo, es muy dif\u00edcil que una saga muera en Hollywood y Sony ha estado varios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126092,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/126091"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=126091"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/126091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/126092"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=126091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=126091"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=126091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}