{"id":126062,"date":"2025-12-22T16:47:38","date_gmt":"2025-12-22T16:47:38","guid":{"rendered":"https:\/\/www.ole.com.ar\/boxeo\/kevin-trabaja-barrendero-consagro-campeon-pesado-boxing-grand-prix-cmb-ahora-quiere-hacer-historia-crucero-sueno_0_R5oS0J3oW6.html"},"modified":"2025-12-22T16:47:38","modified_gmt":"2025-12-22T16:47:38","slug":"trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/12\/22\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno\/","title":{"rendered":"Trabaja como barrendero, se consagr\u00f3 campe\u00f3n pesado del Boxing Grand Prix del CMB y ahora quiere hacer historia en Crucero: \u00abEse es mi otro sue\u00f1o\u00bb"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-12-22T13:47:38-03:00\">22\/12\/2025 13:47hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38.818565400844\">\n<p>En un a\u00f1o no tan fruct\u00edfero para el boxeo argentino a nivel internacional, <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/kevin-ramirez.html\" title=\"Kevin Ramirez\" alt=\"Kevin Ramirez\" class=\"slug\">Kevin Ram\u00edrez<\/a><\/strong> nos regal\u00f3 una enorme alegr\u00eda en los \u00faltimos d\u00edas del 2025. El oriundo de Wilde, de 25 a\u00f1os y con un r\u00e9cord invicto de <strong>12 victorias (4KOs) y 2 empates,<\/strong> se consagr\u00f3 campe\u00f3n de la categor\u00eda pesado del <strong>Boxing Grand Prix del Consejo Mundial de Boxeo (CMB)<\/strong>, tras vencer por puntos en fallo un\u00e1nime, <strong>al bosnio Ahmed Krnjic en la final que se disput\u00f3 este fin de semana en Riad. <\/strong><\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Una consagraci\u00f3n hist\u00f3rica, no s\u00f3lo por tratarse del primer campe\u00f3n en este innovador torneo, sino porque adem\u00e1s lo consigui\u00f3 en una divisional superior a la suya, que es Crucero, y <strong>ante un rival 12 cent\u00edmetros m\u00e1s alto y 32 kilos m\u00e1s pesado (1.94 metro contra 1.82 m y 122.150 kg contra 91.500 kg). <\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"42\">\n<p>Subir de categor\u00eda fue un desaf\u00edo m\u00e1s para Ram\u00edrez, en una vida de sacrificios, que estuvo cerca de alejarlo del boxeo hace un tiempo, cuando <strong>las necesidades econ\u00f3micas apremiaban y pens\u00f3 seriamente en dedicarse de lleno a sus otros trabajos y dejar de pelear.<\/strong> Sin embargo, su esposa y su hermano, el ex campe\u00f3n mundial Crucero, <strong>V\u00edctor Ram\u00edrez, lo convencieron de seguir.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>As\u00ed, continu\u00f3 mechando el entrenamiento con su trabajo como <strong>barrendero en la Ciudad de Buenos Aires, haciendo tareas de carga y descarga en el mercado frutihort\u00edcola de Lan\u00fas<\/strong>, y hasta sumando unos pesos extra como <strong>chofer de Uber. <\/strong>Todo, mientras esperaba una oportunidad, que finalmente lleg\u00f3.<\/p>\n<\/div>\n<div id=\"element-body-4\" class=\"sc-136cd478-0 ekTCfV\" readability=\"42\">\n<p>El camino de Kevin en el Boxing Grand Prix comenz\u00f3 all\u00e1 por abril, cuando <strong> venci\u00f3 al neerland\u00e9s Brian Zwart, quien lo superaba por 17 cent\u00edmetros y 20 kilos<\/strong>, en apenas 27 segundos. En la segunda ronda, super\u00f3 por puntos y en decisi\u00f3n un\u00e1nime <strong>al congole\u00f1o Reagan Apanu (17,5 kilos m\u00e1s que \u00e9l)<\/strong>. En cuartos enfrent\u00f3 una pelea cerrada frente el polaco Piotr Lacz, que termin\u00f3 en empate y tuvo que resolverse con el panel de supervisores del CMB, que decidi\u00f3 fallar a su favor. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-5\"><img alt=\"Kevin Ram\u00edrez se consagr\u00f3 campe\u00f3n del Boxing Grand Prix. Fotos: Boxing Grand Prix\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno-2.jpg\"><span class=\"epigraphe\">Kevin Ram\u00edrez se consagr\u00f3 campe\u00f3n del Boxing Grand Prix. Fotos: Boxing Grand Prix<\/span><\/div>\n<div id=\"element-body-6\" class=\"sc-136cd478-0 ekTCfV\" readability=\"41\">\n<p>En semifinales, venci\u00f3 al estadounidense <strong>Dante Stone, quien le llevaba m\u00e1s de 28 kilos de ventaja.<\/strong> Pese a eso, Ram\u00edrez no tuvo problemas en <strong>mandarlo a la lona en el primer round,<\/strong> con un derechazo certero al ment\u00f3n. Golpe que termin\u00f3 siendo clave para que <strong> finalmente le dieran por ganada la pelea en decisi\u00f3n dividida.<\/strong> Finalmente, en la final se encontr\u00f3 con un peligroso Krnjic, que <strong>llegaba a esta instancia tras imponerse por KO en sus dos primeras peleas y por puntos en cuartos y semifinales. <\/strong><\/p>\n<\/div>\n<div id=\"element-body-7\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>\u201cMe siento muy bendecido. Esto es un sue\u00f1o. Quiero agradecerle a mi familia, a mi equipo. Es un orgullo para m\u00ed, me siento muy agradecido. Pas\u00e9 por muchas cosas que nadie sabe. <strong> Estuve a punto de colgar los guantes, la estaba pasando mal. Mi hermano que me ayud\u00f3\u201d<\/strong>, reconoci\u00f3 luego de su hist\u00f3rica consagraci\u00f3n.<\/p>\n<\/div>\n<div id=\"element-body-8\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35\">\n<p>El flamante campe\u00f3n del Boxing Grand Prix <strong> no s\u00f3lo embols\u00f3 la importante suma de m\u00e1s de 200 mil d\u00f3lares por su t\u00edtulo<\/strong>, sino que adem\u00e1s recibi\u00f3 un premio a\u00fan m\u00e1s importante a nivel deportivo: <strong>tendr\u00e1 la oportunidad de competir por el t\u00edtulo de plata en su divisi\u00f3n. <\/strong><\/p>\n<\/div>\n<div id=\"element-body-9\" class=\"sc-136cd478-0 ekTCfV\" readability=\"33\">\n<p><strong>\u201cQuiero ser campe\u00f3n mundial en crucero. Ese es mi otro sue\u00f1o\u201d, <\/strong>avis\u00f3. <\/p>\n<\/div>\n<p><h2> <strong>La vida de Kevin Ram\u00edrez fuera del ring y su v\u00ednculo con <\/strong>camioneros<\/h2>\n<\/p>\n<div id=\"element-body-11\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>El boxeo no lo es todo en la vida de Kevin Ram\u00edrez. S\u00ed, es que adem\u00e1s de pelear entre las cuerdas, el disc\u00edpulo de Javier Sena tiene otro trabajo: <strong> es barrendero en la Ciudad de Buenos Aires para la empresa de higiene urbana Ashira.<\/strong> Y eso no es todo, porque en el curr\u00edculum hay diez a\u00f1os de experiencia (2013 a 2023) <strong>haciendo tareas de carga y descarga en el mercado frutihort\u00edcola de Lan\u00fas.<\/strong> As\u00ed, es afiliado al Sindicato y con paso por la empresa Urbasur.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-12\"><img alt=\"Kevin Ram\u00edrez, de Camioneros a pelear por el Boxing Grand Prix\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno-3.jpg\"><span class=\"epigraphe\">Kevin Ram\u00edrez, de Camioneros a pelear por el Boxing Grand Prix<\/span><\/div>\n<div id=\"element-body-13\" class=\"sc-136cd478-0 ekTCfV\" readability=\"35\">\n<p>El apoyo clave para poder empezar a llevarse los focos en lo profesional <strong>lo tiene por parte del Sindicato de Camioneros<\/strong>, donde <strong>le dan ciertas licencias especiales para poder combinar lo deportivo<\/strong> (le ceden las instalaciones del club para entrenar) con lo laboral del d\u00eda a d\u00eda.<\/p>\n<\/div>\n<div id=\"element-body-14\" class=\"sc-a7166897-0 eoLsBE\" readability=\"32\">\n<section readability=\"4\"><picture><img alt=\"Mientras se recupera de la doble fractura de mand\u00edbula, Jake Paul cuenta billetes y busca revancha\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Mientras se recupera de la doble fractura de mand\u00edbula, Jake Paul cuenta billetes y busca revancha<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-15\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Bonavena le gan\u00f3 a Monz\u00f3n en P\u00e1rense de Manos\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Bonavena le gan\u00f3 a Monz\u00f3n en P\u00e1rense de Manos<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-16\" class=\"sc-a7166897-0 eoLsBE\" readability=\"32\">\n<section readability=\"4\"><picture><img alt=\"A tres meses de su hist\u00f3rica victoria ante Canelo \u00c1lvarez, Terence Crawford anunci\u00f3 su retiro del boxeo: &quot;Este deporte me lo dio todo&quot;\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/12\/trabaja-como-barrendero-se-consagro-campeon-pesado-del-boxing-grand-prix-del-cmb-y-ahora-quiere-hacer-historia-en-crucero-ese-es-mi-otro-sueno-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>A tres meses de su hist\u00f3rica victoria ante Canelo \u00c1lvarez, Terence Crawford anunci\u00f3 su retiro del boxeo: \u00abEste deporte me lo dio todo\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>22\/12\/2025 13:47hs. En un a\u00f1o no tan fruct\u00edfero para el boxeo argentino a nivel internacional, Kevin Ram\u00edrez nos regal\u00f3 una enorme alegr\u00eda en los \u00faltimos d\u00edas del 2025. El oriundo de Wilde, de 25 a\u00f1os y con un r\u00e9cord invicto de 12 victorias (4KOs) y 2 empates, se consagr\u00f3 campe\u00f3n de la categor\u00eda pesado del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":126063,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/126062"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=126062"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/126062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/126063"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=126062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=126062"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=126062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}