{"id":121776,"date":"2025-11-07T22:54:01","date_gmt":"2025-11-07T22:54:01","guid":{"rendered":"https:\/\/www.ole.com.ar\/autos\/flaco-lopez-giay-visita-colapinto-interlagos-regalo-palmeiras_0_0at5qZJ9a9.html"},"modified":"2025-11-07T22:54:01","modified_gmt":"2025-11-07T22:54:01","slug":"el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/11\/07\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas\/","title":{"rendered":"El Flaco L\u00f3pez, Giay y una visita a Colapinto en Interlagos: regalo especial, fotos con los fan\u00e1ticos y m\u00e1s"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas.jpg\"><\/p>\n<p><span class=\"createDate\">07\/11\/2025 19:54hs.<\/span><time class=\"modificatedDate\" datetime=\"2025-11-07T19:57:39-03:00\"> Actualizado al 07\/11\/2025 19:57hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div id=\"element-body-0\" class=\"sc-136cd478-0 ekTCfV\" readability=\"27.291666666667\">\n<p>No estuvo exenta de famosos de otros deportes la jornada del viernes en el GP de Brasil de la F\u00f3rmula 1, como <a href=\"https:\/\/www.ole.com.ar\/tema\/jose-lopez.html\" title=\"Jos\u00e9 L\u00f3pez\" alt=\"Jos\u00e9 L\u00f3pez\" class=\"slug\">Jos\u00e9 Manuel L\u00f3pez<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/agustin-giay.html\" title=\"Agust\u00edn Giay\" alt=\"Agust\u00edn Giay\" class=\"slug\">Agust\u00edn Giay<\/a>, jugadores del <a href=\"https:\/\/www.ole.com.ar\/tema\/palmeiras.html\" title=\"Palmeiras\" alt=\"Palmeiras\" class=\"slug\">Palmeiras<\/a>, quienes se dieron una vuelta por Interlagos <strong>para ver la clasificaci\u00f3n de la carrera sprint y saludar a su coterr\u00e1neo argentino, <a href=\"https:\/\/www.ole.com.ar\/autos\/franco-colapinto-f1-alpine-gp-brasil-interlagos-viernes-vivo_0_lOkPIv7NwF.html\" target=\"_blank\" title=\"Franco Colapinto, quien finaliz\u00f3 16\u00b0 y largar\u00e1 desde esa posici\u00f3n el s\u00e1bado.\" alt=\"Franco Colapinto, quien finaliz\u00f3 16\u00b0 y largar\u00e1 desde esa posici\u00f3n el s\u00e1bado.\" rel=\"noopener noreferrer\">Franco Colapinto, quien finaliz\u00f3 16\u00b0 y largar\u00e1 desde esa posici\u00f3n el s\u00e1bado.<\/a><\/strong><\/p>\n<\/div>\n<div id=\"element-body-1\" class=\"sc-136cd478-0 ekTCfV\" readability=\"38\">\n<p>Desde una tribuna especial, el correntino y el santafesino observaron la acci\u00f3n del pilarense sobre el circuito y despu\u00e9s uno de los jefes de prensa de Alpine los hizo ingresar al hospitality (el espacio social y de descanso de la escuder\u00eda), <strong>donde le obsequiaron a Franco una camiseta de Palmeiras con su n\u00famero, el #43.<\/strong><\/p>\n<\/div>\n<div id=\"element-body-2\" class=\"sc-136cd478-0 ekTCfV\" readability=\"39\">\n<p>Giay, surgido de San Lorenzo, llev\u00f3 tambi\u00e9n la suya del Verdao, la #4, <strong>y aprovech\u00f3 para regal\u00e1rsela al brit\u00e1nico Lando Norris, piloto de McLaren, quien utiliza el mismo n\u00famero. <\/strong><\/p>\n<\/div>\n<div id=\"element-body-3\" class=\"sc-136cd478-0 ekTCfV\" readability=\"41\">\n<p>Si bien no ten\u00edan permitido brindarle declaraciones a la prensa, se los vio muy animados y contentos. Y con toda l\u00f3gica, no solo por estar en un Gran Premio de la F\u00f3rmula 1, sino porque ambos vienen de conseguir una tremenda haza\u00f1a con Palmeiras: <strong>vencieron a Liga de Quito por 4-0 en la vuelta de las semifinales de la Copa Libertadores, luego de haber ca\u00eddo por 3-0 en la ida en Ecuador, para meterse en la gran final, en la que enfrentar\u00e1n a Flamengo en Lima (29\/11).<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-4\"><img alt=\"Jos\u00e9 Manuel el Flaco L\u00f3pez y Agust\u00edn Giay, jugadores de Palmeiras. (Foto: Camila Corrales \/ Ol\u00e9) \" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-2.jpg\"><span class=\"epigraphe\">Jos\u00e9 Manuel el Flaco L\u00f3pez y Agust\u00edn Giay, jugadores de Palmeiras. (Foto: Camila Corrales \/ Ol\u00e9) <\/span><\/div>\n<div id=\"element-body-5\" class=\"sc-136cd478-0 ekTCfV\" readability=\"36\">\n<p>Muchos brasile\u00f1os se les acercaron a pedirles fotos y aut\u00f3grafos. Incluso, hubo argentinos que, en chiste, <strong>les reprochaban haberle ganado a River en los cuartos de final (5-2 global).<\/strong><\/p>\n<\/div>\n<div id=\"element-body-6\" class=\"sc-136cd478-0 ekTCfV\" readability=\"42\">\n<p>El domingo (20:30) enfrentar\u00e1n al reci\u00e9n ascendido pero sorpresivo Mirassol (est\u00e1 cuarto en la tabla, con 63 puntos), por la fecha 33 del Brasileirao, donde lideran con 68 unidades. Luego, el Flaco, formado en Lan\u00fas, <strong> se incorporar\u00e1 a la Selecci\u00f3n Argentina, para la que fue convocado nuevamente tras su gran presente (23 goles en 57 partidos este a\u00f1o) y con la que disputar\u00e1 un amistoso ante Angola en Luanda (14\/11).<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-7\"><img alt=\"El Flaco L\u00f3pez fue a alentar a Colapinto a Interlagos.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-3.jpg\"><span class=\"epigraphe\">El Flaco L\u00f3pez fue a alentar a Colapinto a Interlagos.<\/span><\/div>\n<div id=\"element-body-8\" class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-e8b2828-0 fBmEJc vertical\" type=\"embedvertical\">\n<div class=\"sc-e8b2828-1 iPLbWT videoText\" id=\"contentTitleembedverticalAbw9BWDq\" type=\"embedvertical\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>Franco Colapinto<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Giay, jugador de Palmeiras, presente en el GP de Interlagos<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedverticalAbw9BWDq\"><\/span><\/div>\n<div class=\"JWvideoNota_title\">\n<p>Video: Ol\u00e9.<\/p>\n<\/div>\n<\/div>\n<p><h2><strong>C\u00f3mo sigue la actividad en la F\u00f3rmula 1<\/strong><\/h2>\n<\/p>\n<div id=\"element-body-10\" class=\"sc-136cd478-0 ekTCfV\" readability=\"41\">\n<p>La actividad de la F\u00f3rmula 1 en Interlagos continuar\u00e1 este s\u00e1bado a las 11.00, cuando se disputar\u00e1 la carrera Sprint, y a las 15.00, hora en la que tendr\u00e1 lugar la clasificaci\u00f3n que ordenar\u00e1 la grilla para la carrera principal, que ser\u00e1 el domingo a las 14:00. <strong>Toda la acci\u00f3n ser\u00e1 transmitida por Fox Sports y Disney+ Premium y se podr\u00e1 seguir, adem\u00e1s, el minuto a minuto a trav\u00e9s de la web de Ol\u00e9.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\" id=\"element-body-11\"><img alt=\"Colapinto, acompa\u00f1ado de su madre y hermana. (@dcoronel)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-4.jpg\"><span class=\"epigraphe\">Colapinto, acompa\u00f1ado de su madre y hermana. (@dcoronel)<\/span><\/div>\n<p><h3><strong>Sergio Stuart &#8211; enviado especial<\/strong><\/h3>\n<\/p>\n<div id=\"element-body-13\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Franco Colapinto palpit\u00f3 el supercl\u00e1sico entre Boca y River con Ol\u00e9\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Franco Colapinto palpit\u00f3 el supercl\u00e1sico entre Boca y River con Ol\u00e9<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-14\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"Banderazo argentino por Franco Colapinto en Brasil: cu\u00e1ndo y d\u00f3nde ser\u00e1\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Banderazo argentino por Franco Colapinto en Brasil: cu\u00e1ndo y d\u00f3nde ser\u00e1<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div id=\"element-body-15\" class=\"sc-a7166897-0 eoLsBE\" readability=\"31\">\n<section readability=\"2\"><picture><img alt=\"El especial apoyo familiar para Colapinto en el d\u00eda de su renovaci\u00f3n con Alpine\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/el-flaco-lopez-giay-y-una-visita-a-colapinto-en-interlagos-regalo-especial-fotos-con-los-fanaticos-y-mas-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El especial apoyo familiar para Colapinto en el d\u00eda de su renovaci\u00f3n con Alpine<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>07\/11\/2025 19:54hs. Actualizado al 07\/11\/2025 19:57hs. No estuvo exenta de famosos de otros deportes la jornada del viernes en el GP de Brasil de la F\u00f3rmula 1, como Jos\u00e9 Manuel L\u00f3pez y Agust\u00edn Giay, jugadores del Palmeiras, quienes se dieron una vuelta por Interlagos para ver la clasificaci\u00f3n de la carrera sprint y saludar a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":121777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121776"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=121776"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/121777"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=121776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=121776"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=121776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}