{"id":121695,"date":"2025-11-08T13:00:13","date_gmt":"2025-11-08T13:00:13","guid":{"rendered":"https:\/\/www.espinof.com\/directores-y-guionistas\/christopher-nolan-defiende-ambiciosa-pelicula-zack-snyder-que-fue-fracaso-hubiera-sido-fascinante-verla-despues-vengadores"},"modified":"2025-11-08T13:00:13","modified_gmt":"2025-11-08T13:00:13","slug":"hubiera-sido-fascinante-verla-despues-de-los-vengadores-christopher-nolan-cree-que-el-publico-no-estaba-listo-para-watchmen","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/11\/08\/hubiera-sido-fascinante-verla-despues-de-los-vengadores-christopher-nolan-cree-que-el-publico-no-estaba-listo-para-watchmen\/","title":{"rendered":"\u00abHubiera sido fascinante verla despu\u00e9s de los Vengadores\u00bb: Christopher Nolan cree que el p\u00fablico no estaba listo para &#8216;Watchmen&#8217;"},"content":{"rendered":"<p>All\u00e1 por el a\u00f1o 2009, <strong>Zack <\/strong><strong>Snyder<\/strong> estren\u00f3 la pel\u00edcula <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/watchmen-diez-anos-mejor-adaptacion-comic-superheroes-elevada-a-enesima-potencia-su-ultimate-cut\" data-vars-post-title=\"'Watchmen': la mejor adaptaci\u00f3n de un c\u00f3mic de superh\u00e9roes alcanza su cima con el 'Ultimate Cut'\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/watchmen-diez-anos-mejor-adaptacion-comic-superheroes-elevada-a-enesima-potencia-su-ultimate-cut\">&#8216;Watchmen&#8217;<\/a>, basada en un m\u00edtico c\u00f3mic de <strong>Alan Moore y Dave Gibbons<\/strong> que se consideraba, hasta entonces, <strong>absolutamente inadaptable al cine<\/strong>.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Por aquel entonces solo se hab\u00edan estrenado dos pel\u00edculas del <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/marvel-que-orden-conviene-ver-todas-peliculas-superheroes-mcu\" data-vars-post-title=\"Cronolog\u00eda Marvel - Orden definitivo para ver las pel\u00edculas y series del Universo Marvel\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/marvel-que-orden-conviene-ver-todas-peliculas-superheroes-mcu\">Universo Cinematogr\u00e1fico de Marvel<\/a> y adaptaciones tan ambiciosas como &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/los-vengadores-gracias-joss-whedon\" data-vars-post-title=\"'Los Vengadores', gracias, Joss Whedon\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/los-vengadores-gracias-joss-whedon\">Los Vengadores<\/a>&#8216; o &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/liga-justicia-zack-snyder-brutal-consagracion-hbo-estilo-unico-cine-superheroes\" data-vars-post-title=\"\u2018La Liga de la Justicia de Zack Snyder\u2019 es brutal: la consagraci\u00f3n en HBO de un estilo \u00fanico en el cine de superh\u00e9roes\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/liga-justicia-zack-snyder-brutal-consagracion-hbo-estilo-unico-cine-superheroes\">La Liga de la Justicia<\/a>&#8216; a\u00fan pertenec\u00edan exclusivamente a las fantas\u00edas de los fans. Quiz\u00e1 el p\u00fablico no estaba preparado. <strong>Lo cierto es que &#8216;Watchmen&#8217; pinch\u00f3 en taquilla <\/strong>recaudando solo 187 millones de d\u00f3lares frente a los 150M$ del presupuesto inicial. Un doloroso fracaso para Snyder aunque esto no impidi\u00f3 que siguiera intent\u00e1ndolo en el cine de superh\u00e9roes.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<h2>\u00bfQui\u00e9n vigila a Zack Snyder?<\/h2>\n<p>A pesar del palo en taquilla, la pel\u00edcula se ha convertido en un t\u00edtulo de culto y tiene una legi\u00f3n de fans entre los que se encuentra otro cineasta que sabe lo que es dirigir adaptaciones de c\u00f3mics. <strong>Christopher Nolan<\/strong> ha <strong>defendido<\/strong> a Zack Snyder en <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.hollywoodreporter.com\/movies\/movie-features\/zack-snyder-cut-rebel-moon-netflix-1235680491\/\">The Hollywood Reporter<\/a> afirmando que su versi\u00f3n de &#8216;Watchmen&#8217; fue una pel\u00edcula <strong><em>\u00abadelantada a su tiempo\u00bb<\/em><\/strong>. Y a\u00f1ade: <em>\u00abLa idea de un equipo de superh\u00e9roes, que subvierte de manera tan brillante, <\/em><strong><em>ni siquiera exist\u00eda en las pel\u00edculas<\/em><\/strong><em>. Hubiera sido fascinante ver su lanzamiento despu\u00e9s de Los Vengadores\u00bb<\/em>.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/tom-cruise-quiso-protagonizar-watchmen-zack-snyder-director-tenia-otro-papel-mente-para-quiero-al-tio-raro-pirado\" class=\"pivot-outboundlink\" data-vars-post-title=\"Tom Cruise quiso protagonizar la 'Watchmen' de Zack Snyder, pero el director ten\u00eda otro papel en mente para \u00e9l. &quot;Quiero al t\u00edo raro y pirado&quot;\"> <img loading=\"lazy\" alt=\"Tom Cruise quiso protagonizar la 'Watchmen' de Zack Snyder, pero el director ten\u00eda otro papel en mente para \u00e9l. &quot;Quiero al t\u00edo raro y pirado&quot;\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/hubiera-sido-fascinante-verla-despues-de-los-vengadores-christopher-nolan-cree-que-el-publico-no-estaba-listo-para-watchmen.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>Por su parte, Snyder, que pretende vivir dentro y fuera del ecosistema hollywoodiense al mismo tiempo, <strong>ha afirmado en varias ocasiones que Nolan es su \u00fanico amigo director de cine <\/strong>y que, de hecho, hablan por tel\u00e9fono una vez al mes aproximadamente para ponerse al d\u00eda. Francamente, ojal\u00e1 poder escuchar esas conversaciones. Seg\u00fan se cuenta, si Snyder se atrevi\u00f3 a hacer su &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/el-hombre-de-acero-un-superman-diferente-caotico-y-destructivo\" data-vars-post-title=\"'El hombre de acero', un Superman diferente, ca\u00f3tico y destructivo \" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/el-hombre-de-acero-un-superman-diferente-caotico-y-destructivo\">Hombre de acero<\/a>&#8216; fue exclusivamente porque <strong>Nolan ya hab\u00eda pavimentado el camino<\/strong> con &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/christopher-nolan-batman-begins-el-justiciero-de-la-ciudad\" data-vars-post-title=\"Christopher Nolan: 'Batman Begins', el justiciero de la ciudad\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/christopher-nolan-batman-begins-el-justiciero-de-la-ciudad\">Batman Begins<\/a>&#8216; y, sobre todo, la m\u00e1s ambiciosa &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/christopher-nolan-el-caballero-oscuro-heroe-o-villano\" data-vars-post-title=\"Christopher Nolan: 'El Caballero Oscuro', \u00bfh\u00e9roe o villano?\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/christopher-nolan-el-caballero-oscuro-heroe-o-villano\">El caballero oscuro<\/a>&#8216;.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<p>Actualmente, <strong>ambos viven muy a gusto fuera de las franquicias de capas y mallas<\/strong>, aunque <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/zack-snyder-desvela-dos-unicas-peliculas-marvel-dc-que-volveria-al-cine-superheroes-no-me-entusiasma-como-antes\" data-vars-post-title=\"Zack Snyder desvela las dos \u00fanicas pel\u00edculas de Marvel y DC por las que volver\u00eda al cine de superh\u00e9roes: &quot;Ya no me entusiasma como antes&quot; \" data-vars-post-url=\"https:\/\/www.espinof.com\/directores-y-guionistas\/zack-snyder-desvela-dos-unicas-peliculas-marvel-dc-que-volveria-al-cine-superheroes-no-me-entusiasma-como-antes\">Zack Snyder ha afirmado<\/a> que no le importar\u00eda volver al cine de superh\u00e9roes. O bien en Marvel para filmar su versi\u00f3n de &#8216;Elektra Lives Again&#8217; o volver a DC para hacer la adaptaci\u00f3n de &#8216;El regreso del caballero oscuro&#8217;; no es casualidad que sean dos c\u00f3mics de<strong> Frank Miller<\/strong>, a quien ya adapt\u00f3 en la exitosa &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/300-salvaje-y-bellisimo-espectaculo\" data-vars-post-title=\"'300', salvaje y bell\u00edsimo espect\u00e1culo\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/300-salvaje-y-bellisimo-espectaculo\">300<\/a>&#8216;. Pero siendo realistas, podemos esperar sentados a verle de nuevo en ese ambiente porque no tiene pinta de que esos proyectos vayan a ponerse en marcha pr\u00f3ximamente.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/todas-peliculas-zack-snyder-ordenadas-peor-a-mejor\" data-vars-post-title=\"Todas las pel\u00edculas de Zack Snyder ordenadas de peor a mejor\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/todas-peliculas-zack-snyder-ordenadas-peor-a-mejor\">Todas las pel\u00edculas de Zack Snyder ordenadas de peor a mejor<\/a><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/todas-peliculas-zack-snyder-ordenadas-peor-a-mejor\" data-vars-post-title=\"Todas las pel\u00edculas de Zack Snyder ordenadas de peor a mejor\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/todas-peliculas-zack-snyder-ordenadas-peor-a-mejor\">Todas las pel\u00edculas de Christopher Nolan ordenadas de peor a mejor<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>All\u00e1 por el a\u00f1o 2009, Zack Snyder estren\u00f3 la pel\u00edcula &#8216;Watchmen&#8217;, basada en un m\u00edtico c\u00f3mic de Alan Moore y Dave Gibbons que se consideraba, hasta entonces, absolutamente inadaptable al cine. Por aquel entonces solo se hab\u00edan estrenado dos pel\u00edculas del Universo Cinematogr\u00e1fico de Marvel y adaptaciones tan ambiciosas como &#8216;Los Vengadores&#8216; o &#8216;La Liga [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":121696,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121695"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=121695"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121695\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/121696"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=121695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=121695"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=121695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}