{"id":121376,"date":"2025-11-04T12:14:38","date_gmt":"2025-11-04T12:14:38","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2025\/11\/04\/sin-bancos-este-jueves-en-cordoba-como-operar-durante-el-dia-del-bancario\/"},"modified":"2025-11-04T12:14:38","modified_gmt":"2025-11-04T12:14:38","slug":"sin-bancos-este-jueves-en-cordoba-como-operar-durante-el-dia-del-bancario","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/11\/04\/sin-bancos-este-jueves-en-cordoba-como-operar-durante-el-dia-del-bancario\/","title":{"rendered":"Sin bancos este jueves en C\u00f3rdoba: c\u00f3mo operar durante el D\u00eda del Bancario"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/sin-bancos-este-jueves-en-cordoba-como-operar-durante-el-dia-del-bancario.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>Este jueves 6 de noviembre, los bancos de <strong>C\u00f3rdoba <\/strong>y de todo el pa\u00eds no abrir\u00e1n sus puertas por la celebraci\u00f3n del <strong>D\u00eda del Bancario<\/strong>, una fecha que conmemora la creaci\u00f3n de la <strong>Asociaci\u00f3n Bancaria en 1924.<\/strong> El feriado gremial dejar\u00e1 <strong>sin atenci\u00f3n presencial<\/strong> a las sucursales, aunque los servicios digitales y los cajeros seguir\u00e1n funcionando con normalidad.<\/p>\n<p class=\"destacadoNota\"><a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/cordoba\/la-iglesia-catolica-de-cordoba-informo-13-casos-de-supuestos-abusos.phtml\" rel=\"noopener noreferrer\">La Iglesia Cat\u00f3lica de C\u00f3rdoba inform\u00f3 13 casos de supuestos abusos<\/a><\/p>\n<p>El <strong>Banco Central de la Rep\u00fablica Argentina <\/strong>(BCRA) no considera esta fecha como un feriado nacional, pero el acuerdo colectivo del sector la reconoce como un d\u00eda de descanso obligatorio. Por eso, se recomienda anticipar tr\u00e1mites o vencimientos previstos para el<strong> 6 de noviembre<\/strong> y evitar demoras. <\/p>\n<h2>\u00bfQu\u00e9 se puede hacer?<\/h2>\n<p>Durante la jornada no se atender\u00e1n<strong> gestiones presenciales<\/strong>, como apertura de cuentas, firma de documentos o consultas personalizadas. Adem\u00e1s, algunas operaciones entre bancos que requieren compensaci\u00f3n, como ciertos pagos o transferencias programadas, se postergar\u00e1n autom\u00e1ticamente al viernes 7, <strong>primer d\u00eda h\u00e1bil posterior al feriado gremial<\/strong>.<\/p>\n<p>Aunque las puertas est\u00e9n cerradas, los servicios <strong>digitales <\/strong>continuar\u00e1n activos. Los usuarios podr\u00e1n ingresar a <strong>home banking y aplicaciones m\u00f3viles <\/strong>para hacer transferencias, pagar servicios o consultar movimientos.<\/p>\n<p>Tambi\u00e9n estar\u00e1n operativos los<strong> cajeros autom\u00e1ticos<\/strong> y <strong>terminales de autoservicio <\/strong>para extracciones, dep\u00f3sitos o pagos. Las tarjetas de d\u00e9bito y cr\u00e9dito, junto con las <strong>billeteras virtuales<\/strong>, mantendr\u00e1n su funcionamiento habitual, sin restricciones.<\/p>\n<h2> <\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 6 de noviembre, los bancos de C\u00f3rdoba y de todo el pa\u00eds no abrir\u00e1n sus puertas por la celebraci\u00f3n del D\u00eda del Bancario, una fecha que conmemora la creaci\u00f3n de la Asociaci\u00f3n Bancaria en 1924. El feriado gremial dejar\u00e1 sin atenci\u00f3n presencial a las sucursales, aunque los servicios digitales y los cajeros seguir\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":121377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[2232,1898,41,1672],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121376"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=121376"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121376\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/121377"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=121376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=121376"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=121376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}