{"id":121190,"date":"2025-11-03T11:30:57","date_gmt":"2025-11-03T11:30:57","guid":{"rendered":"https:\/\/www.espinof.com\/cine-clasico\/mejores-peliculas-oeste-clint-eastwood-hoy-tv-western-que-enfado-a-directores-hollywood"},"modified":"2025-11-03T11:30:57","modified_gmt":"2025-11-03T11:30:57","slug":"es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/11\/03\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood\/","title":{"rendered":"Es una de las mejores pel\u00edculas del oeste de Clint Eastwood. Hoy en TV, el western que enfad\u00f3 a los directores de Hollywood"},"content":{"rendered":"<p><strong>Clint Eastwood<\/strong> es sin\u00f3nimo de cine del oeste. Es cierto que ha hecho pel\u00edculas de todo tipo a lo largo de los a\u00f1os, pero el western le lanz\u00f3 a la fama y particip\u00f3 en varios t\u00edtulos inolvidables. Hoy me toca hablaros de uno de ellos, pues esta noche puede ver gratis en televisi\u00f3n <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/cine-clasico\/clint-eastwood-el-fuera-de-la-ley\" data-vars-post-title=\"Clint Eastwood: 'El fuera de la ley'\" data-vars-post-url=\"https:\/\/www.espinof.com\/cine-clasico\/clint-eastwood-el-fuera-de-la-ley\">&#8216;El fuera de la ley&#8217;<\/a>.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Hay varios motivos por los que este western es recordado, pero hay uno tan importante que ser\u00e1 mejor hablar primero de ello: Eastwood provoc\u00f3 el despido del director <strong>Philip Kaufman<\/strong> cuando ya se llevan varias semanas de rodaje. Para liarlo todo m\u00e1s, \u00e9l asumi\u00f3 la puesta en escena, provocando un terrible enfado en el Sindicato de Directores de Hollywood. A consecuencia de ello se cre\u00f3 la llamada <strong>Regla Eastwood<\/strong> que desde entonces ha impedido que algo as\u00ed vuelva a suceder.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<p>Las fricciones entre Eastwood y Kaufman tuvieron su origen en la novela que adaptaba la pel\u00edcula. Kaufman cre\u00eda que estaba escrito por un fascista, tal y como <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/esto-ha-escrito-burdo-fascista-clint-eastwood-despidio-al-director-este-western-llevarle-contraria-cambio-hollywood-para-siempre\" data-vars-post-title=\"&quot;Esto lo ha escrito un burdo fascista&quot;. Clint Eastwood despidi\u00f3 al director de este western por llevarle la contraria y cambi\u00f3 Hollywood para siempre\" data-vars-post-url=\"https:\/\/www.espinof.com\/directores-y-guionistas\/esto-ha-escrito-burdo-fascista-clint-eastwood-despidio-al-director-este-western-llevarle-contraria-cambio-hollywood-para-siempre\">se confirm\u00f3 poco despu\u00e9s<\/a>, y quer\u00eda suavizar eso en la pel\u00edcula, pero Eastwood se neg\u00f3 en redondo. Teniendo eso en cuenta, <strong>bastante raro fue ya que las grabaciones empezaron con Kaufman en la silla del director<\/strong>.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<h2>Una pel\u00edcula clave de Eastwood<\/h2>\n<p>Dejando a un lado todas esas pol\u00e9micas, lo realmente importante es que &#8216;El fuera de la ley&#8217; es <strong>uno de los mejores westerns de Eastwood<\/strong>, quien llevaba unos a\u00f1os alejados del g\u00e9nero tras firmar \u00e9l mismo la estimable <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/cine-clasico\/clint-eastwood-el-primer-western-como-director\" data-vars-post-title=\"Clint Eastwood: el primer western como director\" data-vars-post-url=\"https:\/\/www.espinof.com\/cine-clasico\/clint-eastwood-el-primer-western-como-director\">&#8216;Infierno de cobardes&#8217;<\/a>. Aqu\u00ed no tuvo el \u00e9xito merecido en su momento -en taquilla no fue mal, pero los cr\u00edticos fueron bastante duros con ellas-, pero bien poco tard\u00f3 en revalorizarse como una de sus obras mayores.<\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/dia-que-kevin-costner-descubrio-que-clint-eastwood-no-espera-a-nadie-me-pagan-para-grabar-peliculas\" class=\"pivot-outboundlink\" data-vars-post-title=\"&quot;Le dije lo que tendr\u00eda que hacer&quot;. Kevin Costner se pele\u00f3 con Clint Eastwood en el rodaje de 'Un mundo perfecto' y sali\u00f3 perdiendo\"> <img loading=\"lazy\" alt=\"&quot;Le dije lo que tendr\u00eda que hacer&quot;. Kevin Costner se pele\u00f3 con Clint Eastwood en el rodaje de 'Un mundo perfecto' y sali\u00f3 perdiendo\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>A su manera, &#8216;El fuera de la ley&#8217; es una combinaci\u00f3n de los estilos de <strong>Sergio Leone<\/strong>, <strong>Don Siegel<\/strong> y el propio Eastwood. El \u00faltimo no tuvo problemas <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/clint-eastwood-elogia-al-director-que-admiraba-que-cambio-su-carrera-para-siempre-sabia-cine-que-nadie\" data-vars-post-title=\"&quot;Sab\u00eda m\u00e1s de cine que nadie&quot;. Clint Eastwood elogia al director que m\u00e1s admiraba y que cambi\u00f3 su carrera para siempre\" data-vars-post-url=\"https:\/\/www.espinof.com\/directores-y-guionistas\/clint-eastwood-elogia-al-director-que-admiraba-que-cambio-su-carrera-para-siempre-sabia-cine-que-nadie\">en reconocer<\/a> en que los dos primeros fueron sus grandes referentes como directores, pero \u00e9l siempre ha tenido una voz que fue puliendo a lo largo de los a\u00f1os y en la que la sobriedad era uno de los principales rasgos distintivos.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1080\" width=\"1920\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-4.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-5.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-6.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-1.jpg\" alt=\"Josey Wales Eastwood\"> <noscript><img alt=\"Josey Wales Eastwood\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Rabiosa por momentos -tanto la propia historia que contaba como la realidad social de la \u00e9poca invitaban a ello- y nihilista en l\u00edneas generales, en su ra\u00edz estamos ante la historia de una venganza, pero <strong>Eastwood nunca comete el error de reducir &#8216;El fuera de la ley&#8217; a solamente eso<\/strong>, por lo que tampoco deber\u00edamos hacerlo nosotros.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<p>De hecho, los personajes, donde destaca que fue la primera pel\u00edcula en la que colabor\u00f3 con <strong>Sondra Locke<\/strong>, que van apareciendo a lo largo del viaje vital de Josey Wales interpretado por Eastwood marcan la evoluci\u00f3n del mismo y enriquecen el relato. Es cierto que \u00e9l mantiene en todo momento ese actitud vital arisca marcada por la p\u00e9rdida de su familia al inicio de la funci\u00f3n, pero no es ni mucho menos un personaje plano que sea siempre lo mismo.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/actores-y-actrices\/escena-polemica-clint-eastwood-esta-pelicula-que-hizo-justo-antes-perdon-ninfomana-pervertida\" class=\"pivot-outboundlink\" data-vars-post-title=\"Nadie estaba preparado para ver la escena m\u00e1s desagradable de Clint Eastwood en toda su carrera: &quot;Es la \u00fanica en la pel\u00edcula de la que la gente habl\u00f3&quot;\"> <img loading=\"lazy\" alt=\"Nadie estaba preparado para ver la escena m\u00e1s desagradable de Clint Eastwood en toda su carrera: &quot;Es la \u00fanica en la pel\u00edcula de la que la gente habl\u00f3&quot;\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/11\/es-una-de-las-mejores-peliculas-del-oeste-de-clint-eastwood-hoy-en-tv-el-western-que-enfado-a-los-directores-de-hollywood-2.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>S\u00ed es cierto que hacer <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/actores-y-actrices\/morgan-freeman-afirma-que-este-western-conocido-clint-eastwood-su-mejor-pelicula-me-encuentro-tengo-que-volver-a-verlo\" data-vars-post-title=\"&quot;Si me lo encuentro, tengo que volver a verlo&quot;: Morgan Freeman reivindica 'El fuera de la ley' frente a 'Sin perd\u00f3n' y otros western de Eastwood\" data-vars-post-url=\"https:\/\/www.espinof.com\/actores-y-actrices\/morgan-freeman-afirma-que-este-western-conocido-clint-eastwood-su-mejor-pelicula-me-encuentro-tengo-que-volver-a-verlo\">lo que hizo Morgan Freeman<\/a> de elevarla por encima del resto de westerns de Eastwood me resulta excesivo, pero a la hora de la verdad solamente se me ocurren tres en los que haya participado que sean superiores de forma indiscutible. Hoy ten\u00e9is la oportunidad de comprobarlo por vosotros mismos, pues se emite <strong>esta noche en La 2 a partir de las 22:00<\/strong>.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-clint-eastwood\" data-vars-post-title=\"Las 15 mejores pel\u00edculas de Clint Eastwood\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-clint-eastwood\">Las 15 mejores pel\u00edculas de Clint Eastwood<\/a><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/directores-y-guionistas\/clint-eastwood-tiene-regla-basica-que-ha-seguido-principio-su-carrera-dia-hoy-no-quiero-insultar-a-su-inteligencia\" data-vars-post-title=\"La regla b\u00e1sica de Clint Eastwood que sigue desde el principio de su carrera: tener en cuenta la inteligencia del espectador\" data-vars-post-url=\"https:\/\/www.espinof.com\/directores-y-guionistas\/clint-eastwood-tiene-regla-basica-que-ha-seguido-principio-su-carrera-dia-hoy-no-quiero-insultar-a-su-inteligencia\">La regla b\u00e1sica de Clint Eastwood que sigue desde el principio de su carrera: tener en cuenta la inteligencia del espectador<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Clint Eastwood es sin\u00f3nimo de cine del oeste. Es cierto que ha hecho pel\u00edculas de todo tipo a lo largo de los a\u00f1os, pero el western le lanz\u00f3 a la fama y particip\u00f3 en varios t\u00edtulos inolvidables. Hoy me toca hablaros de uno de ellos, pues esta noche puede ver gratis en televisi\u00f3n &#8216;El fuera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":121191,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121190"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=121190"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/121190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/121191"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=121190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=121190"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=121190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}