{"id":120355,"date":"2025-10-24T21:05:33","date_gmt":"2025-10-24T21:05:33","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/atento-racing-flamengo-jugadores-defender-punta-brasileirao_0_9y1EFAeRoN.html"},"modified":"2025-10-24T21:05:33","modified_gmt":"2025-10-24T21:05:33","slug":"atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/10\/24\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao\/","title":{"rendered":"Atento Racing: Flamengo reserva siete jugadores en el Brasileirao"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/10\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-10-24T18:05:33-03:00\">24\/10\/2025 18:05hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"33.721179624665\">\n<p>Los equipos competitivos no se permiten descansar en ninguna competencia, y ese es justamente el presente de <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/flamengo.html\" title=\"Flamengo\" alt=\"Flamengo\" class=\"slug\">Flamengo<\/a><\/strong>. Con la mira puesta en mantener la cima del <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/brasileirao.html\" title=\"brasileirao\" alt=\"brasileirao\" class=\"slug\">Brasileirao<\/a><\/strong> y en el partido de vuelta por las semifinales de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" title=\"Copa Libertadores\" alt=\"Copa Libertadores\" class=\"slug\">Copa Libertadores<\/a><\/strong> ante <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/racing.html\" title=\"Racing\" alt=\"Racing\" class=\"slug\">Racing<\/a><\/strong>, <strong>el Mengao no contar\u00e1 con varias de sus figuras en el duelo de este s\u00e1bado, frente a Fortaleza por el torneo local.<\/strong> <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>La Academia cay\u00f3 1-0 en el Maracan\u00e1 tras el gol de Carrascal, y a menos de una semana del duelo, Gustavo Costas ya prepara al equipo para el partido de vuelta en el Cilindro. La llave sigue abierta, pero Racing deber\u00e1 encontrar la manera de reemplazar a una pieza clave del esquema, como Santiago Sosa, quien sufri\u00f3 una fractura tras un codazo de Marcos Rojo en la ida.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>Sin embargo, Flamengo tambi\u00e9n deber\u00e1 reemplazar a una de sus figuras para el partido de vuelta: <strong>Pedro.<\/strong> El delantero sufri\u00f3 un fuerte choque con Santiago Sosa, termin\u00f3 en el hospital tras el encuentro y ya se confirm\u00f3 que no estar\u00e1 disponible el pr\u00f3ximo mi\u00e9rcoles.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"El delantero sufri\u00f3 un choque con Santiago Sosa. (REUTERS\/Sergio Moraes)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/10\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao-2.jpg\"><span class=\"epigraphe\">El delantero sufri\u00f3 un choque con Santiago Sosa. (REUTERS\/Sergio Moraes)<\/span><\/div>\n<p><h2><strong>Los otros jugadores de Flamengo que no podr\u00e1n jugar ante Fortaleza<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39\">\n<p>Por fuera de Pedro, <strong>Pulgar y Carrascal est\u00e1n suspendidos -ambos fueron titulares en el \u00faltimo partido-, <\/strong>mientras que <strong>Everton<\/strong> es el otro jugador del plantel que se encuentra en el departamento m\u00e9dico. A ellos <strong>se suman L\u00e9o Ortiz, Alex Sandro y Nicol\u00e1s De la Cruz,<\/strong> quienes tampoco viajar\u00e1n con la delegaci\u00f3n.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>L\u00e9o Ortiz sufri\u00f3 una distensi\u00f3n en el tobillo derecho el domingo pasado, intent\u00f3 llegar al duelo ante Racing y volvi\u00f3 a entrenarse este viernes, pero finalmente permanecer\u00e1 en R\u00edo de Janeiro para completar su recuperaci\u00f3n y as\u00ed poder ser una variante para finalizar la serie en Avellaneda.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Alex Sandro, por su parte, descansar\u00e1 por un control de presi\u00f3n indicado por el cuerpo m\u00e9dico del club. De la Cruz atraviesa un cuadro viral que le provoc\u00f3 fiebre y lo oblig\u00f3 a perderse varios entrenamientos, por lo que fue descartado para el encuentro.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"De la Cruz atraviesa un cuadro viral. (REUTERS\/Hannah Mckay)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/10\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao-3.jpg\"><span class=\"epigraphe\">De la Cruz atraviesa un cuadro viral. (REUTERS\/Hannah Mckay)<\/span><\/div>\n<p><h2><strong>La batalla por la punta del Brasileirao<\/strong> <\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"38\">\n<p>A ocho fechas de que termine la liga brasile\u00f1a, Flamengo y Palmeiras son los l\u00edderes. Con 61 puntos, le sacan cinco unidades al Cruzeiro, su competidor m\u00e1s cercano, y sue\u00f1an con lograr el t\u00edtulo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"55\">\n<p>Para los de San Pablo, que cayeron 3-0 ante Liga de Quito por la ida de las semis de la Copa, el fixture sigue con Cruzeiro, Juventude, Santos, Mirassol, Santos, Atl\u00e9tico Mineiro, Fluminense, Gremio, Vit\u00f3ria y Cear\u00e1. <strong>Los de R\u00edo de Janeiro, por su parte, tendr\u00e1n que enfrentar a Fortaleza, Sport Recife, San Pablo, Santos, Sport Recife, Fluminense, Red Bull Bragantino, Atl\u00e9tico Mineiro, Cear\u00e1 y Mirassol.<\/strong><\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"\u00c1rbitros confirmados para las revanchas de Racing y Lan\u00fas en la Libertadores y la Sudamericana\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/10\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00c1rbitros confirmados para las revanchas de Racing y Lan\u00fas en la Libertadores y la Sudamericana<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Di Mar\u00eda, tras la clasificaci\u00f3n de Central a la Libertadores: &quot;Volv\u00ed para esto&quot;\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/10\/atento-racing-flamengo-reserva-siete-jugadores-en-el-brasileirao-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Di Mar\u00eda, tras la clasificaci\u00f3n de Central a la Libertadores: \u00abVolv\u00ed para esto\u00bb<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>24\/10\/2025 18:05hs. Los equipos competitivos no se permiten descansar en ninguna competencia, y ese es justamente el presente de Flamengo. Con la mira puesta en mantener la cima del Brasileirao y en el partido de vuelta por las semifinales de la Copa Libertadores ante Racing, el Mengao no contar\u00e1 con varias de sus figuras en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":120356,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/120355"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=120355"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/120355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/120356"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=120355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=120355"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=120355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}