{"id":12033,"date":"2021-02-06T22:53:00","date_gmt":"2021-02-06T22:53:00","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2021\/02\/06\/las-relaciones-entre-la-ue-y-rusia-lejos-de-ser-satisfactorias-segun-borrell\/"},"modified":"2021-02-06T22:53:00","modified_gmt":"2021-02-06T22:53:00","slug":"las-relaciones-entre-la-ue-y-rusia-lejos-de-ser-satisfactorias-segun-borrell","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2021\/02\/06\/las-relaciones-entre-la-ue-y-rusia-lejos-de-ser-satisfactorias-segun-borrell\/","title":{"rendered":"Las relaciones entre la UE y Rusia \u00ablejos de ser satisfactorias\u00bb, seg\u00fan Borrell"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/02\/las-relaciones-entre-la-ue-y-rusia-lejos-de-ser-satisfactorias-segun-borrell.jpg\"><\/p>\n<div class=\"image\" id=\"image\" readability=\"8\"> <img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2021\/02\/las-relaciones-entre-la-ue-y-rusia-lejos-de-ser-satisfactorias-segun-borrell-2.jpg\" alt=\"Borrell visit\u00f3 Mosc\u00fa en los \u00faltimos d\u00edas y manifest\u00f3 la preocupaci\u00f3n del bloque por la situaci\u00f3n de Navalny. \" title=\"Borrell visit\u00f3 Mosc\u00fa en los \u00faltimos d\u00edas y manifest\u00f3 la preocupaci\u00f3n del bloque por la situaci\u00f3n de Navalny. \"><\/p>\n<p>Borrell visit\u00f3 Mosc\u00fa en los \u00faltimos d\u00edas y manifest\u00f3 la preocupaci\u00f3n del bloque por la situaci\u00f3n de Navalny. <\/p>\n<\/div>\n<p><strong>El jefe de la diplomacia europea, Josep Borrell, admiti\u00f3 este s\u00e1bado que las relaciones entre la Uni\u00f3n Europea (UE) y Rusia \u00abest\u00e1n lejos de ser satisfactorias\u00bb,<\/strong> pero <strong>destac\u00f3 la importancia de mantener abiertos los canales diplom\u00e1ticos,<\/strong> tras finalizar su viaje a Mosc\u00fa, que caus\u00f3 controversia entre los pa\u00edses del bloque.<\/p>\n<p>\u00abLos canales diplom\u00e1ticos deben continuar abiertos, no solo para desactivar crisis o incidentes, sino para tener intercambios directos, enviar mensajes firmes y francos, ahora que las relaciones est\u00e1n lejos de ser satisfactorias\u00bb, dijo Borrell en un comunicado difundido por el Servicio Europeo de Acci\u00f3n Exterior.<\/p>\n<p><strong>El diplom\u00e1tico espa\u00f1ol subray\u00f3, asimismo, la preocupaci\u00f3n del bloque europeo por la situaci\u00f3n de los derechos humanos en Rusia <\/strong>y volvi\u00f3 a condenar la sentencia al opositor ruso Alexey Navalny y solicitar su liberaci\u00f3n.<\/p>\n<p>\u00abDurante la visita de Borrell, los diplom\u00e1ticos de la UE mantuvieron contactos con abogados del se\u00f1or Navalny\u00bb, precis\u00f3 la nota.<\/p>\n<p>La situaci\u00f3n de Navalny<\/p>\n<p>El opositor, de 44 a\u00f1os, fue condenado el martes pasado a dos a\u00f1os y ocho meses de c\u00e1rcel, una decisi\u00f3n que reaviv\u00f3 las protestas desatadas por su arresto, fuertemente reprimidas por las autoridades con unos 10.000 manifestantes detenidos.<\/p>\n<p>L<strong>a situaci\u00f3n de Navalny caus\u00f3 incluso un incidente diplom\u00e1tico entre Bruselas y Mosc\u00fa, luego de que el Kremlin decidiera ayer la expulsi\u00f3n de diplom\u00e1ticos de Suecia, Polonia y Alemania<\/strong> por participar en protestas no autorizadas convocadas por los seguidores del opositor.<\/p>\n<p>Rusia acusa a los delegados europeos de participar en \u00abactos ilegales\u00bb, algo que fue rechazado de manera tajante por los pa\u00edses europeos, que calificaron a las expulsiones de \u00abinjustificadas\u00bb.<\/p>\n<p>Esta decisi\u00f3n comprometi\u00f3 a\u00fan m\u00e1s la visita de Borrell al pa\u00eds, cuestionada por algunos Estados miembros, ya que se produjo durante su estad\u00eda en la capital rusa y horas despu\u00e9s de que se reuniera con su hom\u00f3logo ruso Sergei Lavrov.<\/p>\n<p>Borrell dijo que abordar\u00e1 el viaje a Rusia con los ministros exteriores de los 27 pa\u00edses miembros de la UE el pr\u00f3ximo 22 de febrero, mientras que los l\u00edderes de la UE discutir\u00e1n sobre las relaciones con Rusia en marzo. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Borrell visit\u00f3 Mosc\u00fa en los \u00faltimos d\u00edas y manifest\u00f3 la preocupaci\u00f3n del bloque por la situaci\u00f3n de Navalny. El jefe de la diplomacia europea, Josep Borrell, admiti\u00f3 este s\u00e1bado que las relaciones entre la Uni\u00f3n Europea (UE) y Rusia \u00abest\u00e1n lejos de ser satisfactorias\u00bb, pero destac\u00f3 la importancia de mantener abiertos los canales diplom\u00e1ticos, tras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12034,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/12033"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=12033"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/12033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/12034"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=12033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=12033"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=12033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}