{"id":117318,"date":"2025-09-18T02:57:46","date_gmt":"2025-09-18T02:57:46","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/quintero-river-palmeiras-actitud-libra_0_kJIEEOD6oH.html"},"modified":"2025-09-18T02:57:46","modified_gmt":"2025-09-18T02:57:46","slug":"juanfer-quintero-el-jugador-actitud-libra-de-river","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/09\/18\/juanfer-quintero-el-jugador-actitud-libra-de-river\/","title":{"rendered":"Juanfer Quintero, el jugador Actitud Libra de River"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/juanfer-quintero-el-jugador-actitud-libra-de-river.jpg\"><\/p>\n<p><span class=\"createDate\">17\/09\/2025 23:57hs.<\/span><time class=\"modificatedDate\" datetime=\"2025-09-17T23:59:19-03:00\"> Actualizado al 17\/09\/2025 23:59hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"30.882352941176\">\n<p>La noche arranc\u00f3 mal para River y parec\u00eda que ser\u00eda casi una despedida de la Copa Libertadores. Pero <strong><a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/libertadores\/river-vs-palmeiras-partido-ida-copa-libertadores-cuartos-final_0_qs1Zev2RAW.html\" target=\"_self\" title=\"el triunfo de Palmeiras 2-1 en el Monumentall \" alt=\"el triunfo de Palmeiras 2-1 en el Monumental \" rel=\"noopener noreferrer\">el triunfo de Palmeiras 2-1 en el Monumental<\/a><\/strong>termin\u00f3 con una sensaci\u00f3n diferente al que se imaginaba. Y una de las razones fue el aporte de Juan Fernando Quintero al entrar en el segundo tiempo. <strong>El equipo levant\u00f3 y el colombiano fue el jugador Actitud Libra del Millo.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Nadie va a descubrir el pie fino de Juanfer. River hab\u00eda sido casi bailado en la primera media hora del partido y se fueron al entretiempo con una diferencia de 2-0 que amagaba fin de ciclo en la Libertadores. El ingreso del colombiano, acompa\u00f1ado de otros movimientos t\u00e1cticos en el medio con la entrada de Mart\u00ednez Quarta (de buen partido, tambi\u00e9n), <strong>Gallardo logr\u00f3 lo que hab\u00eda fallado: recuperar el control. Y qui\u00e9n mejor que Quintero para tenerla y distribuir.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"27.309352517986\">\n<p>Tampoco es que River lo abrum\u00f3 a Palmeiras pero ya fue otro partido. <strong><a href=\"https:\/\/www.ole.com.ar\/river-plate\/river-copa-libertadores-palmeiras-puntajes-gallardo-cuartos-final-ida_0_HFjHeLzKAg.html\" target=\"_self\" title=\"Movedizo, preciso y punzante, Quinteros fue clave para que la diferencia se achicara en el resultado y en el manejo del juego\" alt=\"Movedizo, preciso y punzante, Quinteros fue clave para que la diferencia se achicara en el resultado y en el manejo del juego\" rel=\"noopener noreferrer\">Movedizo, preciso y punzante, Quinteros fue clave para que la diferencia se achicara en el resultado y en el manejo del juego<\/a>. <\/strong>Y como si faltaba algo para cerrar una buena noche personal, se puso la pilcha de gran defensor y cuando los brasile\u00f1os metieron una contra infernal, fue al piso y meti\u00f3 un cierre que casi se puede decir vali\u00f3 un gol.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"La gran salvada de Juanfer en defensa.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/juanfer-quintero-el-jugador-actitud-libra-de-river-2.jpg\"><span class=\"epigraphe\">La gran salvada de Juanfer en defensa.<\/span><\/div>\n<p><h2>EL RESUMEN DEL RIVER &#8211; PALMEIRAS<\/h2>\n<\/p>\n<div class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-e8b2828-0 fBmEJc\" type=\"embed\">\n<div class=\"sc-e8b2828-1 iPLbWT videoText\" id=\"contentTitleembednS9FOVKM\" type=\"embed\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>River Plate<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Lo mejor de River 1 &#8211; Palmeiras 2<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembednS9FOVKM\"><\/span><\/div>\n<div class=\"JWvideoNota_title\">\n<p>Video: FOX Sports.\t<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>17\/09\/2025 23:57hs. Actualizado al 17\/09\/2025 23:59hs. La noche arranc\u00f3 mal para River y parec\u00eda que ser\u00eda casi una despedida de la Copa Libertadores. Pero el triunfo de Palmeiras 2-1 en el Monumentaltermin\u00f3 con una sensaci\u00f3n diferente al que se imaginaba. Y una de las razones fue el aporte de Juan Fernando Quintero al entrar en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":117319,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/117318"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=117318"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/117318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/117319"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=117318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=117318"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=117318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}