{"id":116854,"date":"2025-09-13T22:11:35","date_gmt":"2025-09-13T22:11:35","guid":{"rendered":"http:\/\/hoycordobaweb.com\/index.php\/2025\/09\/13\/juan-grabois-propone-un-nuevo-impuesto-a-la-riqueza-del-3-el-proyecto-karina\/"},"modified":"2025-09-13T22:11:35","modified_gmt":"2025-09-13T22:11:35","slug":"juan-grabois-propone-un-nuevo-impuesto-a-la-riqueza-del-3-el-proyecto-karina","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/09\/13\/juan-grabois-propone-un-nuevo-impuesto-a-la-riqueza-del-3-el-proyecto-karina\/","title":{"rendered":"Juan Grabois propone un nuevo impuesto a la riqueza del 3%: el \u00abproyecto Karina\u00bb"},"content":{"rendered":"<div class=\"media_block\"><\/div>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/juan-grabois-propone-un-nuevo-impuesto-a-la-riqueza-del-3-el-proyecto-karina.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>M\u00ednimamente ruido en las redes va a producir la nueva idea de <a target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/modo-fontevecchia\/juan-grabois-espert-fue-financiado-por-narcotraficantes-modof.phtml\" rel=\"noopener noreferrer\"><strong>Juan Grabois<\/strong><\/a>. Se trata, seg\u00fan explic\u00f3, de un nuevo <strong>impuesto a la riqueza <\/strong>similar al que impuls\u00f3 el kirchnerismo en los tiempos de la pandemia, pero permanante y con un nombre altamente chicanero: \u00ab<strong>Proyecto Karina<\/strong>\u00ab.<\/p>\n<p>\u00abEstoy armando un proyecto que se llama Proyecto Karina, <strong>porque es el 3%<\/strong>\u00ab, dijo el el exprecandidato presidencial y ahora postulante en la provincia de Buenos Aires. De m\u00e1s est\u00e1 decir que el chiste alude al porcentaje\/meme de la coimas que habr\u00edan revelado los llamados <a target=\"_blank\" href=\"https:\/\/https:\/\/www.perfil.com\/noticias\/politica\/por-el-escandalo-de-los-audios-declaro-fernando-cerimedo-exasesor-de-javier-milei-y-hablo-hechos-de-corrupcion-y-coimas.phtml\" rel=\"noopener noreferrer\">\u00abaudios de la corrupci\u00f3n\u00bb.<\/a><\/p>\n<p>En declaraciones a <em>Radio con Vos<\/em>, el dirigente pol\u00edtico sostuvo que el impuesto que en su momento empuj\u00f3 <strong>M\u00e1ximo Kirchner<\/strong> \u00abfue muy acertado\u00bb, pero que en su opini\u00f3n tiene que ser fijo.<\/p>\n<div class=\"subscription\" readability=\"6.683257918552\">\n<p> Esto no les gusta a los autoritarios <\/p>\n<div class=\"subscription__container\" readability=\"6.1467391304348\">\n<div class=\"subscription__text-wrapper\" readability=\"31.20652173913\">\n<p> El ejercicio del periodismo profesional y cr\u00edtico es un pilar fundamental de la democracia. Por eso molesta a quienes creen ser los due\u00f1os de la verdad. <\/p>\n<\/p><\/div><\/div><\/div>\n<p>Sobre los montos imponibles, dijo que est\u00e1 trabajando en las escalas, pero ser\u00eda m\u00e1s o menos as\u00ed: quienes tengan declarados m\u00e1s <strong>de US$10 millones<\/strong> <strong>pagar\u00edan el 3%<\/strong>; hasta US$5 millones, 2%, y hasta US$2,5 millones, 1%.<\/p>\n<p>Aclar\u00f3: \u00abTodos los que est\u00e1n abajo de eso, que son el 99,5% de los argentinos, no lo tienen que pagar\u00bb.<\/p>\n<p>Adem\u00e1s, plante\u00f3 que quienes est\u00e9n sujetos a la aplicaci\u00f3n \u00abarmen una comisi\u00f3n para la trazabilidad de esos impuestos y que vean<strong> que va para la educaci\u00f3n, para la salud de los ni\u00f1os y va para urbanizar los barrios\u00bb.<\/strong><\/p>\n<p> \u00abAhora con el blockchain tenemos la posibilidad de tener una trazabilidad 100% inviolable de c\u00f3mo funciona eso\u00bb, precis\u00f3.<\/p>\n<p><em>En desarrollo&#8230;<\/em><\/p>\n<p>LT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00ednimamente ruido en las redes va a producir la nueva idea de Juan Grabois. Se trata, seg\u00fan explic\u00f3, de un nuevo impuesto a la riqueza similar al que impuls\u00f3 el kirchnerismo en los tiempos de la pandemia, pero permanante y con un nombre altamente chicanero: \u00abProyecto Karina\u00ab. \u00abEstoy armando un proyecto que se llama Proyecto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":116855,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/116854"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=116854"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/116854\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/116855"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=116854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=116854"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=116854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}