{"id":116264,"date":"2025-09-07T15:02:02","date_gmt":"2025-09-07T15:02:02","guid":{"rendered":"https:\/\/www.espinof.com\/estrenos\/expediente-warren-4-acaba-hacer-historia-cines-ultimo-rito-supera-todas-expectativas-destroza-record-saga"},"modified":"2025-09-07T15:02:02","modified_gmt":"2025-09-07T15:02:02","slug":"expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/09\/07\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga\/","title":{"rendered":"&#8216;Expediente Warren 4&#8217; acaba de hacer historia en cines: &#8216;El \u00faltimo rito&#8217; supera todas las expectativas y destroza el r\u00e9cord de la saga"},"content":{"rendered":"<p>El <strong>universo Warren<\/strong> hace ya tiempo que se convirti\u00f3 en la saga de terror m\u00e1s taquillera de la historia, pero esta franquicia todav\u00eda ten\u00eda mucho que cines en salas, ya que <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-ultimo-rito-traca-final-polvora-mojada-patrick-wilson-vera-farmiga-vuelven-a-brillar-enfrentandose-al-demonio-exceso-metraje\" data-vars-post-title=\"'Expediente Warren: El \u00faltimo rito' es una traca final con la p\u00f3lvora mojada. Patrick Wilson y Vera Farmiga vuelven a brillar enfrent\u00e1ndose al demonio del exceso de metraje\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-ultimo-rito-traca-final-polvora-mojada-patrick-wilson-vera-farmiga-vuelven-a-brillar-enfrentandose-al-demonio-exceso-metraje\">&#8216;Expediente Warren: El \u00faltimo rito&#8217;<\/a> acaba de superar todas las expectativas que los expertos ten\u00edan en ella. En concreto, el largometraje de <strong>Michael Chaves<\/strong> ha destrozado el r\u00e9cord del mejor estreno de la saga.<\/p>\n<p>Los expertos <a rel=\"noopener, noreferrer\" href=\"https:\/\/deadline.com\/2025\/09\/box-office-conjuring-the-last-rites-1236508461\/\">apuntaban<\/a> hace unos d\u00edas que &#8216;Expediente Warren: El \u00faltimo rito&#8217; iba a superar los 40 millones de d\u00f3lares en taquilla durante su primer fin de semana en las salas de Estados Unidos, con <a rel=\"noopener, noreferrer\" href=\"https:\/\/variety.com\/2025\/film\/box-office\/conjuring-4-box-office-projection-50-million-plus-debut-1236505681\/\">algunas fuentes<\/a> incluso diciendo que podr\u00eda irse m\u00e1s all\u00e1 de los 50. Pues bien, solamente el viernes ya consigui\u00f3 34,6 millones y esa cifra <strong>se ha ido hasta los 83 millones durante sus tres primeros d\u00edas en cines<\/strong>. Se hab\u00edan quedado muy cortos.<\/p>\n<h2>Arrasando con todo<\/h2>\n<p><!-- BREAK 1 --> <\/p>\n<p>Esos 83 millones de d\u00f3lares suponen el mejor estreno de la saga con mucha diferencia. Para que os hag\u00e1is una idea, el r\u00e9cord estaba hasta ahora en manos de <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-the-conjuring-la-mejor-pelicula-de-terror-de-los-ultimos-anos\" data-vars-post-title=\"'Expediente Warren: The Conjuring', la mejor pel\u00edcula de terror de los \u00faltimos a\u00f1os\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-the-conjuring-la-mejor-pelicula-de-terror-de-los-ultimos-anos\">&#8216;Expediente Warren: The Conjuring&#8217;<\/a>, que sum\u00f3 41,8 millones hace ya 12 a\u00f1os. Si ampliamos todo incluyendo los spin-offs, entonces la marca a batir eran los 53,8 millones que hab\u00eda conseguido <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/monja-sindios-narrativo-que-purga-sus-pecados-gracias-a-notable-diseno-produccion\" data-vars-post-title=\"'La monja': un sindi\u00f3s narrativo que purga sus pecados gracias a un notable dise\u00f1o de producci\u00f3n\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/monja-sindios-narrativo-que-purga-sus-pecados-gracias-a-notable-diseno-produccion\">&#8216;La monja&#8217;<\/a> en 2018. <strong>Ni siquiera hay competici\u00f3n.<\/strong><\/p>\n<p>Es verdad que <strong>&#8216;Expediente Warren: El \u00faltimo rito&#8217; es tambi\u00e9n la pel\u00edcula m\u00e1s cara de la saga<\/strong> con un coste de 55 millones de d\u00f3lares -el r\u00e9cord hasta ahora estaba compartido por <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-el-caso-enfield-una-excelente-secuela\" data-vars-post-title=\"'Expediente Warren: El caso Enfield', una excelente secuela\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-el-caso-enfield-una-excelente-secuela\">&#8216;Expediente Warren: El caso Enfield&#8217;<\/a> y &#8216;<a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-obligado-diablo-se-aleja-formula-original-solvente-relato-detectivesco-genio-james-wan\" data-vars-post-title=\"'Expediente Warren: Obligado por el demonio' se aleja de la f\u00f3rmula original con un solvente relato detectivesco sin el genio de James Wan\" data-vars-post-url=\"https:\/\/www.espinof.com\/criticas\/expediente-warren-obligado-diablo-se-aleja-formula-original-solvente-relato-detectivesco-genio-james-wan\">Expediente Warren: Obligado por el demonio&#8217;<\/a> con 40 millones-, pero es que ese dato aqu\u00ed da sencillamente igual.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\"> <a href=\"https:\/\/www.espinof.com\/listas\/warrenverso-todas-peliculas-universo-expediente-warren-ordenadas-peor-a-mejor\" class=\"pivot-outboundlink\" data-vars-post-title=\"De 'Expediente Warren: The Conjuring' a 'La monja 2', todas las pel\u00edculas del Warrenverso ordenadas de peor a mejor\"> <img loading=\"lazy\" alt=\"De 'Expediente Warren: The Conjuring' a 'La monja 2', todas las pel\u00edculas del Warrenverso ordenadas de peor a mejor\" width=\"375\" height=\"142\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga.jpg\"> <\/a> <\/div><\/div><\/div>\n<\/div>\n<p>De hecho, <strong>la gran duda ahora est\u00e1 en saber cu\u00e1l ser\u00e1 el techo en taquilla para &#8216;Expediente Warren: El \u00faltimo rito&#8217;<\/strong>, pues solamente un milagro va a impedir que tambi\u00e9n es convierta en la m\u00e1s taquillera de la saga. Para ello hay dos objetivos a batir, el primero los 321 millones &#8216;El caso Enfield&#8217;, mientras que el segundo est\u00e1 en superar los 366 millones de recaudaci\u00f3n mundial de &#8216;La monja&#8217;.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\"> <img class=\"centro_sinmarco\" height=\"1080\" width=\"1920\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-3.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-4.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-5.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-1.jpg\" alt=\"Expediente Rito\"> <noscript><img alt=\"Expediente Rito\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/09\/expediente-warren-4-acaba-de-hacer-historia-en-cines-el-ultimo-rito-supera-todas-las-expectativas-y-destroza-el-record-de-la-saga-1.jpg\"><\/noscript> <\/div>\n<\/div>\n<p>Por lo pronto, &#8216;Expediente Warren: El \u00faltimo rito&#8217; suma ya unos ingresos mundiales por valor de 187 millones de d\u00f3lares, ya que ha sumado otros 104 millones en el resto del mundo. Un estreno arrollador que deja claro que exist\u00eda mucho inter\u00e9s entre el p\u00fablico por ver la entrega final de la saga encabezada por <strong>Patrick Wilson y Vera Farmiga<\/strong>.<\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/mejor-orden-para-ver-todas-peliculas-expediente-warren\" data-vars-post-title=\"El mejor orden para ver todas las pel\u00edculas de 'Expediente Warren': una gu\u00eda para no perderse en este universo de conjuros, mu\u00f1ecas pose\u00eddas y monjas diab\u00f3licas\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/mejor-orden-para-ver-todas-peliculas-expediente-warren\">El mejor orden para ver todas las pel\u00edculas de &#8216;Expediente Warren&#8217;: una gu\u00eda para no perderse en este universo de conjuros, mu\u00f1ecas pose\u00eddas y monjas diab\u00f3licas<\/a><\/p>\n<p>En Espinof | <a class=\"text-outboundlink\" href=\"https:\/\/www.espinof.com\/listas\/21-mejores-secuelas-historia-cine-terror\" data-vars-post-title=\"Las 21 mejores secuelas de la historia del cine de terror\" data-vars-post-url=\"https:\/\/www.espinof.com\/listas\/21-mejores-secuelas-historia-cine-terror\">Las 21 mejores secuelas de la historia del cine de terror<br \/><\/a><\/p>\n<p><!-- BREAK 4 --> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El universo Warren hace ya tiempo que se convirti\u00f3 en la saga de terror m\u00e1s taquillera de la historia, pero esta franquicia todav\u00eda ten\u00eda mucho que cines en salas, ya que &#8216;Expediente Warren: El \u00faltimo rito&#8217; acaba de superar todas las expectativas que los expertos ten\u00edan en ella. En concreto, el largometraje de Michael Chaves [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":116265,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/116264"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=116264"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/116264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/116265"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=116264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=116264"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=116264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}