{"id":115966,"date":"2025-09-04T17:26:49","date_gmt":"2025-09-04T17:26:49","guid":{"rendered":"https:\/\/fono.fcm.unc.edu.ar\/?p=14086"},"modified":"2025-09-04T17:26:49","modified_gmt":"2025-09-04T17:26:49","slug":"4-de-septiembre-dia-de-las-secretarias","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/09\/04\/4-de-septiembre-dia-de-las-secretarias\/","title":{"rendered":"4 de septiembre: D\u00eda de las Secretarias"},"content":{"rendered":"<h2 class=\"fusion-post-title\">4 de septiembre: D\u00eda de las Secretarias<\/h2>\n<div class=\"post-content\" readability=\"36\">\n<p><img loading=\"lazy\" fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-14087 size-fusion-400\" src=\"https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-400x392.png\" alt width=\"400\" height=\"392\" srcset=\"https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-66x66.png 66w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-200x196.png 200w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-300x294.png 300w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-400x392.png 400w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-600x589.png 600w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-768x753.png 768w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-800x785.png 800w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-1024x1005.png 1024w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-1200x1177.png 1200w, https:\/\/fono.fcm.unc.edu.ar\/wp-content\/uploads\/sites\/14\/2025\/09\/1-3-e1757006400241-1536x1507.png 1536w\" sizes=\"(max-width: 400px) 100vw, 400px\">Desde la Escuela de Fonoaudiolog\u00eda reconocemos y celebramos el compromiso, la dedicaci\u00f3n y el trabajo conjunto&nbsp; de las secretarias de nuestra instituci\u00f3n.<\/p>\n<p>\u00a1Feliz d\u00eda a quienes son parte fundamental de cada logro colectivo!<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>4 de septiembre: D\u00eda de las Secretarias Desde la Escuela de Fonoaudiolog\u00eda reconocemos y celebramos el compromiso, la dedicaci\u00f3n y el trabajo conjunto&nbsp; de las secretarias de nuestra instituci\u00f3n. \u00a1Feliz d\u00eda a quienes son parte fundamental de cada logro colectivo!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/115966"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=115966"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/115966\/revisions"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=115966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=115966"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=115966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}