{"id":115245,"date":"2025-08-28T03:32:32","date_gmt":"2025-08-28T03:32:32","guid":{"rendered":"https:\/\/www.ole.com.ar\/opinion\/reducen-entradas-seleccion-castigo-cantos-homofobicos-discriminatorios_0_cvoejXquBy.html"},"modified":"2025-08-28T03:32:32","modified_gmt":"2025-08-28T03:32:32","slug":"por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/08\/28\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion\/","title":{"rendered":"Por culpa de la gente hay menos entradas para la Selecci\u00f3n"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-08-28T00:32:32-03:00\">28\/08\/2025 00:32hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"39\">\n<p>Meterse con el hincha es piantavotos. Cuantim\u00e1s, desde la publicaci\u00f3n deportiva por excelencia: el hincha es nuestro principal cliente, y encima lo solemos sentir como una extensi\u00f3n de nosotros mismos, nos mimetizamos, <strong>nos identificamos con la pasi\u00f3n del que va a la tribuna<\/strong> convocado por su divisa y por sus colores.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>Eso no significa que, aunque el hincha <strong>es el \u00fanico capital irreemplazable del f\u00fatbol<\/strong>, creamos que todo lo que hacemos como hinchas est\u00e1 bien.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>En pocas horas vuelan las entradas para el partido de la Selecci\u00f3n con Venezuela. La Scaloneta es un verdadero equipo de \u00e9poca, el mejor combinado argento de la historia, y <strong>no son muchas las oportunidades de verla en casa<\/strong>. Menos todav\u00eda con los precios saladitos que les ponen a los tickets.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Y t porque <strong>otra vez estamos castigados<\/strong>. Una parte del aforo debe cederse a delegaciones de ni\u00f1os de clubes y ONG que<strong> luchan contra la discriminaci\u00f3n<\/strong>, y esto, al margen de las consabidas entradas de protocolo de las que l\u00f3gicamente disponen los sponsors, reduce las chances del espectador com\u00fan.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>El que va a la cancha a denigrar a los rivales (la sanci\u00f3n se debe a cantos<strong> \u201chomof\u00f3bicos y discriminatorios\u201d proferidos por nuestro p\u00fablico<\/strong> en el partido contra Colombia) no piensa, quiz\u00e1, en lo que est\u00e1 diciendo; o cree que eso est\u00e1 mal en cualquier otro lado, <strong>pero en la tribuna vale todo<\/strong>; o sabe que est\u00e1 mal pero le importa un pito, y putear y humillar al rival lo hace sentir m\u00e1s argentino.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>Ser\u00e1 una lucha de a\u00f1os. Por ahora, acaso llegue a tener alg\u00fan efecto que<strong> cuando le grit\u00e1s despectivamente \u201cnegro\u201d o \u201cputo\u201d a un adversario<\/strong>, lo primero que est\u00e1s logrando es que, en el pr\u00f3ximo partido, m\u00e1s hinchas argentinos se queden <strong>sin la posibilidad de tener un lugar en el estadio<\/strong> para poder ver al equipo de Messi.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Hinchas venezolanos en el Monumental. A tratarlos bien (AFP \/ Juan Mabromata).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion-2.jpg\"><span class=\"epigraphe\">Hinchas venezolanos en el Monumental. A tratarlos bien (AFP \/ Juan Mabromata).<\/span><\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Clima feo en el \u00faltimo Argentina-Colombia. Ese d\u00eda hubo cantos (EFE \/ Juan Ignacio Roncoroni).\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion-3.jpg\"><span class=\"epigraphe\">Clima feo en el \u00faltimo Argentina-Colombia. Ese d\u00eda hubo cantos (EFE \/ Juan Ignacio Roncoroni).<\/span><\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Messi de Selecci\u00f3n: doblete y una final antes de jugar con Argentina\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Messi de Selecci\u00f3n: doblete y una final antes de jugar con Argentina<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Video del golazo de Messi: pecho, pared y zurdazo que dej\u00f3 parado a Gallese\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/por-culpa-de-la-gente-hay-menos-entradas-para-la-seleccion-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video del golazo de Messi: pecho, pared y zurdazo que dej\u00f3 parado a Gallese<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>28\/08\/2025 00:32hs. Meterse con el hincha es piantavotos. Cuantim\u00e1s, desde la publicaci\u00f3n deportiva por excelencia: el hincha es nuestro principal cliente, y encima lo solemos sentir como una extensi\u00f3n de nosotros mismos, nos mimetizamos, nos identificamos con la pasi\u00f3n del que va a la tribuna convocado por su divisa y por sus colores. Eso no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":115246,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/115245"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=115245"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/115245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/115246"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=115245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=115245"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=115245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}