{"id":114671,"date":"2025-08-22T03:09:26","date_gmt":"2025-08-22T03:09:26","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/river-libertadores-penales-clasificacion_0_GzxslV0biQ.html"},"modified":"2025-08-22T03:09:26","modified_gmt":"2025-08-22T03:09:26","slug":"los-memes-por-el-pase-de-river-a-cuartos-de-final","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/08\/22\/los-memes-por-el-pase-de-river-a-cuartos-de-final\/","title":{"rendered":"Los memes por el pase de River a cuartos de final"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/los-memes-por-el-pase-de-river-a-cuartos-de-final.jpg\"><\/p>\n<div><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/08\/los-memes-por-el-pase-de-river-a-cuartos-de-final-2.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p><strong><a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a><\/strong> pas\u00f3 a cuartos de final de la <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" title=\"Copa Libertadores\" alt=\"Copa Libertadores\" class=\"slug\">Copa Libertadores<\/a><\/strong> <a href=\"https:\/\/www.ole.com.ar\/futbol-internacional\/libertadores\/river-vs-libertad-partido-vuelta-copa-libertadores-2025-minuto-minuto_0_x0oP3DzCRL.html\" target=\"_self\" title=\"tras superar por penales a Libertad\" alt=\"tras superar por penales a Libertad\" rel=\"noopener noreferrer\">tras superar por penales a Libertad<\/a>, de Paraguay, tras el 1 a 1 en los 90 minutos. Fue bravo: en el segundo tiempo fue expulsado Galoppo y hubo que jugar con diez. Desde los 12 pasos, se luci\u00f3 <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/franco-armani.html\" title=\"Franco Armani\" alt=\"Franco Armani\" class=\"slug\">Franco Armani<\/a><\/strong> y el Millo festej\u00f3 la clasificaci\u00f3n y ya piensa en la serie contra Palmeiras. El pase gener\u00f3 algo t\u00edpico del folklore futbolero: los memes, con mucho enfoque en el arquero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>River pas\u00f3 a cuartos de final de la Copa Libertadores tras superar por penales a Libertad, de Paraguay, tras el 1 a 1 en los 90 minutos. Fue bravo: en el segundo tiempo fue expulsado Galoppo y hubo que jugar con diez. Desde los 12 pasos, se luci\u00f3 Franco Armani y el Millo festej\u00f3 la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":114672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/114671"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=114671"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/114671\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/114672"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=114671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=114671"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=114671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}