{"id":112194,"date":"2025-07-27T02:01:28","date_gmt":"2025-07-27T02:01:28","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-primera\/guido-carrillo-racing-estudiantes-golsequia-racha-empates-goles_0_vMym7DWPEH.html"},"modified":"2025-07-27T02:01:28","modified_gmt":"2025-07-27T02:01:28","slug":"el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/27\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura\/","title":{"rendered":"El gol que rompi\u00f3 la racha de los 0-0 en el Clausura"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-07-26T23:01:28-03:00\">26\/07\/2025 23:01hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"29.34375\">\n<p>La tercera fecha del Torneo Clausura ven\u00eda dejando mucho que desear en cuanto a los resultados, pero el <strong>choque entre <a href=\"https:\/\/www.ole.com.ar\/tema\/racing.html\" title=\"Racing\" alt=\"Racing\" class=\"slug\">Racing <\/a>y <a href=\"https:\/\/www.ole.com.ar\/tema\/estudiantes-de-la-plata.html\" title=\"Estudiantes de La Plata\" alt=\"Estudiantes de La Plata\" class=\"slug\">Estudiantes<\/a><\/strong>se convirti\u00f3 en un oasis en el desierto para romper la <a href=\"https:\/\/www.ole.com.ar\/futbol-primera\/fecha-insolito-goles-clausura-cero-cero-empates-aburrido-jornada-partidos-salieron_0_axWPZsJliO.html\" title=\"incre\u00edble racha de encuentros sin goles\" alt=\"incre\u00edble racha de encuentros sin goles\">incre\u00edble racha de encuentros sin goles<\/a> que se ven\u00eda dando. <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/guido-carrillo.html\" target=\"_blank\" title=\"Guido Carrillo\" alt=\"Guido Carrillo\" class=\"slug\" rel=\"noopener noreferrer\">Guido Carrillo<\/a> puso el 1-0 en el Cilindro<\/strong> y provoc\u00f3 el primer grito sagrado despu\u00e9s de unos cuantos minutos de tranquilidad&#8230;<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>Es que la jornada del f\u00fatbol argentino regal\u00f3 la llamativa cifra de que <strong>seis de los primeros siete partidos del finde semana terminaron empatados sin goles,<\/strong> con el dato de que solamente se anotaron dos goles en esos siete encuentros.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"36\">\n<p>La jornada comenz\u00f3 bien, el viernes en la tarde noche de Jun\u00edn, donde <strong>Lan\u00fas se impuso con un 2-0 a domicilio ante Sarmiento<\/strong> para as\u00ed conseguir su primera victoria en el campeonato. Pero <strong>de ah\u00ed en adelante fue todo una meseta.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Castillo, el autor de los \u00fanicos dos goles de la fecha hasta el momento. \" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-2.jpg\"><span class=\"epigraphe\">Castillo, el autor de los \u00fanicos dos goles de la fecha hasta el momento. <\/span><\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>La noche del viernes tuvo dos partidos. Independiente Rivadavia recibi\u00f3 a Belgrano en Mendoza, mientras que, en simult\u00e1neo, Tigre visit\u00f3 el 15 de abril para medirse ante Uni\u00f3n. <strong>El desenlace fue el mismo en ambas canchas: empate sin goles.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>El s\u00e1bado llegaba con varios encuentros que promet\u00edan. Una nueva funci\u00f3n de Di Mar\u00eda en Arroyito, el cl\u00e1sico interzonal de la jornada, entre otros, pero no hubo con que darle. <strong>Aldosivi frente a Newell\u00b4s, Rosario Central versus San Mart\u00edn de San Juan, Platense contra Argentinos y V\u00e9lez ante Instituto: todos terminaron 0-0.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p><strong>Racing y Estudiantes ten\u00edan la posibilidad<\/strong>, y la responsabilidad,<strong> de romper esta sequ\u00eda.<\/strong> Un encuentro que promet\u00eda, pero en el que la tendencia no ayudaba&#8230; Sin embargo,<strong> tuvo que aparecer un goleador nato para cortar la racha<\/strong> y devolverle los goles al f\u00fatbol argentino.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"El festejo de Guido Carrillo ante Racing. (Foto Marcelo Carroll)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-3.jpg\"><span class=\"epigraphe\">El festejo de Guido Carrillo ante Racing. (Foto Marcelo Carroll)<\/span><\/div>\n<p><h2><strong>El gol de Carrillo que rompi\u00f3 la racha de empates 0-0<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"38\">\n<p>Iban nueve minutos del segundo tiempo en el Cilindro, donde la Academia y el Pincha igualaban sin goles, haci\u00e9ndole honor a la floja fecha que se ven\u00eda dando. Hasta que apareci\u00f3 el goleador. Edwuin Cetr\u00e9 sac\u00f3 un centro pasado al \u00e1rea de Racing, donde <strong>Carrillo se tom\u00f3 un tiempo m\u00e1s para controlar de gran manera y definir cruzado<\/strong> ante la presencia de Gabriel Arias.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"33\">\n<p>De la mano de Carrillo y de Estudiantes, el Torneo Clausura volvi\u00f3 a tener goles.<\/p>\n<\/div>\n<div class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-d00d9e74-0 hnHYbk\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembedtaoMKypT\" type=\"embed\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Estudiantes de La Plata<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Carrillo marc\u00f3 el 1-0 para el Pincha<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedtaoMKypT\"><\/span><\/div>\n<div class=\"JWvideoNota_title\">\n<p>Video: TNT Sports<\/p>\n<\/div>\n<\/div>\n<p><h2><strong>Los resultados de la fecha<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"32\">\n<p>Sarmiento 0 &#8211; Lan\u00fas 2 (Zona B)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>Independiente Rivadavia 0 &#8211; Belgrano 0 (Zona B)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>Uni\u00f3n 0 &#8211; Tigre 0 (Zona A)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>Aldosivi 0 &#8211; Newell\u00b4s 0 (Zona A)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>Rosario Central 0 &#8211; San Mart\u00edn SJ 0 (Zona B)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>Platense 0 &#8211; Argentinos Juniors 0 (Interzonal)<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"32\">\n<p>V\u00e9lez 0 &#8211; Instituto 0 (Zona B)<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Sin emoci\u00f3n: Platense y Argentinos empataron en un cl\u00e1sico aburrido\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Sin emoci\u00f3n: Platense y Argentinos empataron en un cl\u00e1sico aburrido<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"La lucha por evitar los descensos en Primera Divisi\u00f3n\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La lucha por evitar los descensos en Primera Divisi\u00f3n<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"\u00a1Seis partidos terminaron 0-0 en la fecha 3!\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00a1Seis partidos terminaron 0-0 en la fecha 3!<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Estudiantes consigui\u00f3 un importante triunfo ante Racing en Avellaneda\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-gol-que-rompio-la-racha-de-los-0-0-en-el-clausura-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Estudiantes consigui\u00f3 un importante triunfo ante Racing en Avellaneda<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>26\/07\/2025 23:01hs. La tercera fecha del Torneo Clausura ven\u00eda dejando mucho que desear en cuanto a los resultados, pero el choque entre Racing y Estudiantesse convirti\u00f3 en un oasis en el desierto para romper la incre\u00edble racha de encuentros sin goles que se ven\u00eda dando. Guido Carrillo puso el 1-0 en el Cilindro y provoc\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":112195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/112194"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=112194"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/112194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/112195"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=112194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=112194"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=112194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}