{"id":111993,"date":"2025-07-25T02:08:05","date_gmt":"2025-07-25T02:08:05","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-femenino\/seleccion-argentina-femenina-copa-america-semifinales-ecuador-victoria-grupo_0_YjESJIw1eS.html"},"modified":"2025-07-25T02:08:05","modified_gmt":"2025-07-25T02:08:05","slug":"argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/25\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina\/","title":{"rendered":"Argentina le gan\u00f3 a Ecuador, qued\u00f3 primera de su grupo y se meti\u00f3 en semis de la Copa Am\u00e9rica Femenina"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina.jpg\"><\/p>\n<p><span class=\"createDate\">24\/07\/2025 23:08hs.<\/span><time class=\"modificatedDate\" datetime=\"2025-07-24T23:11:49-03:00\"> Actualizado al 24\/07\/2025 23:11hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"30.12\">\n<p>Nueva victoria de una <a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-argentina.html\" title=\"Selecci\u00f3n Argentina\" alt=\"Selecci\u00f3n Argentina\" class=\"slug\">Selecci\u00f3n Argentina<\/a> que se acostumbr\u00f3 a ganar en la <a href=\"https:\/\/www.ole.com.ar\/tema\/copa-america-femenina.html\" title=\"Copa Am\u00e9rica Femenina\" alt=\"Copa Am\u00e9rica Femenina\" class=\"slug\">Copa Am\u00e9rica Femenina<\/a>, con la que se asegur\u00f3 el primer puesto de su grupo y ahora espera rival en la semifinal. Las chicas de la Albiceleste se impusieron por <strong>2-0 ante <a href=\"https:\/\/www.ole.com.ar\/tema\/seleccion-de-ecuador.html\" title=\"Selecci\u00f3n de Ecuador\" alt=\"Selecci\u00f3n de Ecuador\" class=\"slug\">Ecuador<\/a> y cerraron la primera etapa con puntaje ideal.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"34.769503546099\">\n<p>El equipo dirigido por <a href=\"https:\/\/www.ole.com.ar\/tema\/german-portanova.html\" title=\"Germ\u00e1n Portanova\" alt=\"Germ\u00e1n Portanova\" class=\"slug\">Germ\u00e1n Portanova<\/a> llegaba al \u00faltimo choque de la fase de grupos nueve unidades, gracias a las tres victorias al hilo obtenidas ante Uruguay, Chile y Per\u00fa, por lo que <strong>se perfilaba como claro candidato a quedarse con el primer puesto de la Zona A.<\/strong> Y as\u00ed fue.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>En un encuentro en el que La Tri contaba con los m\u00e1s de <strong>2800 metros de altura <\/strong>del Estadio Banco Guayaquil en Quito, casa de Independiente del Valle, la Selecci\u00f3n Argentina tard\u00f3 unos minutos en hacer pie. Sin embargo, en 19 minutos de juego <strong>aprovech\u00f3 una de las primeras que tuvo para ponerse arriba en el marcador.<\/strong><\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"El festejo de las jugadores de Argentina ante Ecuador. (EFE\/ Jos\u00e9 J\u00e1come)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-2.jpg\"><span class=\"epigraphe\">El festejo de las jugadores de Argentina ante Ecuador. (EFE\/ Jos\u00e9 J\u00e1come)<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Fue con una gran jugada de Paulina Gramaglia, que encar\u00f3 con un desborde por derecha sac\u00e1ndose de encima a tres rivales, para meterse en el zona de peligro y ensayar un centro raso al coraz\u00f3n del \u00e1rea chica. All\u00ed apareci\u00f3 <strong>Kishi N\u00fa\u00f1ez,<\/strong> quien hizo honor al n\u00famero nueve que porta en la espalda y solo tuvo que<strong> empujarla con el exterior de su pie derecho<\/strong> para romper el cero en la noche ecuatoriana.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>Ya en el complemento, el equipo de Portanova aprovech\u00f3 la ventaja para comenzar a manejar el encuentro y, luego de algunas ocasiones desperdiciadas, lleg\u00f3 el segundo. Maricel Pereyra se tom\u00f3 un segundo adentro del \u00e1rea para ubicar a <strong>Florencia Bonsegundo, quien apenas llevaba unos minutos en cancha, y defini\u00f3 con un derechazo al techo del arco.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"35\">\n<p>A destacar la gran actuaci\u00f3n de la arquera argentina <strong>Abigail Chaves,<\/strong> que <strong>respondi\u00f3 de gran manera cada vez que la exigieron<\/strong> y se qued\u00f3 con un sinf\u00edn de centros que cayeron en el \u00e1rea albiceleste.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Abigail Chaves la rompi\u00f3 contra Ecuador. EFE\/ Jos\u00e9 J\u00e1come\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-3.jpg\"><span class=\"epigraphe\">Abigail Chaves la rompi\u00f3 contra Ecuador. EFE\/ Jos\u00e9 J\u00e1come<\/span><\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>De esta manera, la Selecci\u00f3n Argentina Femenina se adue\u00f1\u00f3 del primer puesto de su zona, <strong>se meti\u00f3 entre los cuatro mejores del torneo y se asegur\u00f3 un lugar, como m\u00ednimo, en los Juegos Panamericanos 2027.<\/strong> En caso de llegar a la final, se clasificar\u00e1 a los Juegos Ol\u00edmpicos 2028. Ahora solo queda esperar por el rival en semis.<\/p>\n<\/div>\n<p><h2><strong>Los goles de Argentina contra Ecuador<\/strong><\/h2>\n<\/p>\n<div class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-d00d9e74-0 hnHYbk\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembed25yC1ze3\" type=\"embed\" readability=\"56\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\" readability=\"7\">\n<p>Selecci\u00f3n Argentina<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Los goles de Argentina ante Ecuador en la Copa Am\u00e9rica femenina<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembed25yC1ze3\"><\/span><\/div>\n<\/div>\n<p><h2><strong>\u00bfA qui\u00e9n enfrentar\u00e1 Argentina en semifinales?<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"37\">\n<p>El combinado nacional espera entre los cuatro mejores del certamen por el desenlace del Grupo B. <strong>Argentina se ver\u00e1 las caras con el equipo que termine segundo en esta zona. <\/strong>Por el momento, Brasil marcha puntero con nueve unidades, seguido por Colombia con siete y Venezuela con cuatro. Este viernes se enfrentan Colombia con Brasil y Venezuela con Paraguay.<\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"La llave de la Sudamericana: Independiente ya conoce a su rival y cruce argentino en octavos de final\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La llave de la Sudamericana: Independiente ya conoce a su rival y cruce argentino en octavos de final<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Con la Juanfer intacta: las ganas de Quintero por tener su reestreno contra San Lorenzo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Con la Juanfer intacta: las ganas de Quintero por tener su reestreno contra San Lorenzo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Copa Am\u00e9rica Femenina: qu\u00e9 necesita Argentina para evitar a Brasil en la semifinal\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Copa Am\u00e9rica Femenina: qu\u00e9 necesita Argentina para evitar a Brasil en la semifinal<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"Flamengo, a un paso de sumar a otros dos jugadores desde Europa para so\u00f1ar con la Libertadores\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/argentina-le-gano-a-ecuador-quedo-primera-de-su-grupo-y-se-metio-en-semis-de-la-copa-america-femenina-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Flamengo, a un paso de sumar a otros dos jugadores desde Europa para so\u00f1ar con la Libertadores<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>24\/07\/2025 23:08hs. Actualizado al 24\/07\/2025 23:11hs. Nueva victoria de una Selecci\u00f3n Argentina que se acostumbr\u00f3 a ganar en la Copa Am\u00e9rica Femenina, con la que se asegur\u00f3 el primer puesto de su grupo y ahora espera rival en la semifinal. Las chicas de la Albiceleste se impusieron por 2-0 ante Ecuador y cerraron la primera [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111993"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111993"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111994"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111993"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}