{"id":111812,"date":"2025-07-22T23:28:48","date_gmt":"2025-07-22T23:28:48","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-internacional\/italia\/lautaro-martinez-entrenamiento-club-san-francisco-bahia-blanco_0_VTsdI45jdW.html"},"modified":"2025-07-22T23:28:48","modified_gmt":"2025-07-22T23:28:48","slug":"antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/22\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa\/","title":{"rendered":"Antes de volver a Italia, Lautaro Mart\u00ednez se entren\u00f3 en el club de su pap\u00e1"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-07-22T20:28:48-03:00\">22\/07\/2025 20:28hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"37.350746268657\">\n<p>Despu\u00e9s de una larga temporada con el Inter, en la que no termin\u00f3 de la manera que se esperaba, <a href=\"https:\/\/www.ole.com.ar\/tema\/lautaro-martinez.html\" title=\"Lautaro Mart\u00ednez\" alt=\"Lautaro Mart\u00ednez\" class=\"slug\">Lautaro Mart\u00ednez<\/a> se fue de vacaciones con su familia. Al Toro se lo pudo ver paseando por M\u00e9xico y Disney con su familia. Despu\u00e9s de esos d\u00edas de descanso, <strong>regres\u00f3 al pa\u00eds para su \u00faltima semana libre antes de regresar a Italia. En este contexto, Lautaro no se dej\u00f3 estar y pens\u00f3 en lo que viene<\/strong>.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Por ejemplo este martes, el <strong>Toro se entren\u00f3 en el Club Deportivo San Francisco de Bah\u00eda Blanca<\/strong>, su ciudad natal. Si bien el delantero dio sus primeros pasos en Liniers de la misma ciudad, en San Francisco <strong>su pap\u00e1 es presidente y su hermano se desempe\u00f1a como defensor<\/strong>. El Celeste comparti\u00f3 im\u00e1genes del entrenamiento y public\u00f3 un video con declaraciones del Toro.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-2.jpg\"><span class=\"epigraphe\">Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)<\/span><\/div>\n<p><h2><strong>La pr\u00e1ctica de Lautaro en Bah\u00eda Blanca<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"40\">\n<p>\u00abFamilia es la principal palabra que este club transmite. Mi pap\u00e1 se retir\u00f3 ac\u00e1 y lo hemos vivido en carne propia. Hoy mi pap\u00e1 es presidente, mi hermano juega ac\u00e1 y mi mam\u00e1 trabaja en el club. <strong>La familia est\u00e1 presente y hoy est\u00e1n viviendo para San Francisco<\/strong>\u00ab, afirm\u00f3 Lautaro. San Francisco participa de la Liga del Sur, que tiene su sede en Bah\u00eda Blanca. Pelusa Mart\u00ednez, como se lo conoce al pap\u00e1 de Lautaro, se retir\u00f3 como jugador de dicho club y ahora es presidente.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>El Toro mencion\u00f3 lo especial que es para \u00e9l el hecho de ver a su familia ah\u00ed. \u00ab<strong>Se trabaj\u00f3 siempre a pulm\u00f3n, es un club que est\u00e1 hecho por sus hinchas, donde es familia. Por eso tambi\u00e9n me gusta venir y pasar el tiempo.<\/strong> La vez pasada que el club estaba de vacaciones me toc\u00f3 estar tambi\u00e9n ac\u00e1 y pude recorrerlo con mi pap\u00e1\u00bb, cont\u00f3 el delantero. Lautaro se reincorporar\u00e1 al Inter la pr\u00f3xima semana para afrontar la pretemporada.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-3.jpg\"><span class=\"epigraphe\">Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)<\/span><\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Siguiendo esta l\u00ednea, el centrodelantero expres\u00f3 que trata de aprovechar los d\u00edas en su ciudad para seguir entrenando y movi\u00e9ndose, de cara a otra temporada exigente con el Neroazzurro. Destac\u00f3 la calidez con la que lo recibieron los chicos del plantel y record\u00f3: \u00abEs hacer que los chicos pasen un gran momento y yo tambi\u00e9n, re\u00edrme y <strong>volver a esos inicios tambi\u00e9n que fui muy feliz cuando arranqu\u00e9 a jugar al f\u00fatbol y cuando jugaba en una liga amateur<\/strong>\u00ab.<\/p>\n<\/div>\n<p><h2><strong>El mensaje de Lautaro para el club de su pap\u00e1<\/strong><\/h2>\n<\/p>\n<div class=\"sc-3c5a76cc-1 idjLTd\" readability=\"6\">\n<div class=\"sc-d00d9e74-0 hnHYbk vertical\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembedQmgu5jQe\" type=\"embed\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>Lautaro Mart\u00ednez<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedQmgu5jQe\"><\/span><\/div>\n<div class=\"JWvideoNota_title\" readability=\"7\">\n<p>Cr\u00e9ditos: @clubdsanfrancisco<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-4.jpg\"><span class=\"epigraphe\">Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)<\/span><\/div>\n<div class=\"custom-text \" readability=\"34.267002518892\">\n<p>Desde lo deportivo <strong>no fue el mejor campeonato en la Liga para San Francisco<\/strong>. Finaliz\u00f3 \u00faltimo en la tabla de la Primera Divisi\u00f3n y no pudo acceder a los playoffs. Tampoco pudo pelear por un lugar en el <a href=\"https:\/\/www.ole.com.ar\/tema\/torneo-regional-amateur.html\" title=\"Torneo Regional Amateur\" alt=\"Torneo Regional Amateur\" class=\"slug\">Torneo Regional Amateur<\/a>, la cuarta divisi\u00f3n del f\u00fatbol argentino, que otorga plazas para disputar el <a href=\"https:\/\/www.ole.com.ar\/tema\/federal-a.html\" title=\"Federal A\" alt=\"Federal A\" class=\"slug\">Torneo Federal A<\/a>, la tercera categor\u00eda para los clubes afiliados indirectamente a la AFA. <\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>En este sentido, Lautaro les dej\u00f3 un mensaje motivacional especial para todo San Francisco: \u00abObviamente un mal momento lo pueden tener todos, pero d<strong>e ese mal momento se tiene que salir m\u00e1s fuerte que nunca<\/strong>. As\u00ed que desearle lo mejor y gracias por recibirme de esta manera y ojal\u00e1 que los chicos se lo hayan pasado bien\u00bb. <\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-5.jpg\"><span class=\"epigraphe\">Lautaro Mart\u00ednez se entren\u00f3 en el Club San Francisco de Bah\u00eda Blanca. (Foto: prensa San Francisco)<\/span><\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Patricia Bullrich le exigi\u00f3 a Toviggino que se retracte\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Patricia Bullrich le exigi\u00f3 a Toviggino que se retracte<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El italiano m\u00e1s caro de la historia es argentino\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-7.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El italiano m\u00e1s caro de la historia es argentino<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Video: el golazo de arco a arco en el torneo de L'Alcudia\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/antes-de-volver-a-italia-lautaro-martinez-se-entreno-en-el-club-de-su-papa-8.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Video: el golazo de arco a arco en el torneo de L&#8217;Alcudia<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>22\/07\/2025 20:28hs. Despu\u00e9s de una larga temporada con el Inter, en la que no termin\u00f3 de la manera que se esperaba, Lautaro Mart\u00ednez se fue de vacaciones con su familia. Al Toro se lo pudo ver paseando por M\u00e9xico y Disney con su familia. Despu\u00e9s de esos d\u00edas de descanso, regres\u00f3 al pa\u00eds para su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111813,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111812"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111812"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111813"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111812"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}