{"id":111804,"date":"2025-07-23T00:22:23","date_gmt":"2025-07-23T00:22:23","guid":{"rendered":"https:\/\/www.ole.com.ar\/san-lorenzo\/san-lorenzo-julio-lopardo-presidente-inhibiciones-mercado-refuerzos-moretti-afa-elecciones_0_T80AssHeEu.html"},"modified":"2025-07-23T00:22:23","modified_gmt":"2025-07-23T00:22:23","slug":"lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/23\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones\/","title":{"rendered":"Lopardo: la decisi\u00f3n de no reforzar el plantel, Moretti, la AFA y su mirada sobre las elecciones"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-07-22T21:22:23-03:00\">22\/07\/2025 21:22hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"38.227027027027\">\n<p>Lo que arranc\u00f3 como un rumor y se confirm\u00f3 como informaci\u00f3n, lo hizo oficial el propio <strong>Julio Lopardo<\/strong> en off y despu\u00e9s p\u00fablicamente en di\u00e1logo con La Red. \u201c<strong>Las inhibiciones las vamos a levantar pero con m\u00e1s tiempo. Decidimos apostar a los chicos y no traer jugadores que no iban a cambiar la ecuaci\u00f3n y que iban a tapar a los chicos<\/strong>. Eso s\u00ed,<strong> si no traemos no vamos a vender, entonces la \u00fanica forma que se vaya un jugador es por la cl\u00e1usula<\/strong>\u201d, asegur\u00f3 el directivo que oficia de presidente de <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/san-lorenzo.html\" title=\"San Lorenzo\" alt=\"San Lorenzo\" class=\"slug\">San Lorenzo<\/a><\/strong> ante la licencia de Marcelo Moretti.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"43\">\n<p>Lopardo sostuvo que <strong>\u201ces una apuesta\u201d<\/strong> y se reconoce consciente de que la suerte puede jugar de su lado o no. \u201cSi sale bien, sale bien. Y si sale mal, peor de lo que estamos no vamos a estar&#8230;\u201d, solt\u00f3. Tal como hab\u00eda anticipado en declaraciones anteriores, se mueve bajo lo que cree correcto y asume el costo: <strong>\u201cEs una decisi\u00f3n dif\u00edcil, pol\u00edticamente incorrecta, pero creo que es a lo que hay que apostar<\/strong>. Yo no vine a hacer pol\u00edtica, <strong>vine a hacer lo que tengo que hacer, no me interesa presentarme en las pr\u00f3ximas elecciones ni quiero ser reelecto<\/strong>\u201d.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Seg\u00fan dijo el directivo, la determinaci\u00f3n no se tom\u00f3 por falta de dinero, ya que con las ventas de Braida e Irala m\u00e1s el resarcimiento de Boca por Russo se podr\u00eda haber negociado. <strong>\u201cLa plata la quiero utilizar para no malvender y para que no se le falte m\u00e1s el respeto a San Lorenzo. Hoy nos ofecen dos manies y tres gaseosas por cualquier jugador&#8230;\u201d<\/strong>, destac\u00f3.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"38\">\n<p>Adem\u00e1s, dej\u00f3 en claro que conf\u00eda \u201cen las condiciones\u201d de Ayude y en la de los juveniles. \u201c<strong>Tenemos unos pibes que son muy buenos pero est\u00e1n maltratados por todo el entorno pol\u00edtico<\/strong>. Tenemos que cuidarlos porque son pibes que van a valer mucho&#8230; <strong>Los clubes viven de los jugadores y nosotros los maltratamos, los insultamos y los tapamos con tipos de 30 a\u00f1os<\/strong>\u201d, afirm\u00f3.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"41\">\n<p>En sus declaraciones radiales, Lopardo volvi\u00f3 a cargar contra Moretti. \u201c<strong>En estos 60 d\u00edas h\u00e1biles que me toc\u00f3 gobernar lo estamos haciendo bien, pero no se nota porque hay un fantasma que hace calentar a la gente\u201d<\/strong>, dispar\u00f3. Luego enumer\u00f3 algunas cuestiones econ\u00f3micas: \u201cLevantamos m\u00e1s de 1000 millones de pesos en embargos, m\u00e1s de 700 millones de pesos en cheques, no emitimos deuda, el plantel no est\u00e1 yendo a Agremiados como hace tres meses y pagamos los aguinaldos\u201d.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Para Lopardo, lo hecho en este tiempo \u201ces cortito pero es algo\u201d y siente que no hay un reconocimiento porque <strong>\u201cla gente est\u00e1 atr\u00e1s de una renuncia que solo se dar\u00e1 si \u00e9l quiere y yo no puedo hacer nada. Le ped\u00ed 20 veces que renuncie y no quiere, tampoco soy la Justicia para tomar una determinaci\u00f3n<\/strong>. La verdad que es un clima que no ayuda para nada y <strong>si Moretti renuncia traer\u00eda paz<\/strong>\u201d.<\/p>\n<\/div>\n<p><h2><strong>La relaci\u00f3n con AFA<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"39\">\n<p>\u201cEstoy muy bien con AFA, tuve muy buenas reuniones con Tapia&#8230; AFA hace lo que tiene que hacer, cumple con lo que tiene que cumplir. Despu\u00e9s, si te dan un penal a favor o no&#8230; <strong>Lo que est\u00e1 haciendo AFA con Moretti es lo que har\u00eda con cualquier dirigente, no es que lo hace porque lo quieren a Moretti<\/strong>\u201d<\/p>\n<\/div>\n<p><h2><strong>\u00bfPens\u00f3 en renunciar d\u00edas atr\u00e1s?<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"36\">\n<p>\u201cFue algo interno, en una mesa chiquita&#8230; <strong>Le ped\u00ed a un par de muchachos que se alinearan y dije que sino lo hac\u00edan renunciaba<\/strong>. Fue una conversaci\u00f3n, no una presi\u00f3n. Pasa que <strong>en San Lorenzo hay que tener cuidado porque escuchan las paredes<\/strong>\u201d.<\/p>\n<\/div>\n<p><h2><strong>La posibilidad de que haya elecciones anticipadas<\/strong><\/h2>\n<\/p>\n<div class=\"custom-text \" readability=\"40\">\n<p>\u201cEs algo que<strong> no puede suceder porque para eso tiene que renunciar toda la Comisi\u00f3n Directiva<\/strong>. Pedir elecciones es un apriete, no es legal&#8230; Este es un gobierno legal y ese pedido es un deseo pol\u00edtico. <strong>Quiz\u00e1s algunos no me quiere reconocer porque no me eligi\u00f3 la gente, pero capaz termino siendo mejor que muchos que fueron votados<\/strong>. Sinceramente, <strong>si yo supiera que las elecciones pueden ser la soluci\u00f3n, lo har\u00eda, pero no creo que lo sean.<\/strong><\/p>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"\u00daltimas horas del mercado de pases: los refuerzos y las bajas finales\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones-2.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00daltimas horas del mercado de pases: los refuerzos y las bajas finales<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"A la espera de Boca y River, as\u00ed se jugar\u00e1n los octavos de final de Copa Argentina\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones-3.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>A la espera de Boca y River, as\u00ed se jugar\u00e1n los octavos de final de Copa Argentina<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Se adelant\u00f3 el horario del cl\u00e1sico entre River y San Lorenzo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Se adelant\u00f3 el horario del cl\u00e1sico entre River y San Lorenzo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"\u00c1rbitros de la tercera: Ram\u00edrez en River - San Lorenzo\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>\u00c1rbitros de la tercera: Ram\u00edrez en River &#8211; San Lorenzo<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"La llave de la Sudamericana: cruce argentino en octavos de final\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/lopardo-la-decision-de-no-reforzar-el-plantel-moretti-la-afa-y-su-mirada-sobre-las-elecciones-6.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>La llave de la Sudamericana: cruce argentino en octavos de final<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>22\/07\/2025 21:22hs. Lo que arranc\u00f3 como un rumor y se confirm\u00f3 como informaci\u00f3n, lo hizo oficial el propio Julio Lopardo en off y despu\u00e9s p\u00fablicamente en di\u00e1logo con La Red. \u201cLas inhibiciones las vamos a levantar pero con m\u00e1s tiempo. Decidimos apostar a los chicos y no traer jugadores que no iban a cambiar la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111804"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111804"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111805"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111804"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}