{"id":111716,"date":"2025-07-22T11:30:31","date_gmt":"2025-07-22T11:30:31","guid":{"rendered":"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/mary-jane-esparto-bailarinas-verano-fresquitas-comodas-20250722133030-nt.html"},"modified":"2025-07-22T11:30:31","modified_gmt":"2025-07-22T11:30:31","slug":"mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/22\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo\/","title":{"rendered":"Mary Jane de esparto: las bailarinas del verano fresquitas y c\u00f3modas que te pondr\u00e1s con todo"},"content":{"rendered":"<p><!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial \">\n<!-- AUTHOR --><\/p>\n<div class=\"voc-author-timesocial__signature \">\n<!-- IMAGE AUTHOR -->\n<picture class=\"voc-image-signature\">\n<img class=\"voc-image-signature__img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo.jpg\" alt=\"Raquel Rodr\u00edguez\">\n<\/picture>\n<!-- INFO AUTHOR --> <\/div><\/div>\n<p><!-- COMPONENTS --><\/p>\n<p class=\"voc-paragraph\">Hay vida m\u00e1s all\u00e1 de las <a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/sandalias-fichar-rebajas-verano-comodas-elegantes-versatiles-20250702133815-nt.html\" title=\"www.mujerhoy.com\" data-voc-vtm-id=\"in-text-traffic\" data-mrf-link=\"www.mujerhoy.com\">sandalias <\/a>en verano y hoy te traemos la mejor prueba de ello. Como sabr\u00e1s, las bailarinas son un tipo de<strong> calzado s\u00faper tendencia <\/strong>que llevan varias temporadas como protagonista. Se han postulado como el tipo de zapato perfecto para ir c\u00f3moda y elegante a diario, sobre todo, cuando se trata de la opci\u00f3n de estilo Mary Jane.<\/p>\n<p class=\"voc-paragraph\">Sin embargo, no son unos <a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/zapatos-planos-comodos-fresquitos-no-son-sandalias-verano-20250521104605-nt.html\" title=\"www.mujerhoy.com\" data-voc-vtm-id=\"in-text-traffic\" data-mrf-link=\"www.mujerhoy.com\">zapatos planos fresquitos<\/a> y aptos para las altas temperaturas. Es por ello, que algunas firmas han querido sacar a la venta una propuesta mucho m\u00e1s veraniega que es ideal para lucir a diario. Hablamos de bailarinas con suela de esparto que quedar\u00e1n de maravilla con tus<strong> looks de verano<\/strong>.<\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/reina-letizia-zapatos-favoritos-donde-comprar-merceditas-negras-20250714202345-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"D\u00f3nde copiar los zapatos destalonados favoritos de la reina Letizia\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-1.jpg\" alt=\"D\u00f3nde copiar los zapatos destalonados favoritos de la reina Letizia\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/tendencias\/sandalias-flor-tendencia-unirte-verano-modelos-preciosos-20250713135308-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Sandalias con flor, la tendencia a la que tienes que unirte en verano: 7 modelos preciosos\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-2.jpg\" alt=\"Sandalias con flor, la tendencia a la que tienes que unirte en verano: 7 modelos preciosos\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-930\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-3.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt data-voc-vtm-id=\"in-text-traffic\"> <\/button>\n<\/div>\n<\/div>\n<div id=\"photo-930\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-930\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-3.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p><h3 class=\"v-cmp-suh\">\nCon plataforma<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\"><strong>Toms<\/strong>, la marca que a\u00fana estilo, comodidad y compromiso social, presenta una de sus grandes apuestas para disfrutar del verano: la Mary Jane de mujer Carolina, disponible en tono dark sky y en negro. Una reinterpretaci\u00f3n moderna y desenfadada de un cl\u00e1sico atemporal que llega con fuerza para conquistar los d\u00edas m\u00e1s c\u00e1lidos.<\/p>\n<p class=\"voc-paragraph\">Dise\u00f1adas para acompa\u00f1arte en todos tus planes estivales, estas alpargatas combinan una est\u00e9tica relajada con un sutil toque elegante. La parte superior en denim texturizado o en color negro y los acabados en cuerda natural aportan frescura y personalidad, convirti\u00e9ndolas en el calzado perfecto para quienes busca<strong>n confort sin renunciar a las tendencias<\/strong>. Precio: rebajadas a 59,92 euros.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-824\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-4.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt data-voc-vtm-id=\"in-text-traffic\"> <\/button>\n<\/div>\n<\/div>\n<div id=\"photo-824\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-824\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-4.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p><h3 class=\"v-cmp-suh\">\nCon un toque de brillo<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">La alpargata mercedita Cuba de <strong>Monpiel<\/strong> est\u00e1 fabricada en una combinaci\u00f3n de piel aut\u00e9ntica y tela. Se convertir\u00e1 en el modelo perfecto para tu d\u00eda a d\u00eda del verano. Est\u00e1 fabricada artesanalmente y disponible en lona beige con brillo y en leopardo negro, dos combinaciones atrevidas, pero a la vez b\u00e1sicas que creemos que dar\u00e1n ese toque especial a tu fondo de armario. <\/p>\n<p class=\"voc-paragraph\">Es el calzado perfecto para ir de viaje, ir a la oficina o dar un paseo. Cuenta con suela de yute, tac\u00f3n de 4cm (plataforma de 2cm) y punta cuadrada que est\u00e1 tan en tendencia. Se sujeta al pie con una tira cerrada con hebilla y es una mercedita que no pasar\u00e1 de moda y ser\u00e1 todo un aliado de tu armario. Precio: rebajadas a 93,90 euros.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-432\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-5.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt data-voc-vtm-id=\"in-text-traffic\"> <\/button>\n<\/div>\n<\/div>\n<div id=\"photo-432\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-432\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-5.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p><h3 class=\"v-cmp-suh\">\nTejido calado<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Si lo que buscas es una opci\u00f3n muy fresquita, que sea tan gustosa de llevar como una sandalias, prueba con este modelo calado de <strong>Popa<\/strong>. Se trata del modelo Lira, confeccionada en material picado y es la bailarina perfecta para quienes buscan estilo y ligereza. <\/p>\n<p class=\"voc-paragraph\">Su textura \u00fanica y piso de yute aportan un toque moderno y c\u00f3modo, mientras que la sujeci\u00f3n con tira y hebilla asegura un ajuste seguro. Es un zapato ideal para quienes quieren un calzado vers\u00e1til que marque la diferencia en sus looks. Precio: rebajadas a 29,99 euros.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-386\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-6.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt data-voc-vtm-id=\"in-text-traffic\"> <\/button>\n<\/div>\n<\/div>\n<div id=\"photo-386\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-386\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-6.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p><h3 class=\"v-cmp-suh\">\nTipo alpargata<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">En <strong>Casta\u00f1er <\/strong>hemos encontrado una versi\u00f3n de su cl\u00e1sica y famos\u00edsima alpargata, pero en formato bailarina. Es un zapato de estilo Mary Jane que est\u00e1 confeccionada en un tejido de algod\u00f3n org\u00e1nico lavado y en un bonito color mostaza que combina con casi todo.<\/p>\n<p class=\"voc-paragraph\">Disponible tambi\u00e9n en color gris oscuro, est\u00e1 caracterizado por su suela plana de yute con puntera reforzada y por una tira con cierre de hebilla que cruza el empeine y que hace que el zapato quede sujeto y sea mucho m\u00e1s c\u00f3modo. Precio: rebajado a 100 euros.<\/p>\n<div class=\"v-c-cmp v-c-cmp--s\">\n<div class=\"v-cmp-m \">\n<article class=\"v-a v-a--cmp-m v-c-cmp--m-z\">\n<div class=\"v-a-img-c \">\n<div class=\"v-a-fig\">\n<button class=\"v-a-link\" popovertarget=\"photo-163\"><br \/>\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-7.jpg\" class=\"v-a-img\" width=\"650\" height=\"650\" alt data-voc-vtm-id=\"in-text-traffic\"> <\/button>\n<\/div>\n<\/div>\n<div id=\"photo-163\" popover class=\"v-mdl v-mdl--fw\">\n<button class=\"v-x\" popovertarget=\"photo-163\" popovertargetaction=\"hide\"><br \/>\n<span class=\"v-i\"><br \/>\n<svg width=\"24\" height=\"23.996\" viewBox=\"0 0 24 23.996\">\n<path data-name=\"Uni\u00f3n 29\" d=\"M12,14.03,2.031,24,0,21.963,9.968,12,0,2.033,2.031,0,12,9.966,21.969,0,24,2.033,14.032,12,24,21.963,21.969,24Z\" \/>\n<\/svg><br \/>\n<\/span><br \/>\n<\/button><\/p>\n<div class=\"v-mdl__c\">\n<div class=\"v-mdl__w\">\n<img loading=\"lazy\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-7.jpg\" class=\"v-mdl__img-z\" width=\"650\" height=\"650\" alt>\n<\/div>\n<\/div>\n<\/div>\n<p><span class=\"v-bdp\"><\/span><br \/>\n<\/article>\n<\/div>\n<\/div>\n<p><h3 class=\"v-cmp-suh\">\nMetalizadas<br \/>\n<\/h3>\n<\/p>\n<p class=\"voc-paragraph\">Este zapato plano de esparto de <strong>miMaO<\/strong> cuenta con una suela de 2.5 cm de altura y est\u00e1 elaborado en piel de napa de color dorado, perfecto para aquellas que no quieren pasar desapercibidas. Incluye una tira en el empeine para ofrecer un ajuste m\u00e1s c\u00f3modo y evitar que chancletee al caminar.<\/p>\n<p class=\"voc-paragraph\">Adem\u00e1s, tienen una plantilla de piel transpirable Ultra Confort Gel que amortigua el peso del cuerpo cuando se pisa para aumentar la comodidad y reducir las molestias en los pies. Precio: rebajadas a 66,50 euros.<\/p>\n<div class=\"v-c-cmp v-c-cmp--t1 \">\n<div class=\"v-cmp-rld v-cmp-rld--2 \">\n<div class=\"v-cnt-m v-cnt-m--m\">\n<div class=\"v-cnt-m__c\">\n<div class=\"v-cnt-m__w v-cnt-m__w--1\">\n<p class=\"v-cnt-m__t\">\nTAMBI\u00c9N TE INTERESA\n<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"v-g v-g--2-c v-g--bdr-min-xs\">\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/tendencias\/zapatos-verano-tendencia-2025-rebajas-bershka-20250711105200-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:1:cmp:2-not\" class=\"v-a-link\" title=\"Estos son los zapatos de verano m\u00e1s deseados que comprar\u00e1s en las rebajas de Bershka\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-8.jpg\" alt=\"Estos son los zapatos de verano m\u00e1s deseados que comprar\u00e1s en las rebajas de Bershka\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"v-g__c \">\n<article class=\"v-a v-a--cmp-rld v-a--cmp-rld-2 v-a--p-l\">\n<div class=\"v-a-img-c\">\n<figure class=\"v-a-fig\">\n<a href=\"https:\/\/www.mujerhoy.com\/moda\/no-te-pierdas\/nauticos-zapatos-clasicos-verano-mujeres-mayores-50-anos-corte-ingles-20250708112154-nt.html#vtm_modulosEngag=mod-rel:moda:noticia:2:cmp:2-not\" class=\"v-a-link\" title=\"Nada de chanclas: los n\u00e1uticos son el zapato de verano favorito de las mujeres cl\u00e1sicas +50\"><br \/>\n<img loading=\"lazy\" class=\"v-a-img\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/mary-jane-de-esparto-las-bailarinas-del-verano-fresquitas-y-comodas-que-te-pondras-con-todo-9.jpg\" alt=\"Nada de chanclas: los n\u00e1uticos son el zapato de verano favorito de las mujeres cl\u00e1sicas +50\"><br \/>\n<\/a><br \/>\n<\/figure>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"media_block\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hay vida m\u00e1s all\u00e1 de las sandalias en verano y hoy te traemos la mejor prueba de ello. Como sabr\u00e1s, las bailarinas son un tipo de calzado s\u00faper tendencia que llevan varias temporadas como protagonista. Se han postulado como el tipo de zapato perfecto para ir c\u00f3moda y elegante a diario, sobre todo, cuando se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111716"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111716"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111716\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111717"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111716"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}