{"id":111708,"date":"2025-07-22T00:09:19","date_gmt":"2025-07-22T00:09:19","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/river-plate-marcelo-gallardo-copa-libertadores_0_3IlQeEu3cx.html"},"modified":"2025-07-22T00:09:19","modified_gmt":"2025-07-22T00:09:19","slug":"el-importante-paso-que-dio-river-pensando-en-la-libertadores-2026","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/22\/el-importante-paso-que-dio-river-pensando-en-la-libertadores-2026\/","title":{"rendered":"El importante paso que dio River pensando en la Libertadores 2026"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-importante-paso-que-dio-river-pensando-en-la-libertadores-2026.jpg\"><\/p>\n<p><time class=\"createDate\" datetime=\"2025-07-21T21:09:19-03:00\">21\/07\/2025 21:09hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"40.147058823529\">\n<p>M\u00e1s all\u00e1 de la renovaci\u00f3n en el plantel que pretende consolidar <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/marcelo-gallardo.html\" title=\"Marcelo Gallardo\" alt=\"Marcelo Gallardo\" class=\"slug\">Marcelo Gallardo<\/a><\/strong> para el segundo semestre del a\u00f1o, hay un objetivo inalterable fijado en el inicio de cada a\u00f1o. La <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/copa-libertadores.html\" title=\"Copa Libertadores\" alt=\"Copa Libertadores\" class=\"slug\">Libertadores <\/a><\/strong>es una obsesi\u00f3n en <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River <\/a><\/strong>y al margen de poder ganarla o no, decir presente se transform\u00f3 en una obligaci\u00f3n. <strong>Los dos triunfos en las primeras fechas del Torneo Clausura (3-1 ante Platense y 4-0 frente a Instituto), y aprovechando el tropez\u00f3n de sus competidores directos, River se posicion\u00f3 bien de arranque:<\/strong> escal\u00f3 hasta el segundo lugar de la tabla anual con 37 puntos. Qued\u00f3 a solo dos de Rosario Central, el puntero con 39, y tambi\u00e9n le sac\u00f3 ventaja a Boca, que hoy ocupa el \u00faltimo puesto clasificatorio a la Libertadores con 35 unidades.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"Marcelo Gallardo y el deber de clasificarse a la CL. Foto: Enrique Garcia Medina\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-importante-paso-que-dio-river-pensando-en-la-libertadores-2026-2.jpg\"><span class=\"epigraphe\">Marcelo Gallardo y el deber de clasificarse a la CL. Foto: Enrique Garcia Medina<\/span><\/div>\n<div class=\"custom-text \" readability=\"40\">\n<p>Con todos los autitos apretaditos en la clasificaci\u00f3n, con m\u00ednimas distancias entre unos y otros, el correr de los partidos comenzar\u00e1 a acomodar a candidatos y rezagados, por lo que River no solamente necesita seguir sumando para terminar entre los primeros ocho de la zona B y tener as\u00ed la posibilibidad de jugar los mata-mata por el t\u00edtulo. <strong>Ante ese panorama, agarrar envi\u00f3n de arranque es clave teniendo en cuenta que a partir del 14 de agosto habr\u00e1 doble competencia por los octavos<\/strong> de final de la CL frente a Libertad, momento en el que comenzar\u00e1 a sentirse el desgaste y la rotaci\u00f3n ganar\u00e1 protagonismo.<\/p>\n<\/div>\n<div class=\"sc-e7b891c4-0 ifHnQL image-embed\"><img alt=\"River se entrena con la mente puesta en San Lorenzo. Prensa River.\" loading=\"lazy\" width=\"720\" height=\"100\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/el-importante-paso-que-dio-river-pensando-en-la-libertadores-2026-3.jpg\"><span class=\"epigraphe\">River se entrena con la mente puesta en San Lorenzo. Prensa River.<\/span><\/div>\n<div class=\"custom-text \" readability=\"42\">\n<p>Si bien levantar la Copa Argentina, el t\u00edtulo en el Clausura y hasta la conquista de Am\u00e9rica le permitir\u00e1n competir en la Libertadores 2026, <strong>el equipo de MG buscar\u00e1 conseguir el objetivo de antemano y est\u00e1 obligado a una buena cosecha: por ahora comenz\u00f3 de buena manera. <\/strong>Es que a diferencia de otros a\u00f1os, Platense, el vigente campe\u00f3n, no realiz\u00f3 un campa\u00f1\u00f3n, suma 23 puntos y no se perfila para terminar entre los primeros tres, un escenario que le dar\u00eda el pasaje al cuarto de la tabla en el reordenamiento de posiciones en las plazas.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>21\/07\/2025 21:09hs. M\u00e1s all\u00e1 de la renovaci\u00f3n en el plantel que pretende consolidar Marcelo Gallardo para el segundo semestre del a\u00f1o, hay un objetivo inalterable fijado en el inicio de cada a\u00f1o. La Libertadores es una obsesi\u00f3n en River y al margen de poder ganarla o no, decir presente se transform\u00f3 en una obligaci\u00f3n. Los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111708"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111708"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111709"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111708"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}