{"id":111329,"date":"2025-07-18T00:24:16","date_gmt":"2025-07-18T00:24:16","guid":{"rendered":"https:\/\/www.ole.com.ar\/river-plate\/river-facundo-colidio-renovacion-contrato-acuerdo-clausula_0_DqfCTUiEku.html"},"modified":"2025-07-18T00:24:16","modified_gmt":"2025-07-18T00:24:16","slug":"otra-buena-para-river-facundo-colidio-renueva-su-contrato","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/18\/otra-buena-para-river-facundo-colidio-renueva-su-contrato\/","title":{"rendered":"Otra buena para River: Facundo Colidio renueva su contrato"},"content":{"rendered":"<p><img src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/otra-buena-para-river-facundo-colidio-renueva-su-contrato.jpg\"><\/p>\n<p><span class=\"createDate\">17\/07\/2025 21:24hs.<\/span><time class=\"modificatedDate\" datetime=\"2025-07-17T22:14:29-03:00\"> Actualizado al 17\/07\/2025 22:14hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"38.461538461538\">\n<p><strong>\u00abObviamente quiero renovar. Estamos en charlas y ojal\u00e1 se d\u00e9 pronto\u00bb.<\/strong> Lo que en el Mundial de Clubes \u00e9l mismo hab\u00eda adelantado, de acuerdo a una intenci\u00f3n que ya era conocida, en las \u00faltimas horas se termin\u00f3 de acordar de palabra: <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/facundo-colidio.html\" title=\"Facundo Colidio\" alt=\"Facundo Colidio\" class=\"slug\">Facundo Colidio<\/a><\/strong> <strong>renovar\u00e1 su contrato, que venc\u00eda en diciembre de este a\u00f1o, hasta fines del 2027<\/strong>. En un d\u00eda de buenas noticias para <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/river-plate.html\" title=\"River Plate\" alt=\"River Plate\" class=\"slug\">River<\/a><\/strong> por la presentaci\u00f3n de <strong>Juanfer Quintero<\/strong> y las confirmaciones de los pases de <strong>Juan Carlos Portillo y Mat\u00edas Galarza Fonda<\/strong>, se suma una m\u00e1s.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37.121387283237\">\n<p>Clave para <strong><a href=\"https:\/\/www.ole.com.ar\/tema\/marcelo-gallardo.html\" title=\"Marcelo Gallardo\" alt=\"Marcelo Gallardo\" class=\"slug\">Marcelo Gallardo<\/a><\/strong> y goleador del equipo en el a\u00f1o con ocho tantos, el delantero <strong>siempre tuvo en su cabeza continuar<\/strong> y ni se le cruz\u00f3 por la cabeza firmar un precontrato con otro club (algo que legalmente podr\u00eda haber hecho desde el 1\u00b0 de julio) o irse libre en diciembre: tal es as\u00ed que ni siquiera dej\u00f3 prosperar un inter\u00e9s del Flamengo hace algunos d\u00edas de sumarlo por la cl\u00e1usula, de 30 millones de euros. Gestos que conducen a lo que este viernes ser\u00e1 oficial con las fotos de la firma en las oficinas del Monumental y junto al Mu\u00f1eco, Jorge Brito y Stefano Di Carlo en el Monumental (como se hizo con los refuerzos y en la renovaci\u00f3n contractual de Lautaro Rivero).<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39\">\n<p>A sus 25 a\u00f1os, <strong>Colidio viene de demostrar su jerarqu\u00eda tras haber sido el jugador m\u00e1s regular de River en el Mundial de Clubes y luego del combo de golazo y asistencia del fin de semana contra Platense<\/strong>, en la primera fecha del Clausura. En la primera que tuvo en el partido, recibi\u00f3 un gran pase de Paulo D\u00edaz, recort\u00f3 hacia el medio y le colg\u00f3 la pelota de un \u00e1ngulo a un Cozzani que ni siquiera volando para la foto lleg\u00f3 a tirar el manotazo.<\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Y 32 minutos despu\u00e9s de esa bomba colocada para abrir el marcador contra Platense, fue clave nuevamente en el marcador: tras una jugada con el sello MG (acaso una de las pocas de este nuevo ciclo), <strong>recibi\u00f3 por la izquierda dentro del \u00e1rea y asisti\u00f3 de primera a Maxi Salas<\/strong> para que convirtiera en su estreno con la camiseta de <strong>River<\/strong>. Fue su segundo pase-gol del a\u00f1o y el octavo desde su llegada al club a mediados del 2023.<\/p>\n<\/div>\n<p><h2><strong>El gol y asistencia de Colidio ante Platense<\/strong><\/h2>\n<\/p>\n<div class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-d00d9e74-0 hnHYbk\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembedqLtjBcSc\" type=\"embed\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>Facundo Colidio<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Golazo de Colidio para abrir el marcador<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedqLtjBcSc\"><\/span><\/div>\n<div class=\"JWvideoNota_title\">\n<p>TNT Sports.<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-3c5a76cc-1 idjLTd\">\n<div class=\"sc-d00d9e74-0 hnHYbk\" type=\"embed\">\n<div class=\"sc-d00d9e74-1 iKVbz videoText\" id=\"contentTitleembedAeeyYLak\" type=\"embed\"><svg fill=\"#ffffff\"><symbol id=\"play\" viewBox=\"0 0 512 512\"><path d=\"M512 256C512 397.4 397.4 512 256 512C114.6 512 0 397.4 0 256C0 114.6 114.6 0 256 0C397.4 0 512 114.6 512 256zM176 168V344C176 352.7 180.7 360.7 188.3 364.9C195.8 369.2 205.1 369 212.5 364.5L356.5 276.5C363.6 272.1 368 264.4 368 256C368 247.6 363.6 239.9 356.5 235.5L212.5 147.5C205.1 142.1 195.8 142.8 188.3 147.1C180.7 151.3 176 159.3 176 168V168z\" \/><\/symbol><use xlink:href=\"#play\" \/><\/svg><\/p>\n<div class=\"right\">\n<p>Maximiliano Salas<!-- --> &#8211; <span>&nbsp;<\/span><\/p>\n<h2 class=\"title-vid\">Maxi Salas anot\u00f3 su primer gol con la camiseta de River<\/h2>\n<\/div>\n<\/div>\n<p><span class=\"back\" id=\"spanBackembedAeeyYLak\"><\/span><\/div>\n<div class=\"JWvideoNota_title\">\n<p>TNT Sports.<\/p>\n<\/div>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El particular ranking en el que no figuran Boca ni River luego de 13 a\u00f1os\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/otra-buena-para-river-facundo-colidio-renueva-su-contrato-2.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El particular ranking en el que no figuran Boca ni River luego de 13 a\u00f1os<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Gallardo y la primera frase que expres\u00f3 tras el regreso de Juanfer Quintero\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/otra-buena-para-river-facundo-colidio-renueva-su-contrato-3.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Gallardo y la primera frase que expres\u00f3 tras el regreso de Juanfer Quintero<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"7\">\n<section readability=\"4\"><picture><img alt=\"Un espejo, un mensaje y un horario con historia: las perlitas de c\u00f3mo River anunci\u00f3 la vuelta de Quintero\" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/otra-buena-para-river-facundo-colidio-renueva-su-contrato-4.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Un espejo, un mensaje y un horario con historia: las perlitas de c\u00f3mo River anunci\u00f3 la vuelta de Quintero<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 eoLsBE\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Dos refuerzos m\u00e1s para Gallardo: River cerr\u00f3 a Portillo y Galarza Fonda \" loading=\"lazy\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"1\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/otra-buena-para-river-facundo-colidio-renueva-su-contrato-5.jpg\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Dos refuerzos m\u00e1s para Gallardo: River cerr\u00f3 a Portillo y Galarza Fonda <\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>17\/07\/2025 21:24hs. Actualizado al 17\/07\/2025 22:14hs. \u00abObviamente quiero renovar. Estamos en charlas y ojal\u00e1 se d\u00e9 pronto\u00bb. Lo que en el Mundial de Clubes \u00e9l mismo hab\u00eda adelantado, de acuerdo a una intenci\u00f3n que ya era conocida, en las \u00faltimas horas se termin\u00f3 de acordar de palabra: Facundo Colidio renovar\u00e1 su contrato, que venc\u00eda en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111329"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111329"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111330"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111329"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}