{"id":111059,"date":"2025-07-15T15:02:00","date_gmt":"2025-07-15T15:02:00","guid":{"rendered":"https:\/\/www.trendencias.com\/viajes\/problema-masificacion-turistica-levante-llega-a-rios-piscinas-naturales-se-nos-va-manos-no-baja-nadie-pueblo-a-banarse"},"modified":"2025-07-15T15:02:00","modified_gmt":"2025-07-15T15:02:00","slug":"la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse","status":"publish","type":"post","link":"http:\/\/hoycordobaweb.com\/index.php\/2025\/07\/15\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse\/","title":{"rendered":"La masificaci\u00f3n tur\u00edstica en Levante llega a los r\u00edos y piscinas naturales: \u00abse nos va de las manos, ya no baja nadie del pueblo a ba\u00f1arse\u00bb"},"content":{"rendered":"<p>Las <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/viajes\/aqui-no-hay-playa-piscinas-naturales-instagrameables-espana-2\" data-vars-post-title=\"Aqu\u00ed no hay playa, pero s\u00ed las piscinas naturales m\u00e1s instagrameables de Espa\u00f1a \" data-vars-post-url=\"https:\/\/www.trendencias.com\/viajes\/aqui-no-hay-playa-piscinas-naturales-instagrameables-espana-2\">piscinas naturales id\u00edlicas<\/a> est\u00e1n de moda y esto se ha convertido en un grave problema para algunos pueblos de Levante, como Antella. All\u00ed, el r\u00edo X\u00faquer crea zonas de ba\u00f1o c\u00f3modas y muy refrescantes, que anta\u00f1o eran el refugio contra el calor de los vecinos. Ahora va todo el mundo y se asfixian en <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/viajes\/cuando-turismo-demasiado-turismo-barcelona-baleares-canarias-se-ahogan-sobreturismo-estas-soluciones\" data-vars-post-title=\"Cuando el turismo es demasiado turismo: Barcelona, Baleares y Canarias se ahogan con el sobreturismo y estas son las soluciones\" data-vars-post-url=\"https:\/\/www.trendencias.com\/viajes\/cuando-turismo-demasiado-turismo-barcelona-baleares-canarias-se-ahogan-sobreturismo-estas-soluciones\">masificaci\u00f3n tur\u00edstica<\/a>: <strong>basura, coches y hasta agresiones<\/strong>.<\/p>\n<p><!-- BREAK 1 --> <\/p>\n<p>Antella tiene <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.ine.es\/jaxiT3\/Datos.htm?t=2903#_tabs-tabla\">1100 habitantes<\/a> y una playa fluvial preciosa llamada L&#8217;Assut d&#8217;Antella. Este reclamo tur\u00edstico se ha ido de las manos y <strong>ha convertido a la localidad en un &#8216;pueblo sin ley&#8217;<\/strong>. Las zonas de ba\u00f1o est\u00e1n saturadas, los basureros desbordados y las carreteras llenas de coches mal estacionados, que impiden la correcta circulaci\u00f3n en ambos sentidos.<\/p>\n<p><!-- BREAK 2 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"500\" width=\"1000\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-4.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-5.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-6.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse.jpg\" alt=\"Masificacion Turistica Levante Espa\u00f1a\"> <noscript><img alt=\"Masificacion Turistica Levante Espa\u00f1a\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse.jpg\"><\/noscript> <span>L&#8217;Assut d&#8217;Antella<\/span> <\/div><\/div>\n<\/div>\n<p>\u00abYa no baja nadie del pueblo a ba\u00f1arse y es una l\u00e1stima porque son los vecinos quienes pagan realmente los impuestos\u00bb <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2025\/07\/09\/ola-solidaridad-alcaldesa-antella-agresion-banistas-119515506.html\">afirma la alcaldesa<\/a>. Para poner remedio a la situaci\u00f3n, el ayuntamiento ha a\u00f1adido <strong>polic\u00eda, vigilantes a pie de r\u00edo, limpieza y hasta un aparcamiento<\/strong> donde los visitantes pueden estacionar sin ocupar la v\u00eda p\u00fablica. Este <em>parking <\/em>es gratis entre semana, pero en temporada alta lo cobran a <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2024\/02\/16\/antella-cobrara-15-euros-aparcar-evitar-masifique-lassut-98265510.html\">15 euros diarios<\/a>.<\/p>\n<p><!-- BREAK 3 --> <\/p>\n<p>De esta forma, <strong>pueden recaudar dinero para el mantenimiento de la piscina<\/strong>, ya que no se trata de un paraje natural protegido y no pueden pedir ayudas gubernamentales ni cobrar la entrada a ella. Esta medida ha molestado mucho a los turistas, llevando incluso a <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2025\/07\/08\/zarandean-coche-alcaldesa-enfrentarse-banistas-antella-119477072.html\">agresiones<\/a> contra responsables del ayuntamiento.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <img class=\"centro_sinmarco\" height=\"853\" width=\"1280\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-1.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-7.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-8.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-9.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-1.jpg\" alt=\"Masificacion Turistica Levante Espa\u00f1a\"> <noscript><img alt=\"Masificacion Turistica Levante Espa\u00f1a\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-1.jpg\"><\/noscript> <span>Turistas en la playa fluvial de Antella<\/span> <\/div><\/div>\n<\/div>\n<p>Estas reacciones agresivas no han frenado el empe\u00f1o del Ayuntamiento de poner orden en su localidad. <strong>Tambi\u00e9n han prohibido aparcar en el casco urbano<\/strong> del pueblo, excepto a residentes y familiares. Adem\u00e1s, han <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2023\/08\/05\/antella-cortara-caminos-evitar-masificacion-otras-zonas-xuquer-90666146.html\">cerrado los caminos rurales<\/a> para evitar que aparquen ah\u00ed y estropeen los campos de los agricultores.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n<div class=\"caption-img \"> <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2025\/07\/12\/masificacion-torno-xuquer-deja-150-119588517.html\"> <img class=\"centro_sinmarco\" height=\"675\" width=\"1200\" loading=\"lazy\" decoding=\"async\" sizes=\"100vw\" fetchpriority=\"high\" srcset=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-2.jpg 450w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-10.jpg 681w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-11.jpg 1024w, http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-12.jpg 1366w\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-2.jpg\" alt=\"Masificacion Turistica Levante Espana\"> <noscript><img alt=\"Masificacion Turistica Levante Espana\" class=\"centro_sinmarco\" src=\"http:\/\/hoycordobaweb.com\/wp-content\/uploads\/2025\/07\/la-masificacion-turistica-en-levante-llega-a-los-rios-y-piscinas-naturales-se-nos-va-de-las-manos-ya-no-baja-nadie-del-pueblo-a-banarse-2.jpg\"><\/noscript> <\/a> <span>Foto cortes\u00eda de Levante EMV. (Coches de ba\u00f1istas aparcados en Antella).<\/span> <\/div><\/div>\n<\/div>\n<p>Con estas medidas, buscan frenar los abusos tur\u00edsticos y redirigirlos hacia las zonas de aparcamiento de pago. De esa forma, al menos la <strong>masificaci\u00f3n generar\u00e1 dinero<\/strong> para la localidad.<\/p>\n<p><!-- BREAK 6 --> <\/p>\n<blockquote><p>\u00abHay cero consumo en el pueblo y un aut\u00e9ntico desastre el r\u00edo por la tarde. Bolsas, sillas rotas, estructuras de lonas, etc. Sin contar todo tipo de m\u00fasica a todo volumen todo el d\u00eda. Rompen todas las reglas de la ordenanza municipal y no se hace absolutamente nada. La situaci\u00f3n es insoportable d\u00eda tras d\u00eda.\u00bb<\/p><\/blockquote>\n<p>Fotos | <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.antella.es\/\">Ayuntamiento de Antella<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/riberaturisme.es\/alojamiento\/lassut-dantella\/\">La Ribera de X\u00faquer<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.guiarepsol.com\/es\/fichas\/localidad\/antella-606\/\">Gu\u00eda Repsol<\/a>, <a rel=\"noopener, noreferrer\" href=\"https:\/\/www.levante-emv.com\/ribera\/2025\/07\/12\/masificacion-torno-xuquer-deja-150-119588517.html\">Levante EMV<\/a>.<\/p>\n<p>En Trendencias | <a class=\"text-outboundlink\" href=\"https:\/\/www.trendencias.com\/viajes\/27-escapadas-espana-para-hacer-pareja-que-quiza-no-habias-pensado\" data-vars-post-title=\"Las 35 escapadas rom\u00e1nticas por Espa\u00f1a para hacer en pareja en las que quiz\u00e1 no hab\u00edas pensado\" data-vars-post-url=\"https:\/\/www.trendencias.com\/viajes\/27-escapadas-espana-para-hacer-pareja-que-quiza-no-habias-pensado\">Las 35 escapadas rom\u00e1nticas por Espa\u00f1a para hacer en pareja en las que quiz\u00e1 no hab\u00edas pensado<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las piscinas naturales id\u00edlicas est\u00e1n de moda y esto se ha convertido en un grave problema para algunos pueblos de Levante, como Antella. All\u00ed, el r\u00edo X\u00faquer crea zonas de ba\u00f1o c\u00f3modas y muy refrescantes, que anta\u00f1o eran el refugio contra el calor de los vecinos. Ahora va todo el mundo y se asfixian en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":111060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111059"}],"collection":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/comments?post=111059"}],"version-history":[{"count":0,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/posts\/111059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media\/111060"}],"wp:attachment":[{"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/media?parent=111059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/categories?post=111059"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hoycordobaweb.com\/index.php\/wp-json\/wp\/v2\/tags?post=111059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}